{"id":88834,"date":"2019-05-10T08:00:04","date_gmt":"2019-05-10T06:00:04","guid":{"rendered":"https:\/\/osr.org\/?p=88834"},"modified":"2019-05-21T00:12:29","modified_gmt":"2019-05-20T22:12:29","slug":"galaxia-de-andromeda","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/","title":{"rendered":"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela"},"content":{"rendered":"<p>A gal\u00e1xia de Andr\u00f4meda, ainda que sendo a mais pr\u00f3xima da nossa, fica a mais de 2,5 milh\u00f5es de anos-luz de nosso planeta. Ela recebeu esse nome por sua proximidade com a constela\u00e7\u00e3o de Andr\u00f4meda que, por sua vez, recebeu esse nome por conta da uma princesa da mitologia grega, que era chamada Andr\u00f4meda.<\/p>\n<p>Andr\u00f4meda era filha de Cefeu, o Rei da Eti\u00f3pia, e de Cassiopeia. A gal\u00e1xia de Andr\u00f4meda se expande com maior velocidade do que as outras gal\u00e1xias do mesmo grupo, e essa \u00e9 apenas uma das curiosidades que essa gal\u00e1xia apresenta. Conhe\u00e7a outras delas agora mesmo!<\/p>\n<h2><span style=\"color: #15acdf\">1. A gal\u00e1xia de Andr\u00f4meda tamb\u00e9m \u00e9 conhecida como Messier 31<br \/>\n<\/span><\/h2>\n<p>Ela ganhou esse nome por conta de Charles Messier, um famoso astr\u00f4nomo franc\u00eas que catalogou em primeira m\u00e3o esta gigantesca gal\u00e1xia. Ele foi respons\u00e1vel por catalogar diversos objetos no espa\u00e7o, que s\u00e3o conhecidos geralmente como &#8220;messier&#8221; ou &#8220;catalog messier&#8221;.<\/p>\n<div id=\"attachment_88855\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-88855\" class=\"size-full wp-image-88855\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda.jpg\" alt=\"\" width=\"758\" height=\"426\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda.jpg 758w, https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda-300x169.jpg 300w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><p id=\"caption-attachment-88855\" class=\"wp-caption-text\"><p class=\"caption-text\">Pixabay<\/p><\/figure> Pixabay<\/p><\/div>\n<h2><span style=\"color: #15acdf\">2. Constela\u00e7\u00e3o de Andr\u00f4meda<br \/>\n<\/span><\/h2>\n<p>Essa constela\u00e7\u00e3o fica muito pr\u00f3xima \u00e0 gal\u00e1xia, e foi por isso que o nome de uma foi para a outra. Mas acontece que esse padr\u00e3o estelar recebeu esse nome por conta de um conto m\u00edtico grego. A constela\u00e7\u00e3o em si foi catalogada pela primeira vez por um astr\u00f4nomo chamado Ptolomeu, durante o s\u00e9culo dois. Ela, as vezes, \u00e9 chamada de Dama Acorrentada, Persea ou Cepheis.<\/p>\n<h2><span style=\"color: #15acdf\">3. Tr\u00eas vezes maior que nossa gal\u00e1xia<br \/>\n<\/span><\/h2>\n<p>Geralmente, para se medir as coisas dentro da astronomia, usamos como unidade de medida o ano-luz. A gal\u00e1xia de Andr\u00f4meda tem cerca de 220.000 anos-luz de di\u00e2metro. Ela \u00e9 MUITO maior que a nossa gal\u00e1xia! Tirando que ela fica a mais de 2,5 milh\u00f5es de anos luz da Via L\u00e1ctea.<\/p>\n<h2><span style=\"color: #15acdf\">4. Estrelas para dar e vender<br \/>\n<\/span><\/h2>\n<p><a href=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/sol\/?currency=BRL\">Nossa gal\u00e1xia<\/a> tem por volta de 400 bilh\u00f5es de estrelas. Pode parecer muito, mas a Gal\u00e1xia de Andr\u00f4meda tem mais de que o dobro de estrelas. J\u00e1 parou para tentar imaginar isso?<\/p>\n<div id=\"attachment_88875\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-88875\" class=\"size-full wp-image-88875\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/Gal\u00e1xia-de-Andr\u00f4meda.jpg\" alt=\"\" width=\"758\" height=\"505\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/Gal\u00e1xia-de-Andr\u00f4meda.jpg 758w, https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/Gal\u00e1xia-de-Andr\u00f4meda-300x200.jpg 300w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><p id=\"caption-attachment-88875\" class=\"wp-caption-text\"><p class=\"caption-text\">Pixabay<\/p><\/figure> Pixabay<\/p><\/div>\n<h2><span style=\"color: #15acdf\">5. N\u00facleos g\u00eameos<br \/>\n<\/span><\/h2>\n<p>Geralmente, as gal\u00e1xias giram ao redor de um ponto fixo, chamado de n\u00facleo. Mas Andr\u00f4meda tem dois n\u00facleos diferentes, formados por um agrupamento gigantesco de bilh\u00f5es de estrelas densamente compactas. Esses agrupamentos est\u00e3o a apenas cinco anos-luz um do outro, sendo conhecidos como P1 e P2.<\/p>\n<p>Isso tudo \u00e9 apenas uma parte do que essa gigantesca gal\u00e1xia esconde em seus mist\u00e9rios, e planetas quase incont\u00e1veis. Sabemos que ela est\u00e1 distante, mas ser\u00e1 que algum dia nossa ra\u00e7a poder\u00e1 ir atr\u00e1s de novos mundos em meio a esse colosso universal?<\/p>\n<p>Para saber mais sobre o cosmos e muito mais, \u00e9 bem simples. Fique antenado no nosso blog, e n\u00e3o deixe de nos procurar no Facebook!<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Acompanhe nosso Blog<\/a><\/p>\n<p>Um bom presente para quem faz anivers\u00e1rio em Maio \u00e9 uma estrela. Isso mesmo, hoje voc\u00ea pode presentear algu\u00e9m com uma! Entenda como.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/order\/en\/giftpack\">D\u00ea nome a uma estrela<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A gal\u00e1xia de Andr\u00f4meda, ainda que sendo a mais pr\u00f3xima da nossa, fica a mais de 2,5 milh\u00f5es de anos-luz de nosso planeta. Ela recebeu esse nome por sua proximidade com a constela\u00e7\u00e3o de Andr\u00f4meda que, por sua vez, recebeu esse nome por conta da uma princesa da mitologia grega, que era chamada Andr\u00f4meda. Andr\u00f4meda [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[486],"tags":[545],"class_list":["post-88834","post","type-post","status-publish","format-standard","hentry","category-astronomia-br","tag-galaxia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela<\/title>\n<meta name=\"description\" content=\"A gal\u00e1xia mais pr\u00f3xima da nossa, e que fica a &quot;meros&#039;&#039; 2 milh\u00f5es e meio de anos-luz de dist\u00e2ncia, \u00e9 a gal\u00e1xia de Andr\u00f4meda, uma gal\u00e1xia cheia de mist\u00e9rios!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela\" \/>\n<meta property=\"og:description\" content=\"A gal\u00e1xia mais pr\u00f3xima da nossa, e que fica a &quot;meros&#039;&#039; 2 milh\u00f5es e meio de anos-luz de dist\u00e2ncia, \u00e9 a gal\u00e1xia de Andr\u00f4meda, uma gal\u00e1xia cheia de mist\u00e9rios!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-10T06:00:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T22:12:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda.jpg\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"headline\": \"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela\",\n\t            \"datePublished\": \"2019-05-10T06:00:04+00:00\",\n\t            \"dateModified\": \"2019-05-20T22:12:29+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/\"\n\t            },\n\t            \"wordCount\": 534,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/galaxia-de-andromeda.jpg\",\n\t            \"keywords\": [\n\t                \"gal\u00e1xia\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Astronomia\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/\",\n\t            \"name\": \"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/galaxia-de-andromeda.jpg\",\n\t            \"datePublished\": \"2019-05-10T06:00:04+00:00\",\n\t            \"dateModified\": \"2019-05-20T22:12:29+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"description\": \"A gal\u00e1xia mais pr\u00f3xima da nossa, e que fica a \\\"meros'' 2 milh\u00f5es e meio de anos-luz de dist\u00e2ncia, \u00e9 a gal\u00e1xia de Andr\u00f4meda, uma gal\u00e1xia cheia de mist\u00e9rios!\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/galaxia-de-andromeda.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/galaxia-de-andromeda.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/galaxia-de-andromeda\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronomia\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/astronomia-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela","description":"A gal\u00e1xia mais pr\u00f3xima da nossa, e que fica a \"meros'' 2 milh\u00f5es e meio de anos-luz de dist\u00e2ncia, \u00e9 a gal\u00e1xia de Andr\u00f4meda, uma gal\u00e1xia cheia de mist\u00e9rios!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/","og_locale":"pt_BR","og_type":"article","og_title":"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela","og_description":"A gal\u00e1xia mais pr\u00f3xima da nossa, e que fica a \"meros'' 2 milh\u00f5es e meio de anos-luz de dist\u00e2ncia, \u00e9 a gal\u00e1xia de Andr\u00f4meda, uma gal\u00e1xia cheia de mist\u00e9rios!","og_url":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/","og_site_name":"Online Star Register","article_published_time":"2019-05-10T06:00:04+00:00","article_modified_time":"2019-05-20T22:12:29+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda.jpg","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"headline":"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela","datePublished":"2019-05-10T06:00:04+00:00","dateModified":"2019-05-20T22:12:29+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/"},"wordCount":534,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda.jpg","keywords":["gal\u00e1xia"],"articleSection":["Astronomia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/","url":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/","name":"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda.jpg","datePublished":"2019-05-10T06:00:04+00:00","dateModified":"2019-05-20T22:12:29+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"description":"A gal\u00e1xia mais pr\u00f3xima da nossa, e que fica a \"meros'' 2 milh\u00f5es e meio de anos-luz de dist\u00e2ncia, \u00e9 a gal\u00e1xia de Andr\u00f4meda, uma gal\u00e1xia cheia de mist\u00e9rios!","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2019\/05\/galaxia-de-andromeda.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Astronomia","item":"https:\/\/osr.org\/pt-br\/astronomia-br\/"},{"@type":"ListItem","position":3,"name":"Gal\u00e1xia de Andr\u00f4meda: tudo o que voc\u00ea precisa saber sobre ela"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/88834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=88834"}],"version-history":[{"count":4,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/88834\/revisions"}],"predecessor-version":[{"id":89639,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/88834\/revisions\/89639"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=88834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=88834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=88834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}