{"id":46518,"date":"2018-05-13T08:00:40","date_gmt":"2018-05-13T06:00:40","guid":{"rendered":"https:\/\/osr.org\/?p=46518\/"},"modified":"2020-05-05T17:01:45","modified_gmt":"2020-05-05T15:01:45","slug":"cores-de-estrelas","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/","title":{"rendered":"Cores de estrelas: um universo para admirar e inspirar"},"content":{"rendered":"<h2><span style=\"color: #15acdf\">Por que existem diversas cores de estrelas?<br \/>\n<\/span><\/h2>\n<p>Voc\u00ea com certeza j\u00e1 percebeu, ao observar o c\u00e9u, que nem todas as estrelas brilham da mesma maneira, certo? E quando falamos de uma estrela em particular, pode-se afirmar que sua diferente colora\u00e7\u00e3o est\u00e1 intimamente relacionada \u00e0 sua temperatura.<\/p>\n<p>Observa-se que as estrelas azuladas s\u00e3o as mais quentes, e isso se justifica sabendo que elas possuem como elemento qu\u00edmico predominante na origem da cor o h\u00e9lio ionizado. Ent\u00e3o podemos dizer que a cor sempre ir\u00e1 variar por conta da temperatura, podendo uma estrela ter in\u00fameras cores, tais como vermelho, azul, laranja, verde, roxo, enfim, todas as cores do arco-\u00edris.<\/p>\n<p>Uma curiosidade interessante \u00e9 que uma mesma estrela pode variar de cor ao longo de sua exist\u00eancia, pois sua identidade n\u00e3o \u00e9 permanente. A tend\u00eancia \u00e9 que com o passar dos anos ela esfrie lentamente, dando lugar de destaque para as mais novas, normalmente as mais quentes.<\/p>\n<p>Durante toda sua vida, que pode ser verdadeiros bilh\u00f5es de anos, uma estrela pode mudar, e muito! Suas temperaturas variam, e muito.<\/p>\n<h2><span style=\"color: #15acdf\">Muito al\u00e9m das cores de estrela<br \/>\n<\/span><\/h2>\n<p>A verdade \u00e9 que a luz vis\u00edvel, as microondas, as ondas de raios, TV, raios ultravioletas, e outros diversos exemplos s\u00e3o verdadeiros fen\u00f4menos f\u00edsicos de uma mesma natureza. Todos pertencem \u00e0 categoria de ondas eletromagn\u00e9ticas.<\/p>\n<p>Uma simples constata\u00e7\u00e3o \u00e9 que todo o corpo, que esteja em uma determinada temperatura, sejam estrelas, chapas de ferro, pessoas ou at\u00e9 mesmo o gelo, irradiam ondas eletromagn\u00e9ticas em um padr\u00e3o que \u00e9 caracter\u00edstico da temperatura em quest\u00e3o.<\/p>\n<p>Caso um equipamento fosse usado para medir o espectro dessas ondas todas, voc\u00ea veria que emite de seu corpo quase todo o tipo de onda. Mas porque voc\u00ea n\u00e3o brilha no escuro, j\u00e1 que emite luz? Isso acontece porque seu corpo emite uma parcela \u00ednfima de luz, que \u00e9 imposs\u00edvel de ser detectada usando apenas a vis\u00e3o.<\/p>\n<p>Essas ondas luminosas s\u00e3o informa\u00e7\u00e3o pura e, na verdade, as estrelas tamb\u00e9m emitem essas luzes, de uma maneira bem mais intensa. E todas as informa\u00e7\u00f5es que temos sobre estrelas bem dessas ondas emitidas, e pelas cores das estrelas. Quanto mais azul, mais quente e mais jovem \u00e9 a estrela, enquanto as mais vermelhas s\u00e3o mais velhas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46511 size-full\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial.png\" alt=\"\" width=\"756\" height=\"383\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial.png 756w, https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial-300x152.png 300w\" sizes=\"auto, (max-width: 756px) 100vw, 756px\" \/><\/p>\n<h2><span style=\"color: #15acdf\">Observando as cores de estrelas<br \/>\n<\/span><\/h2>\n<p>Uma pr\u00e1tica interessante para poder perceber o que est\u00e1 sendo dito aqui \u00e9 a simples observa\u00e7\u00e3o do c\u00e9u, claro, em uma noite que seja limpa e de prefer\u00eancia em uma zona de C\u00e9u Negro, longe de qualquer ilumina\u00e7\u00e3o artificial.<\/p>\n<p>Com um telesc\u00f3pio, ou at\u00e9 mesmo como um bin\u00f3culo, voc\u00ea pode ca\u00e7ar estrelas coloridas no c\u00e9u, comparando-as umas com as outras. Pode ser um pouco complicado no come\u00e7o classificar as estrelas usando apenas a colora\u00e7\u00e3o delas, ainda mais usando um bin\u00f3culo.<\/p>\n<p>Mas n\u00e3o se preocupe, voc\u00ea deve apenas comparar, n\u00e3o classificar. Escolha tr\u00eas estrelas e verifique qual delas \u00e9 a mais azulada, qual a mais avermelhada, e v\u00e1 repetindo esse processo para poder adquirir uma maior habilidade de identifica\u00e7\u00e3o da cor-temperatura-idade das estrelas.<\/p>\n<p>Se voc\u00ea gostou de saber mais sobre as cores de estrelas, voc\u00ea vai gostar de saber como dar nome a uma estrela:<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Compre uma estrela!<\/a><\/p>\n<p>Fique por dentro de tudo que acontece no universo:<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Acesse nosso blog!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por que existem diversas cores de estrelas? Voc\u00ea com certeza j\u00e1 percebeu, ao observar o c\u00e9u, que nem todas as estrelas brilham da mesma maneira, certo? E quando falamos de uma estrela em particular, pode-se afirmar que sua diferente colora\u00e7\u00e3o est\u00e1 intimamente relacionada \u00e0 sua temperatura. Observa-se que as estrelas azuladas s\u00e3o as mais quentes, [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[486],"tags":[489,490],"class_list":["post-46518","post","type-post","status-publish","format-standard","hentry","category-astronomia-br","tag-ceu","tag-estrelas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cores de estrelas: um universo para admirar e inspirar<\/title>\n<meta name=\"description\" content=\"Se voc\u00ea ama saber tudo sobre o universo com certeza voc\u00ea j\u00e1 se pegou pensando sobre as cores de estrelas que existem. Hoje voc\u00ea vai poder descobrir finalmente quais s\u00e3o!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cores de estrelas: um universo para admirar e inspirar\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea ama saber tudo sobre o universo com certeza voc\u00ea j\u00e1 se pegou pensando sobre as cores de estrelas que existem. Hoje voc\u00ea vai poder descobrir finalmente quais s\u00e3o!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-13T06:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-05T15:01:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial.png\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/9f29f2ddba5f99500c50af0d4640c807\"\n\t            },\n\t            \"headline\": \"Cores de estrelas: um universo para admirar e inspirar\",\n\t            \"datePublished\": \"2018-05-13T06:00:40+00:00\",\n\t            \"dateModified\": \"2020-05-05T15:01:45+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/\"\n\t            },\n\t            \"wordCount\": 576,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Universo-Genial.png\",\n\t            \"keywords\": [\n\t                \"C\u00e9u\",\n\t                \"Estrelas\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Astronomia\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/\",\n\t            \"name\": \"Cores de estrelas: um universo para admirar e inspirar\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Universo-Genial.png\",\n\t            \"datePublished\": \"2018-05-13T06:00:40+00:00\",\n\t            \"dateModified\": \"2020-05-05T15:01:45+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/9f29f2ddba5f99500c50af0d4640c807\"\n\t            },\n\t            \"description\": \"Se voc\u00ea ama saber tudo sobre o universo com certeza voc\u00ea j\u00e1 se pegou pensando sobre as cores de estrelas que existem. Hoje voc\u00ea vai poder descobrir finalmente quais s\u00e3o!\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Universo-Genial.png\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Universo-Genial.png\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/cores-de-estrelas\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronomia\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/astronomia-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Cores de estrelas: um universo para admirar e inspirar\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/9f29f2ddba5f99500c50af0d4640c807\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cores de estrelas: um universo para admirar e inspirar","description":"Se voc\u00ea ama saber tudo sobre o universo com certeza voc\u00ea j\u00e1 se pegou pensando sobre as cores de estrelas que existem. Hoje voc\u00ea vai poder descobrir finalmente quais s\u00e3o!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/","og_locale":"pt_BR","og_type":"article","og_title":"Cores de estrelas: um universo para admirar e inspirar","og_description":"Se voc\u00ea ama saber tudo sobre o universo com certeza voc\u00ea j\u00e1 se pegou pensando sobre as cores de estrelas que existem. Hoje voc\u00ea vai poder descobrir finalmente quais s\u00e3o!","og_url":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/","og_site_name":"Online Star Register","article_published_time":"2018-05-13T06:00:40+00:00","article_modified_time":"2020-05-05T15:01:45+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial.png","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/9f29f2ddba5f99500c50af0d4640c807"},"headline":"Cores de estrelas: um universo para admirar e inspirar","datePublished":"2018-05-13T06:00:40+00:00","dateModified":"2020-05-05T15:01:45+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/"},"wordCount":576,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial.png","keywords":["C\u00e9u","Estrelas"],"articleSection":["Astronomia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/","url":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/","name":"Cores de estrelas: um universo para admirar e inspirar","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial.png","datePublished":"2018-05-13T06:00:40+00:00","dateModified":"2020-05-05T15:01:45+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/9f29f2ddba5f99500c50af0d4640c807"},"description":"Se voc\u00ea ama saber tudo sobre o universo com certeza voc\u00ea j\u00e1 se pegou pensando sobre as cores de estrelas que existem. Hoje voc\u00ea vai poder descobrir finalmente quais s\u00e3o!","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial.png","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2018\/05\/Universo-Genial.png"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/cores-de-estrelas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Astronomia","item":"https:\/\/osr.org\/pt-br\/astronomia-br\/"},{"@type":"ListItem","position":3,"name":"Cores de estrelas: um universo para admirar e inspirar"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/9f29f2ddba5f99500c50af0d4640c807","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/46518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=46518"}],"version-history":[{"count":10,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/46518\/revisions"}],"predecessor-version":[{"id":46666,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/46518\/revisions\/46666"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=46518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=46518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=46518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}