{"id":220145,"date":"2023-01-27T08:00:33","date_gmt":"2023-01-27T06:00:33","guid":{"rendered":"https:\/\/osr.org\/?p=220145"},"modified":"2023-07-20T16:07:17","modified_gmt":"2023-07-20T14:07:17","slug":"cor-de-2023","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/","title":{"rendered":"Cor de 2023: como a energia do violeta vai mudar o ano"},"content":{"rendered":"<p>Segundo estudos, a cor de 2023 \u00e9 o violeta. Essa cor \u00e9 respons\u00e1vel por transmutar energias ruins em energias positivas, e a tonalidade tamb\u00e9m est\u00e1 fortemente ligada ao autoconhecimento, \u00e0 sinceridade, ao respeito e \u00e0 prosperidade.<\/p>\n<p>Essa \u00e9 uma cor que nos conecta com nossa ess\u00eancia em busca por mudan\u00e7as. De acordo com especialistas, a cor violeta est\u00e1 diretamente associada ao nosso chakra coron\u00e1rio, que \u00e9 o s\u00e9timo chakra do nosso corpo, e fica localizado no topo da nossa cabe\u00e7a.<\/p>\n<p>Esse chakra est\u00e1 associado com nossa espiritualidade, e tamb\u00e9m a caracter\u00edsticas positivas que nos acalmam e tranquilizam. Essa \u00e9 uma cor que tem um elevado poder de mudar e transmutar energias negativas em energia positiva. A cor de 2023 tem a capacidade de elevar nossa consci\u00eancia para que ela possa alcan\u00e7ar um limite muito maior, gerando mudan\u00e7as muito importantes dentro de nossas vidas.<\/p>\n<div id=\"attachment_220272\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-220272\" class=\"size-full wp-image-220272\" title=\"cor de 2023 1\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1.jpg\" alt=\"\" width=\"758\" height=\"505\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1.jpg 758w, https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1-300x200.jpg 300w, https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1-640x426.jpg 640w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><p id=\"caption-attachment-220272\" class=\"wp-caption-text\"><p class=\"caption-text\">Pixabay<\/p><\/figure> Pixabay<\/p><\/div>\n<h2>Como utilizar a cor de 2023<\/h2>\n<p>Utilizar esse tom na decora\u00e7\u00e3o de ambientes \u00e9 uma excelente ideia. 2023 vai ser um ano extremamente importante para posicionar melhor essa cor em sua vida, j\u00e1 que ela vai lhe ajudar a ter mais foco, mais concentra\u00e7\u00e3o e tranquilidade. Al\u00e9m de objetos para sua casa, voc\u00ea tamb\u00e9m pode usar esse tom na hora de se vestir.<\/p>\n<p>Acess\u00f3rios e roupas tamb\u00e9m v\u00e3o ser muito importantes, j\u00e1 que v\u00e3o ajud\u00e1-lo a sentir na pele o aspecto positivo dessa cor, que com certeza vai trazer muita energia positiva para o seu ano. A cor de 2023 \u00e9 vibrante e cheia de energia, e ela vai trazer mudan\u00e7as positivas para o seu dia a dia, seja aplicada nas suas roupas ou na sua decora\u00e7\u00e3o.<\/p>\n<p>Entender sobre a energia das cores \u00e9 essencial para quem quer alcan\u00e7ar novos patamares na vida. Claro, a influ\u00eancia das vibra\u00e7\u00f5es de cada cor sempre vai ser bem sutil, mas ainda assim \u00e9 algo que deve ser sempre levado em considera\u00e7\u00e3o. Tamb\u00e9m \u00e9 importante lembrar que qualquer tipo de mudan\u00e7a sempre vem a longo prazo, e nada \u00e9 imediato, principalmente quando falamos sobre<a href=\"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/cromoterapia\/?currency=BRL\"> cromoterapia.<\/a><\/p>\n<p>Inclusive, em nosso blog temos v\u00e1rios artigos que falam sobre o assunto. Que tal conferir? Assim voc\u00ea pode aprender mais sobre como usar as cores a seu favor.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Conhe\u00e7a nosso Blog!<\/a><\/p>\n<p>Aqui na OSR tamb\u00e9m temos uma sugest\u00e3o de presente simplesmente inesquec\u00edvel, veja como us\u00e1-la para homenagear quem voc\u00ea ama!<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Nomeie uma estrela!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo estudos, a cor de 2023 \u00e9 o violeta. Essa cor \u00e9 respons\u00e1vel por transmutar energias ruins em energias positivas, e a tonalidade tamb\u00e9m est\u00e1 fortemente ligada ao autoconhecimento, \u00e0 sinceridade, ao respeito e \u00e0 prosperidade. Essa \u00e9 uma cor que nos conecta com nossa ess\u00eancia em busca por mudan\u00e7as. De acordo com especialistas, a [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1429],"tags":[1475,866],"class_list":["post-220145","post","type-post","status-publish","format-standard","hentry","category-news-pt-br","tag-1475","tag-cromoterapia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cor de 2023: como a energia do violeta vai mudar o ano<\/title>\n<meta name=\"description\" content=\"Confira agora o que especialistas t\u00eam a dizer sobre como a cor de 2023 vai impactar o ano de v\u00e1rias formas diferentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cor de 2023: como a energia do violeta vai mudar o ano\" \/>\n<meta property=\"og:description\" content=\"Confira agora o que especialistas t\u00eam a dizer sobre como a cor de 2023 vai impactar o ano de v\u00e1rias formas diferentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T06:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-20T14:07:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1.jpg\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"headline\": \"Cor de 2023: como a energia do violeta vai mudar o ano\",\n\t            \"datePublished\": \"2023-01-27T06:00:33+00:00\",\n\t            \"dateModified\": \"2023-07-20T14:07:17+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/\"\n\t            },\n\t            \"wordCount\": 423,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/cor-de-2023-1.jpg\",\n\t            \"keywords\": [\n\t                \"2023\",\n\t                \"cromoterapia\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Not\u00edcias\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/\",\n\t            \"name\": \"Cor de 2023: como a energia do violeta vai mudar o ano\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/cor-de-2023-1.jpg\",\n\t            \"datePublished\": \"2023-01-27T06:00:33+00:00\",\n\t            \"dateModified\": \"2023-07-20T14:07:17+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"description\": \"Confira agora o que especialistas t\u00eam a dizer sobre como a cor de 2023 vai impactar o ano de v\u00e1rias formas diferentes.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/cor-de-2023-1.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/cor-de-2023-1.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/cor-de-2023\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Not\u00edcias\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/news-pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Cor de 2023: como a energia do violeta vai mudar o ano\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cor de 2023: como a energia do violeta vai mudar o ano","description":"Confira agora o que especialistas t\u00eam a dizer sobre como a cor de 2023 vai impactar o ano de v\u00e1rias formas diferentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/","og_locale":"pt_BR","og_type":"article","og_title":"Cor de 2023: como a energia do violeta vai mudar o ano","og_description":"Confira agora o que especialistas t\u00eam a dizer sobre como a cor de 2023 vai impactar o ano de v\u00e1rias formas diferentes.","og_url":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/","og_site_name":"Online Star Register","article_published_time":"2023-01-27T06:00:33+00:00","article_modified_time":"2023-07-20T14:07:17+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1.jpg","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"headline":"Cor de 2023: como a energia do violeta vai mudar o ano","datePublished":"2023-01-27T06:00:33+00:00","dateModified":"2023-07-20T14:07:17+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/"},"wordCount":423,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1.jpg","keywords":["2023","cromoterapia"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/","url":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/","name":"Cor de 2023: como a energia do violeta vai mudar o ano","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1.jpg","datePublished":"2023-01-27T06:00:33+00:00","dateModified":"2023-07-20T14:07:17+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"description":"Confira agora o que especialistas t\u00eam a dizer sobre como a cor de 2023 vai impactar o ano de v\u00e1rias formas diferentes.","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/cor-de-2023-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/cor-de-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/osr.org\/pt-br\/news-pt-br\/"},{"@type":"ListItem","position":3,"name":"Cor de 2023: como a energia do violeta vai mudar o ano"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/220145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=220145"}],"version-history":[{"count":7,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/220145\/revisions"}],"predecessor-version":[{"id":220584,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/220145\/revisions\/220584"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=220145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=220145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=220145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}