{"id":220143,"date":"2023-01-20T08:00:10","date_gmt":"2023-01-20T06:00:10","guid":{"rendered":"https:\/\/osr.org\/?p=220143"},"modified":"2023-07-20T16:07:19","modified_gmt":"2023-07-20T14:07:19","slug":"biomimetica","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/","title":{"rendered":"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza"},"content":{"rendered":"<p>Voc\u00ea sabia que existem pain\u00e9is coletores de energia solar que funcionam imitando os girass\u00f3is, com o seu m\u00e9todo peculiar de captar a luz? Sabia que as l\u00e2mpadas de LED foram criadas inspiradas na radia\u00e7\u00e3o dos vagalumes? Pois \u00e9, essas inven\u00e7\u00f5es acabaram surgindo atrav\u00e9s da biomim\u00e9tica, uma ci\u00eancia que \u00e9 baseada na natureza.<\/p>\n<p>A palavra biomim\u00e9tica significa Imita\u00e7\u00e3o da Vida. Ou seja, trata-se de uma ci\u00eancia que imita de forma consciente a genialidade da natureza, tentando criar solu\u00e7\u00f5es inovadoras para produtos, e sistemas de v\u00e1rios tipos. Essa \u00e9 a filosofia por tr\u00e1s da ci\u00eancia de olhar para a natureza e para a<a href=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/curiosidades-sobre-a-terra\/?currency=BRL\"> Terra<\/a> como um modelo, e uma mentora para os projetos.<\/p>\n<p>Por conta disso, essa ci\u00eancia est\u00e1 sempre ligada diretamente com solu\u00e7\u00f5es que n\u00e3o prejudicam o meio ambiente &#8211; muito pelo contr\u00e1rio, s\u00e3o solu\u00e7\u00f5es que s\u00e3o regeneradoras e solid\u00e1rias. Embora a biomim\u00e9tica n\u00e3o seja t\u00e3o conhecida no Brasil, ela j\u00e1 foi apontada como uma das cinco principais tend\u00eancias que v\u00e3o orientar o nosso futuro.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-220209\" title=\"Biomim\u00e9tica\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica.jpg\" alt=\"\" width=\"758\" height=\"505\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica.jpg 758w, https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica-300x200.jpg 300w, https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica-640x426.jpg 640w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><\/p>\n<h2>O que podemos esperar da biomim\u00e9tica para o futuro<\/h2>\n<p>A biomim\u00e9tica tem a capacidade de nos dar a chance de aprender com a m\u00e3e natureza, encontrando a melhor maneira para a sustentabilidade. Esse estudo da natureza j\u00e1 encontrou v\u00e1rias solu\u00e7\u00f5es diferentes, e entender esses princ\u00edpios \u00e9 algo que ajuda muito a humanidade a evoluir, criando tecnologias cada vez mais avan\u00e7adas, e que consomem menos energia.<\/p>\n<p>Para o futuro, podemos esperar que a biomim\u00e9tica nos guie para uma vida mais ligada \u00e0 natureza. Ao inv\u00e9s de destrui-la, vamos estar criando condi\u00e7\u00f5es prop\u00edcias para a evolu\u00e7\u00e3o humana e tamb\u00e9m para a vida, de forma geral.<\/p>\n<p>A biomim\u00e9tica ensina que n\u00e3o \u00e9 necess\u00e1rio apenas ser sustent\u00e1vel, \u00e9 importante que a humanidade seja regeneradora. A pr\u00e1tica da regenera\u00e7\u00e3o, por meio da inova\u00e7\u00e3o em tecnologias verdes ativas, \u00e9 um dos principais objetivos dessa ci\u00eancia. Essas tecnologias t\u00eam a capacidade de provocar uma ruptura de padr\u00e3o, mudando o <em>status quo<\/em> j\u00e1 estabelecido no mercado.<\/p>\n<p>Existem muitos exemplos diferentes do uso da biomim\u00e9tica em v\u00e1rios tipos de setores. Em especial, essa ci\u00eancia pode ser aplicada facilmente em estruturas como pr\u00e9dios e conjuntos habitacionais, assim como no setor de energia. Essa \u00e9 uma ci\u00eancia que est\u00e1 engatinhando ainda, mas tem muita capacidade de mudar o mundo.<\/p>\n<p>Se voc\u00ea gosta de acompanhar esse tipo de curiosidade, confira no nosso blog.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Conhe\u00e7a nosso Blog!<\/a><\/p>\n<p>Caso voc\u00ea queira presentear algu\u00e9m com algo inesquec\u00edvel, aqui na nossa plataforma temos uma \u00f3tima sugest\u00e3o.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Nomeie uma estrela!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabia que existem pain\u00e9is coletores de energia solar que funcionam imitando os girass\u00f3is, com o seu m\u00e9todo peculiar de captar a luz? Sabia que as l\u00e2mpadas de LED foram criadas inspiradas na radia\u00e7\u00e3o dos vagalumes? Pois \u00e9, essas inven\u00e7\u00f5es acabaram surgindo atrav\u00e9s da biomim\u00e9tica, uma ci\u00eancia que \u00e9 baseada na natureza. A palavra biomim\u00e9tica [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1429],"tags":[630],"class_list":["post-220143","post","type-post","status-publish","format-standard","hentry","category-news-pt-br","tag-futuro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza<\/title>\n<meta name=\"description\" content=\"A biomim\u00e9tica tem a capacidade de trazer solu\u00e7\u00f5es modernas inspiradas na pr\u00f3pria natureza de uma forma regeneradora. Veja como ela funciona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza\" \/>\n<meta property=\"og:description\" content=\"A biomim\u00e9tica tem a capacidade de trazer solu\u00e7\u00f5es modernas inspiradas na pr\u00f3pria natureza de uma forma regeneradora. Veja como ela funciona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-20T06:00:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-20T14:07:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica.jpg\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"headline\": \"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza\",\n\t            \"datePublished\": \"2023-01-20T06:00:10+00:00\",\n\t            \"dateModified\": \"2023-07-20T14:07:19+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/\"\n\t            },\n\t            \"wordCount\": 468,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Biomimetica.jpg\",\n\t            \"keywords\": [\n\t                \"futuro\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Not\u00edcias\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/\",\n\t            \"name\": \"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Biomimetica.jpg\",\n\t            \"datePublished\": \"2023-01-20T06:00:10+00:00\",\n\t            \"dateModified\": \"2023-07-20T14:07:19+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"description\": \"A biomim\u00e9tica tem a capacidade de trazer solu\u00e7\u00f5es modernas inspiradas na pr\u00f3pria natureza de uma forma regeneradora. Veja como ela funciona.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Biomimetica.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Biomimetica.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/biomimetica\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Guia da OSR\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/osr-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza","description":"A biomim\u00e9tica tem a capacidade de trazer solu\u00e7\u00f5es modernas inspiradas na pr\u00f3pria natureza de uma forma regeneradora. Veja como ela funciona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/","og_locale":"pt_BR","og_type":"article","og_title":"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza","og_description":"A biomim\u00e9tica tem a capacidade de trazer solu\u00e7\u00f5es modernas inspiradas na pr\u00f3pria natureza de uma forma regeneradora. Veja como ela funciona.","og_url":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/","og_site_name":"Online Star Register","article_published_time":"2023-01-20T06:00:10+00:00","article_modified_time":"2023-07-20T14:07:19+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica.jpg","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"headline":"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza","datePublished":"2023-01-20T06:00:10+00:00","dateModified":"2023-07-20T14:07:19+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/"},"wordCount":468,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica.jpg","keywords":["futuro"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/","url":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/","name":"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica.jpg","datePublished":"2023-01-20T06:00:10+00:00","dateModified":"2023-07-20T14:07:19+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"description":"A biomim\u00e9tica tem a capacidade de trazer solu\u00e7\u00f5es modernas inspiradas na pr\u00f3pria natureza de uma forma regeneradora. Veja como ela funciona.","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/12\/Biomimetica.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/biomimetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Guia da OSR","item":"https:\/\/osr.org\/pt-br\/osr-br\/"},{"@type":"ListItem","position":3,"name":"Biomim\u00e9tica: solu\u00e7\u00f5es sustent\u00e1veis inspiradas na natureza"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/220143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=220143"}],"version-history":[{"count":5,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/220143\/revisions"}],"predecessor-version":[{"id":220716,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/220143\/revisions\/220716"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=220143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=220143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=220143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}