{"id":203220,"date":"2022-07-08T08:00:23","date_gmt":"2022-07-08T06:00:23","guid":{"rendered":"https:\/\/osr.org\/?p=203220"},"modified":"2022-06-29T04:13:05","modified_gmt":"2022-06-29T02:13:05","slug":"novo-sistema-solar","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/","title":{"rendered":"Novo sistema solar \u00e9 descoberto em &#8220;bolhas azuis&#8221; no universo"},"content":{"rendered":"<p>Os astr\u00f4nomos da Universidade do Arizona acabaram de identificar cinco exemplos de um novo sistema solar que nunca haviam sido classificados anteriormente. Esses sistemas solares n\u00e3o fazem parte de gal\u00e1xias, existindo de uma maneira totalmente isolada.<\/p>\n<p>Esse tipo recente de novo sistema solar cont\u00e9m apenas estrelas jovens e azuis, que ficam distribu\u00eddas em padr\u00f5es irregulares, e parecem existir em um isolamento nunca visto antes, sem ter qualquer tipo de gal\u00e1xia-m\u00e3e potencial.<\/p>\n<p>Esse novo sistema, segundo os astr\u00f4nomos norte-americanos, tem apar\u00eancia de bolhas azuis atrav\u00e9s do telesc\u00f3pio, e tem o tamanho de pequenas gal\u00e1xias. Esse novo sistema solar fica localizado dentro de um aglomerado de gal\u00e1xias virgens, e ao todo foram identificados cinco sistemas diferentes.<\/p>\n<p>Esses sistemas est\u00e3o totalmente separados de qualquer tipo de outra<a href=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/galaxia-de-andromeda\/?currency=BRL\"> gal\u00e1xia<\/a> em potencial por mais de 300 mil anos luz, tornando extremamente dif\u00edcil identificar a origem desses sistemas. O universo \u00e9 muito mais complicado e dif\u00edcil de ser compreendido do que se imagina.<\/p>\n<div id=\"attachment_203415\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-203415\" class=\"size-full wp-image-203415\" title=\"Novo sistema solar\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar.png\" alt=\"Novo sistema solar\" width=\"758\" height=\"511\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar.png 758w, https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar-300x202.png 300w, https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar-640x431.png 640w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><p id=\"caption-attachment-203415\" class=\"wp-caption-text\"><p class=\"caption-text\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:The_population_of_Blue-Stellar-System_in_the_Virgo_Cluster.jpg\">NASA\/ESA &amp; Hubble<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/2.5\">CC BY-SA 2.5<\/a>, via Wikimedia Commons<\/p><\/figure> Pixabay<\/p><\/div>\n<h2>Novo sistema solar: o que ele pode significar para os cientistas?<\/h2>\n<p>A presen\u00e7a desse sistema solar at\u00edpico pode trazer indicativos diferentes para os cientistas. A simples presen\u00e7a desse tipo de sistema solar pode mudar completamente a forma como vemos o universo, e como identificamos a cria\u00e7\u00e3o de novas gal\u00e1xias e sistemas estelares.<\/p>\n<p>Ainda \u00e9 muito cedo para definir qual o verdadeiro impacto desse novo sistema solar, por\u00e9m, estudos ser\u00e3o feitos em cima dessas descobertas para poder definir com mais precis\u00e3o como esse tipo de evento celestial pode acontecer.<\/p>\n<p>Verdade seja dita, astr\u00f4nomos e cientistas sabem muito pouco sobre como o universo funciona. A grande maioria das descobertas e dogmas cient\u00edficos s\u00e3o meras conjecturas feitas em cima de c\u00e1lculos matem\u00e1ticos, para tentar determinar como cada um desses eventos surgiu, e como o universo teve seu in\u00edcio.<\/p>\n<p>Se voc\u00ea \u00e9 o tipo de pessoa que adora ler mais sobre o nosso universo, e adora curiosidades sobre as gal\u00e1xias e os planetas, com certeza vai gostar bastante do nosso blog. Nele, voc\u00ea vai encontrar artigos dos mais diferentes tipos, indo desde astronomia at\u00e9 astrologia, e muito mais.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Conhe\u00e7a nosso Blog!<\/a><\/p>\n<p>Al\u00e9m disso, temos tamb\u00e9m uma dica de presente muito interessante para quem ama as estrelas. Confira.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Nomeie uma estrela!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os astr\u00f4nomos da Universidade do Arizona acabaram de identificar cinco exemplos de um novo sistema solar que nunca haviam sido classificados anteriormente. Esses sistemas solares n\u00e3o fazem parte de gal\u00e1xias, existindo de uma maneira totalmente isolada. Esse tipo recente de novo sistema solar cont\u00e9m apenas estrelas jovens e azuis, que ficam distribu\u00eddas em padr\u00f5es irregulares, [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[486],"tags":[516,556,1112],"class_list":["post-203220","post","type-post","status-publish","format-standard","hentry","category-astronomia-br","tag-astronomia","tag-ciencia","tag-sistema-solar-pt-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo sistema solar descoberto em &quot;bolhas azuis&quot; no universo<\/title>\n<meta name=\"description\" content=\"Um novo sistema solar foi descoberto, e est\u00e1 fazendo a comunidade cient\u00edfica recalcular os princ\u00edpios conhecidos do universo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo sistema solar descoberto em &quot;bolhas azuis&quot; no universo\" \/>\n<meta property=\"og:description\" content=\"Um novo sistema solar foi descoberto, e est\u00e1 fazendo a comunidade cient\u00edfica recalcular os princ\u00edpios conhecidos do universo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-08T06:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar.png\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"headline\": \"Novo sistema solar \u00e9 descoberto em &#8220;bolhas azuis&#8221; no universo\",\n\t            \"datePublished\": \"2022-07-08T06:00:23+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/\"\n\t            },\n\t            \"wordCount\": 412,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Novo-sistema-solar.png\",\n\t            \"keywords\": [\n\t                \"astronomia\",\n\t                \"ciencia\",\n\t                \"sistema solar\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Astronomia\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/\",\n\t            \"name\": \"Novo sistema solar descoberto em \\\"bolhas azuis\\\" no universo\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Novo-sistema-solar.png\",\n\t            \"datePublished\": \"2022-07-08T06:00:23+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"description\": \"Um novo sistema solar foi descoberto, e est\u00e1 fazendo a comunidade cient\u00edfica recalcular os princ\u00edpios conhecidos do universo.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Novo-sistema-solar.png\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Novo-sistema-solar.png\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/novo-sistema-solar\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronomia\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/astronomia-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Novo sistema solar \u00e9 descoberto em &#8220;bolhas azuis&#8221; no universo\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo sistema solar descoberto em \"bolhas azuis\" no universo","description":"Um novo sistema solar foi descoberto, e est\u00e1 fazendo a comunidade cient\u00edfica recalcular os princ\u00edpios conhecidos do universo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo sistema solar descoberto em \"bolhas azuis\" no universo","og_description":"Um novo sistema solar foi descoberto, e est\u00e1 fazendo a comunidade cient\u00edfica recalcular os princ\u00edpios conhecidos do universo.","og_url":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/","og_site_name":"Online Star Register","article_published_time":"2022-07-08T06:00:23+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar.png","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"headline":"Novo sistema solar \u00e9 descoberto em &#8220;bolhas azuis&#8221; no universo","datePublished":"2022-07-08T06:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/"},"wordCount":412,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar.png","keywords":["astronomia","ciencia","sistema solar"],"articleSection":["Astronomia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/","url":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/","name":"Novo sistema solar descoberto em \"bolhas azuis\" no universo","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar.png","datePublished":"2022-07-08T06:00:23+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"description":"Um novo sistema solar foi descoberto, e est\u00e1 fazendo a comunidade cient\u00edfica recalcular os princ\u00edpios conhecidos do universo.","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar.png","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/06\/Novo-sistema-solar.png"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/novo-sistema-solar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Astronomia","item":"https:\/\/osr.org\/pt-br\/astronomia-br\/"},{"@type":"ListItem","position":3,"name":"Novo sistema solar \u00e9 descoberto em &#8220;bolhas azuis&#8221; no universo"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/203220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=203220"}],"version-history":[{"count":5,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/203220\/revisions"}],"predecessor-version":[{"id":203640,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/203220\/revisions\/203640"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=203220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=203220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=203220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}