{"id":198356,"date":"2022-06-27T08:00:01","date_gmt":"2022-06-27T06:00:01","guid":{"rendered":"https:\/\/osr.org\/?p=198356"},"modified":"2022-05-27T19:12:28","modified_gmt":"2022-05-27T17:12:28","slug":"dieta-anti-inflamatoria","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/","title":{"rendered":"Dieta anti-inflamat\u00f3ria para melhorar a sua vida"},"content":{"rendered":"<p>Voc\u00ea deve estar se perguntando o que \u00e9 uma dieta anti-inflamat\u00f3ria. Trata-se de uma verdadeira reeduca\u00e7\u00e3o alimentar, que tem como principal objetivo a redu\u00e7\u00e3o da inflama\u00e7\u00e3o cr\u00f4nica, relacionada a doen\u00e7as como hipertens\u00e3o, ansiedade, diabetes tipo 2, e tamb\u00e9m depress\u00e3o.<\/p>\n<p>\u00c9, na verdade, muito mais um estilo de alimenta\u00e7\u00e3o do que um regime espec\u00edfico. De maneira geral, essa dieta segue o estilo das ilhas mediterr\u00e2neas, e tem um foco grande em gorduras saud\u00e1veis, alimentos nutritivos, e carboidratos de baixa glicemia.<\/p>\n<p>Por mais que seja uma dieta bem expansiva, a dieta anti-inflamat\u00f3ria ainda assim requer que voc\u00ea retire alguns <a href=\"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/culinaria-holistica\/?currency=BRL\">alimentos<\/a> do seu dia a dia. Por exemplo, sucos ado\u00e7ados e refrigerantes devem ser retirados, assim como carnes processadas, bebidas alco\u00f3licas e carboidratos refinados.<\/p>\n<p>Segundo nutricionistas, para prevenir a inflama\u00e7\u00e3o com uma dieta anti-inflamat\u00f3ria \u00e9 importante manter uma alimenta\u00e7\u00e3o que tenha como base alimentos nutritivos. A dieta anti-inflamat\u00f3ria deve fornecer para voc\u00ea um equil\u00edbrio saud\u00e1vel de gordura, carboidrato, prote\u00edna, minerais vitaminas e tamb\u00e9m fibras.<\/p>\n<div id=\"attachment_198170\" style=\"width: 764px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-198170\" class=\"size-full wp-image-198170\" title=\"Dieta anti-inflamat\u00f3ria\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria.jpg\" alt=\"Dieta anti-inflamat\u00f3ria\" width=\"754\" height=\"516\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria.jpg 754w, https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria-300x205.jpg 300w, https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria-640x438.jpg 640w\" sizes=\"auto, (max-width: 754px) 100vw, 754px\" \/><p id=\"caption-attachment-198170\" class=\"wp-caption-text\"><p class=\"caption-text\">Pixabay<\/p><\/figure> Pixabay<\/p><\/div>\n<h2>Dieta anti-inflamat\u00f3ria: alimentos que n\u00e3o podem faltar na sua dieta<\/h2>\n<p>O primeiro alimento s\u00e3o as uvas roxas, que possuem compostos vegetais com v\u00e1rias propriedades anti-inflamat\u00f3rias. Essas uvas tamb\u00e9m podem ajudar a diminuir o risco de doen\u00e7as card\u00edacas.<\/p>\n<p>Frutas vermelhas tamb\u00e9m s\u00e3o muito interessantes para quem quer uma dieta anti-inflamat\u00f3ria. Elas conseguem ajudar a preparar suas c\u00e9lulas para responder de forma melhor a qualquer tipo de informa\u00e7\u00e3o futura.<\/p>\n<p>O br\u00f3colis tamb\u00e9m \u00e9 um excelente aliado, assim como outros vegetais cruc\u00edferos. O potencial que esses vegetais t\u00eam j\u00e1 foram extensivamente estudados, e esses estudos comprovaram que essa classe de vegetal pode at\u00e9 mesmo retardar o desenvolvimento do c\u00e2ncer.<\/p>\n<p>Os tomates s\u00e3o uma fonte rica de licopeno, que \u00e9 um nutriente com propriedades antioxidantes, que trazem grandes benef\u00edcios para a sa\u00fade do cora\u00e7\u00e3o, assim como prote\u00e7\u00e3o contra queimaduras solares e v\u00e1rios tipos de c\u00e2ncer.<\/p>\n<p>Por fim, gr\u00e3os integrais que cont\u00e9m muita fibra, pot\u00e1ssio, e tamb\u00e9m prote\u00ednas, s\u00e3o muito indicados na dieta antioxidante. Esses s\u00e3o gr\u00e3os que t\u00eam o \u00edndice glic\u00eamico baixo, minimizando os efeitos inflamat\u00f3rios que geralmente est\u00e3o associadas a flutua\u00e7\u00f5es de glicose.<\/p>\n<p>Se voc\u00ea gostou dessas dicas de hoje sobre bem-estar, muito provavelmente vai gostar das outras mat\u00e9rias que est\u00e3o em nosso blog.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Conhe\u00e7a nosso Blog!<\/a><\/p>\n<p>E se voc\u00ea quer presentear algu\u00e9m com algo inesquec\u00edvel, temos uma sugest\u00e3o bem interessante aqui em nossa plataforma.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Nomeie uma estrela!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea deve estar se perguntando o que \u00e9 uma dieta anti-inflamat\u00f3ria. Trata-se de uma verdadeira reeduca\u00e7\u00e3o alimentar, que tem como principal objetivo a redu\u00e7\u00e3o da inflama\u00e7\u00e3o cr\u00f4nica, relacionada a doen\u00e7as como hipertens\u00e3o, ansiedade, diabetes tipo 2, e tamb\u00e9m depress\u00e3o. \u00c9, na verdade, muito mais um estilo de alimenta\u00e7\u00e3o do que um regime espec\u00edfico. De maneira [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[847],"tags":[886,885],"class_list":["post-198356","post","type-post","status-publish","format-standard","hentry","category-bem-estar","tag-bem-estar","tag-felicidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dieta anti-inflamat\u00f3ria para melhorar a sua vida<\/title>\n<meta name=\"description\" content=\"Veja como a dieta anti-inflamat\u00f3ria pode ajudar na sua vida, e quais s\u00e3o os principais alimentos consumidos nela.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dieta anti-inflamat\u00f3ria para melhorar a sua vida\" \/>\n<meta property=\"og:description\" content=\"Veja como a dieta anti-inflamat\u00f3ria pode ajudar na sua vida, e quais s\u00e3o os principais alimentos consumidos nela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-27T06:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria.jpg\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"headline\": \"Dieta anti-inflamat\u00f3ria para melhorar a sua vida\",\n\t            \"datePublished\": \"2022-06-27T06:00:01+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/\"\n\t            },\n\t            \"wordCount\": 464,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Dieta-anti-inflamatoria.jpg\",\n\t            \"keywords\": [\n\t                \"bem-estar\",\n\t                \"felicidade\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Bem-estar\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/\",\n\t            \"name\": \"Dieta anti-inflamat\u00f3ria para melhorar a sua vida\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Dieta-anti-inflamatoria.jpg\",\n\t            \"datePublished\": \"2022-06-27T06:00:01+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"description\": \"Veja como a dieta anti-inflamat\u00f3ria pode ajudar na sua vida, e quais s\u00e3o os principais alimentos consumidos nela.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Dieta-anti-inflamatoria.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Dieta-anti-inflamatoria.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/dieta-anti-inflamatoria\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Bem-estar\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/bem-estar\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Dieta anti-inflamat\u00f3ria para melhorar a sua vida\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dieta anti-inflamat\u00f3ria para melhorar a sua vida","description":"Veja como a dieta anti-inflamat\u00f3ria pode ajudar na sua vida, e quais s\u00e3o os principais alimentos consumidos nela.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/","og_locale":"pt_BR","og_type":"article","og_title":"Dieta anti-inflamat\u00f3ria para melhorar a sua vida","og_description":"Veja como a dieta anti-inflamat\u00f3ria pode ajudar na sua vida, e quais s\u00e3o os principais alimentos consumidos nela.","og_url":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/","og_site_name":"Online Star Register","article_published_time":"2022-06-27T06:00:01+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria.jpg","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"headline":"Dieta anti-inflamat\u00f3ria para melhorar a sua vida","datePublished":"2022-06-27T06:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/"},"wordCount":464,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria.jpg","keywords":["bem-estar","felicidade"],"articleSection":["Bem-estar"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/","url":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/","name":"Dieta anti-inflamat\u00f3ria para melhorar a sua vida","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria.jpg","datePublished":"2022-06-27T06:00:01+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"description":"Veja como a dieta anti-inflamat\u00f3ria pode ajudar na sua vida, e quais s\u00e3o os principais alimentos consumidos nela.","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/05\/Dieta-anti-inflamatoria.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/dieta-anti-inflamatoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Bem-estar","item":"https:\/\/osr.org\/pt-br\/bem-estar\/"},{"@type":"ListItem","position":3,"name":"Dieta anti-inflamat\u00f3ria para melhorar a sua vida"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/198356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=198356"}],"version-history":[{"count":3,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/198356\/revisions"}],"predecessor-version":[{"id":198377,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/198356\/revisions\/198377"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=198356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=198356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=198356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}