{"id":195327,"date":"2022-05-27T08:00:15","date_gmt":"2022-05-27T06:00:15","guid":{"rendered":"https:\/\/osr.org\/?p=195327"},"modified":"2022-04-24T00:44:55","modified_gmt":"2022-04-23T22:44:55","slug":"neurocosmeticos","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/","title":{"rendered":"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar"},"content":{"rendered":"<p>Por acaso voc\u00ea sabia que al\u00e9m de controlar a temperatura do seu corpo, proteg\u00ea-lo contra agentes externos, e tamb\u00e9m auxiliar na regula\u00e7\u00e3o de nossa temperatura, a nossa pele tem um poder incr\u00edvel de nos fazer feliz? Recheada com transmissores e receptores a tudo que acontece \u00e0 sua volta, a pele est\u00e1 muito mais conectada ao seu sistema nervoso do que voc\u00ea imagina, e \u00e9 por isso que os neurocosm\u00e9ticos t\u00eam feito tanto sucesso.<\/p>\n<p>Atrav\u00e9s dos neurocosm\u00e9ticos, uma ci\u00eancia que combina a cosmetologia com a neurologia, alguns produtos de cuidados com a pele t\u00eam se tornado muito atrativos para ajudar no tratamento de problemas mentais. Esses produtos contam com ativos que ajudam a despertar receptores na sua pele, liberando endorfina e estimulando uma <a href=\"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/banho-gelado\/?currency=BRL\">sensa\u00e7\u00e3o de bem-estar.<\/a><\/p>\n<p>Apesar dos neurocosm\u00e9ticos serem pouco explorados pela ind\u00fastria, eles j\u00e1 fazem parte do portf\u00f3lio de v\u00e1rias marcas brasileiras. Mas ser\u00e1 que isso tudo funciona mesmo? \u00c9 isso que n\u00f3s vamos avaliar agora.<\/p>\n<div id=\"attachment_195569\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-195569\" class=\"size-full wp-image-195569\" title=\"Neurocosm\u00e9ticos 1\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1.jpg\" alt=\"Neurocosm\u00e9ticos\" width=\"758\" height=\"505\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1.jpg 758w, https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1-300x200.jpg 300w, https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1-640x426.jpg 640w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><p id=\"caption-attachment-195569\" class=\"wp-caption-text\"><p class=\"caption-text\">Pixabay<\/p><\/figure> Pixabay<\/p><\/div>\n<h2>Neurocosm\u00e9ticos: uma revolu\u00e7\u00e3o na ind\u00fastria ou apenas mais um produto na sua estante?<\/h2>\n<p>Segundo as marcas que j\u00e1 est\u00e3o produzindo esse tipo de produto, a verdade \u00e9 que os cremes e s\u00e9runs de tratamento para a pele possuem ativos que estimulam a produ\u00e7\u00e3o do horm\u00f4nio beta endorfina. Esse horm\u00f4nio \u00e9, na verdade, um neurotransmissor que vai atuar na sua pele, de uma maneira reparadora, e tamb\u00e9m possui propriedades anti-estresse.<\/p>\n<p>Existem v\u00e1rias subst\u00e2ncias diferentes, que podem ser utilizadas para alcan\u00e7ar esse objetivo, como por exemplo, ess\u00eancia de s\u00e2ndalo, alecrim, lavanda, e at\u00e9 mesmo os polifen\u00f3is do cacau. Claro, cada uma dessas subst\u00e2ncias tem seus pr\u00f3prios efeitos, mas de forma geral, todas elas v\u00e3o induzi-lo a uma sensa\u00e7\u00e3o de bem-estar, trazendo mais conforto para a sua vida.<\/p>\n<p>Como estamos vivendo em uma \u00e9poca onde problemas mentais t\u00eam se tornado cada vez mais graves, esse tipo de produto acaba sendo uma excelente escolha para quem quer ter mais sa\u00fade mental. Claro, ele n\u00e3o vai resolver nenhum problema que tenha acontecido em sua vida, entretanto, vai trazer mais tranquilidade e felicidade para o seu dia a dia.<\/p>\n<p>Se voc\u00ea quer ver mais mat\u00e9rias sobre bem-estar, confira nosso blog agora mesmo e verifique nossos artigos.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Conhe\u00e7a nosso Blog!<\/a><\/p>\n<p>Caso voc\u00ea esteja procurando um bom presente para dar a quem ama, mas ainda n\u00e3o sabe o que escolher, temos uma sugest\u00e3o.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Nomeie uma estrela!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por acaso voc\u00ea sabia que al\u00e9m de controlar a temperatura do seu corpo, proteg\u00ea-lo contra agentes externos, e tamb\u00e9m auxiliar na regula\u00e7\u00e3o de nossa temperatura, a nossa pele tem um poder incr\u00edvel de nos fazer feliz? Recheada com transmissores e receptores a tudo que acontece \u00e0 sua volta, a pele est\u00e1 muito mais conectada ao [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[847],"tags":[886],"class_list":["post-195327","post","type-post","status-publish","format-standard","hentry","category-bem-estar","tag-bem-estar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar<\/title>\n<meta name=\"description\" content=\"Os neurocosm\u00e9ticos prometem trazer uma mudan\u00e7a significativa para o setor do bem-estar. Veja o que eles podem fazer!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar\" \/>\n<meta property=\"og:description\" content=\"Os neurocosm\u00e9ticos prometem trazer uma mudan\u00e7a significativa para o setor do bem-estar. Veja o que eles podem fazer!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-27T06:00:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1.jpg\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"headline\": \"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar\",\n\t            \"datePublished\": \"2022-05-27T06:00:15+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/\"\n\t            },\n\t            \"wordCount\": 440,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Neurocosmeticos-1.jpg\",\n\t            \"keywords\": [\n\t                \"bem-estar\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Bem-estar\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/\",\n\t            \"name\": \"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Neurocosmeticos-1.jpg\",\n\t            \"datePublished\": \"2022-05-27T06:00:15+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"description\": \"Os neurocosm\u00e9ticos prometem trazer uma mudan\u00e7a significativa para o setor do bem-estar. Veja o que eles podem fazer!\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Neurocosmeticos-1.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Neurocosmeticos-1.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/bem-estar\\\/neurocosmeticos\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Bem-estar\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/bem-estar\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar","description":"Os neurocosm\u00e9ticos prometem trazer uma mudan\u00e7a significativa para o setor do bem-estar. Veja o que eles podem fazer!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/","og_locale":"pt_BR","og_type":"article","og_title":"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar","og_description":"Os neurocosm\u00e9ticos prometem trazer uma mudan\u00e7a significativa para o setor do bem-estar. Veja o que eles podem fazer!","og_url":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/","og_site_name":"Online Star Register","article_published_time":"2022-05-27T06:00:15+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1.jpg","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"headline":"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar","datePublished":"2022-05-27T06:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/"},"wordCount":440,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1.jpg","keywords":["bem-estar"],"articleSection":["Bem-estar"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/","url":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/","name":"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1.jpg","datePublished":"2022-05-27T06:00:15+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"description":"Os neurocosm\u00e9ticos prometem trazer uma mudan\u00e7a significativa para o setor do bem-estar. Veja o que eles podem fazer!","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2022\/04\/Neurocosmeticos-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/neurocosmeticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Bem-estar","item":"https:\/\/osr.org\/pt-br\/bem-estar\/"},{"@type":"ListItem","position":3,"name":"Neurocosm\u00e9ticos: a mais recente novidade para o bem-estar"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/195327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=195327"}],"version-history":[{"count":9,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/195327\/revisions"}],"predecessor-version":[{"id":195770,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/195327\/revisions\/195770"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=195327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=195327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=195327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}