{"id":176022,"date":"2021-11-15T08:00:21","date_gmt":"2021-11-15T06:00:21","guid":{"rendered":"https:\/\/osr.org\/?p=176022"},"modified":"2023-07-20T16:07:55","modified_gmt":"2023-07-20T14:07:55","slug":"estacoes-do-ano","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/","title":{"rendered":"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?"},"content":{"rendered":"<p>N\u00f3s vivemos durante as esta\u00e7\u00f5es do ano sem nem reparar nelas, muitas vezes. Entretanto, antigamente as coisas eram bem diferentes, principalmente para os gregos antigos! Muitas culturas ao redor do mundo inteiro reconheciam a primavera como o come\u00e7o do ano, como o come\u00e7o do ver\u00e3o.<\/p>\n<p>O pr\u00f3prio nome, <a href=\"https:\/\/osr.org\/pt-br\/blog\/bem-estar\/primavera-2021\/?currency=BRL\">primavera<\/a>, significa &#8221;antes do ver\u00e3o&#8221;. O outono, para eles, era o fim desse per\u00edodo quente e f\u00e9rtil. Desde que a humanidade come\u00e7ou a desenvolver meios de cultivo, a necessidade de entender os melhores momentos para plantar acabou se fazendo presente.<\/p>\n<p>Esse momento de necessidade foi chamado de Revolu\u00e7\u00e3o Agr\u00edcola, quando o ser humano come\u00e7ou a plantar, a ler a natureza ao seu redor e a identificar as esta\u00e7\u00f5es do ano. Mas eles precisavam tamb\u00e9m de uma origem para esses momentos do ano, e uma dessas hist\u00f3rias de origem mais famosas \u00e9 a grega.<\/p>\n<div id=\"attachment_176147\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-176147\" class=\"size-full wp-image-176147\" title=\"Esta\u00e7\u00f5es do ano 1\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1.jpg\" alt=\"Esta\u00e7\u00f5es do ano\" width=\"758\" height=\"400\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1.jpg 758w, https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1-300x158.jpg 300w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><p id=\"caption-attachment-176147\" class=\"wp-caption-text\"><p class=\"caption-text\">Pixabay<\/p><\/figure> Pixabay<\/p><\/div>\n<h2>Como os gregos explicaram as esta\u00e7\u00f5es do ano<\/h2>\n<p>Essa hist\u00f3ria come\u00e7ou com Pers\u00e9fone, que era uma das filhas de Zeus. Pers\u00e9fone era a respons\u00e1vel por trazer alimentos para os povos do mundo inteiro, mas em um belo dia, ela estava passeando quando encontrou outro deus.<\/p>\n<p>Esse deus era Hades, o deus do submundo. Hades n\u00e3o \u00e9, como muitos pensam, um vil\u00e3o. Pelo contr\u00e1rio! O reino de Hades \u00e9 um lugar onde cada um recebe o que merece, de acordo com a vida que levou.<\/p>\n<p>Mas, voltando a hist\u00f3ria, Hades acabou se apaixonando por Pers\u00e9fone, e a levou para um passeio no submundo. O problema \u00e9 que Dem\u00e9ter, m\u00e3e de Pers\u00e9fone, n\u00e3o gostou dessa ideia, j\u00e1 que ela n\u00e3o sabia onde a filha estava. Ela revirou o mundo, e ent\u00e3o declarou que, caso Pers\u00e9fone n\u00e3o voltasse, ela se retiraria do mundo.<\/p>\n<p>O problema \u00e9 que Dem\u00e9ter \u00e9 a deusa da fertilidade, ou seja, sem ela, o mundo provavelmente passaria fome. Dito e feito. A confus\u00e3o foi tanta que Hades acabou libertando Pers\u00e9fone do submundo. Por\u00e9m, at\u00e9 isso acontecer, ela j\u00e1 havia se casado com ele.<\/p>\n<p>Por conta disso, um acordo foi feito, e durante duas partes do ano, Pers\u00e9fone ficaria com sua m\u00e3e. Essas duas partes s\u00e3o o ver\u00e3o e a primavera, enquanto o inverno e outono s\u00e3o as \u00e9pocas em que ela fica com Hades!<\/p>\n<p>Bem interessante essa hist\u00f3ria n\u00e9? Em nosso blog tem mais hist\u00f3rias como essa!<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Conhe\u00e7a nosso Blog!<\/a><\/p>\n<p>Caso voc\u00ea esteja procurando por um bom presente para quem voc\u00ea ama, vem com a gente que temos uma indica\u00e7\u00e3o incr\u00edvel!<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Nomeie uma estrela!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00f3s vivemos durante as esta\u00e7\u00f5es do ano sem nem reparar nelas, muitas vezes. Entretanto, antigamente as coisas eram bem diferentes, principalmente para os gregos antigos! Muitas culturas ao redor do mundo inteiro reconheciam a primavera como o come\u00e7o do ano, como o come\u00e7o do ver\u00e3o. O pr\u00f3prio nome, primavera, significa &#8221;antes do ver\u00e3o&#8221;. O outono, [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1429],"tags":[1280,830,569],"class_list":["post-176022","post","type-post","status-publish","format-standard","hentry","category-news-pt-br","tag-estacoes","tag-inverno","tag-primavera"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?<\/title>\n<meta name=\"description\" content=\"As esta\u00e7\u00f5es do ano eram explicadas de forma bem diferente pelos gregos antigos, e hoje voc\u00ea vai aprender como eles faziam isso!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?\" \/>\n<meta property=\"og:description\" content=\"As esta\u00e7\u00f5es do ano eram explicadas de forma bem diferente pelos gregos antigos, e hoje voc\u00ea vai aprender como eles faziam isso!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-15T06:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-20T14:07:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1.jpg\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"headline\": \"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?\",\n\t            \"datePublished\": \"2021-11-15T06:00:21+00:00\",\n\t            \"dateModified\": \"2023-07-20T14:07:55+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/\"\n\t            },\n\t            \"wordCount\": 467,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Estacoes-do-ano-1.jpg\",\n\t            \"keywords\": [\n\t                \"Esta\u00e7\u00f5es\",\n\t                \"Inverno\",\n\t                \"primavera\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Not\u00edcias\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/\",\n\t            \"name\": \"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Estacoes-do-ano-1.jpg\",\n\t            \"datePublished\": \"2021-11-15T06:00:21+00:00\",\n\t            \"dateModified\": \"2023-07-20T14:07:55+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"description\": \"As esta\u00e7\u00f5es do ano eram explicadas de forma bem diferente pelos gregos antigos, e hoje voc\u00ea vai aprender como eles faziam isso!\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Estacoes-do-ano-1.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Estacoes-do-ano-1.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/news-pt-br\\\/estacoes-do-ano\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Not\u00edcias\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/news-pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?","description":"As esta\u00e7\u00f5es do ano eram explicadas de forma bem diferente pelos gregos antigos, e hoje voc\u00ea vai aprender como eles faziam isso!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/","og_locale":"pt_BR","og_type":"article","og_title":"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?","og_description":"As esta\u00e7\u00f5es do ano eram explicadas de forma bem diferente pelos gregos antigos, e hoje voc\u00ea vai aprender como eles faziam isso!","og_url":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/","og_site_name":"Online Star Register","article_published_time":"2021-11-15T06:00:21+00:00","article_modified_time":"2023-07-20T14:07:55+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1.jpg","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"headline":"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?","datePublished":"2021-11-15T06:00:21+00:00","dateModified":"2023-07-20T14:07:55+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/"},"wordCount":467,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1.jpg","keywords":["Esta\u00e7\u00f5es","Inverno","primavera"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/","url":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/","name":"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1.jpg","datePublished":"2021-11-15T06:00:21+00:00","dateModified":"2023-07-20T14:07:55+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"description":"As esta\u00e7\u00f5es do ano eram explicadas de forma bem diferente pelos gregos antigos, e hoje voc\u00ea vai aprender como eles faziam isso!","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2021\/10\/Estacoes-do-ano-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/news-pt-br\/estacoes-do-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/osr.org\/pt-br\/news-pt-br\/"},{"@type":"ListItem","position":3,"name":"Esta\u00e7\u00f5es do ano: como os gregos antigos as explicavam?"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/176022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=176022"}],"version-history":[{"count":7,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/176022\/revisions"}],"predecessor-version":[{"id":176442,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/176022\/revisions\/176442"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=176022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=176022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=176022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}