{"id":162491,"date":"2021-06-04T08:00:24","date_gmt":"2021-06-04T06:00:24","guid":{"rendered":"https:\/\/osr.org\/?p=162491"},"modified":"2021-05-31T22:26:47","modified_gmt":"2021-05-31T20:26:47","slug":"dia-dos-namorados-ideias","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/","title":{"rendered":"Dia dos namorados ideias: dicas para surpreender seu amor"},"content":{"rendered":"<p>Hoje vamos falar sobre dia dos namorados ideias! O dia t\u00e3o esperado est\u00e1 chegando, e se voc\u00ea est\u00e1 querendo encontrar algo especial para a pessoa que voc\u00ea ama, veio ao lugar certo! Vamos dar algumas ideias, e voc\u00ea pode simplesmente escolher uma delas, ou v\u00e1rias, misturar da forma que voc\u00ea achar melhor e criar um momento fant\u00e1stico para quem voc\u00ea realmente ama!<\/p>\n<p>Bom, ent\u00e3o vamos come\u00e7ar. Vamos dar uns minutos para voc\u00ea pegar uma caneta e um papel, j\u00e1 que voc\u00ea pode ter as suas pr\u00f3prias ideias enquanto est\u00e1 lendo as nossas sugest\u00f5es para esse dia incr\u00edvel!<\/p>\n<div id=\"attachment_162608\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-162608\" class=\"size-full wp-image-162608\" title=\"dia dos namorados ideias\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias.jpg\" alt=\"dia dos namorados ideias\" width=\"758\" height=\"253\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias.jpg 758w, https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias-300x100.jpg 300w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><p id=\"caption-attachment-162608\" class=\"wp-caption-text\"><p class=\"caption-text\">Pixabay<\/p><\/figure> Pixabay<\/p><\/div>\n<h2>Dia dos namorados ideias: dicas incr\u00edveis para voc\u00ea<\/h2>\n<p>\u200cDica n\u00famero 1: Uma lasanha deliciosa para o inverno! &#8211; Pode parecer algo simples, mas quem j\u00e1 comeu uma lasanha, feita com amor e carinho, no friozinho do inverno, com direito a um bom vinho, sabe bem como essa refei\u00e7\u00e3o pode ser fant\u00e1stica. E voc\u00ea pode fazer a lasanha como voc\u00ea bem quiser, seja uma lasanha vegana, ou at\u00e9 mesmo uma lasanha de bacon com calabresa e fil\u00e9 mignon. Seja criativo, fa\u00e7a uma mesa linda, decorada e transforme esse dia em algo incr\u00edvel!<\/p>\n<p>Dica n\u00famero 2: Presentes online surpresa! &#8211; Convenhamos, hoje em dia \u00e9 muito simples comprar qualquer coisa pela internet, mas o dif\u00edcil \u00e9 surpreender a pessoa com isso. Tem que ser um presente bem diferente para ser memor\u00e1vel, e felizmente, a gente aqui da OSR tem exatamente o que voc\u00ea precisa para poder causar essa incr\u00edvel impress\u00e3o.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Nomeie uma estrela!<\/a><\/p>\n<p>Dica n\u00famero 3: Agende uma viagem! &#8211; Ainda estamos em tempos de quarentena e tudo mais, por\u00e9m, o lado legal \u00e9 que voc\u00ea pode agendar uma viagem, ou at\u00e9 mesmo um final de semana em um hotel legal, para daqui alguns meses, quando a grande maioria das pessoas estiverem vacinadas. Al\u00e9m de ser uma boa surpresa, vai ser um bom recome\u00e7o para quando a vida voltar a ser como era antes.<\/p>\n<p>E a\u00ed? Voc\u00ea curtiu as nossas dicas para o dia dos <a href=\"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-2020\/?currency=BRL\">namorados<\/a> ideias? Ent\u00e3o fica a sugest\u00e3o de voc\u00ea dar uma navegada em nosso blog, que tem diversas mat\u00e9rias super divertidas e dicas incr\u00edveis para voc\u00ea!<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Conhe\u00e7a nosso Blog!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje vamos falar sobre dia dos namorados ideias! O dia t\u00e3o esperado est\u00e1 chegando, e se voc\u00ea est\u00e1 querendo encontrar algo especial para a pessoa que voc\u00ea ama, veio ao lugar certo! Vamos dar algumas ideias, e voc\u00ea pode simplesmente escolher uma delas, ou v\u00e1rias, misturar da forma que voc\u00ea achar melhor e criar um [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[488],"tags":[855,818,497],"class_list":["post-162491","post","type-post","status-publish","format-standard","hentry","category-dicas-presentes","tag-amor","tag-namorados","tag-presentes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dia dos namorados ideias: dicas para surpreender seu amor<\/title>\n<meta name=\"description\" content=\"Ter um bom dia dos namorados ideias com a pessoa que voc\u00ea mais ama pode ser algo dif\u00edcil de planejar, mas n\u00e3o se preocupe! Vamos te ajudar!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia dos namorados ideias: dicas para surpreender seu amor\" \/>\n<meta property=\"og:description\" content=\"Ter um bom dia dos namorados ideias com a pessoa que voc\u00ea mais ama pode ser algo dif\u00edcil de planejar, mas n\u00e3o se preocupe! Vamos te ajudar!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-04T06:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias.jpg\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"headline\": \"Dia dos namorados ideias: dicas para surpreender seu amor\",\n\t            \"datePublished\": \"2021-06-04T06:00:24+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/\"\n\t            },\n\t            \"wordCount\": 397,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/dia-dos-namorados-ideias.jpg\",\n\t            \"keywords\": [\n\t                \"amor\",\n\t                \"namorados\",\n\t                \"Presentes\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Dicas &amp; Presentes\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/\",\n\t            \"name\": \"Dia dos namorados ideias: dicas para surpreender seu amor\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/dia-dos-namorados-ideias.jpg\",\n\t            \"datePublished\": \"2021-06-04T06:00:24+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\"\n\t            },\n\t            \"description\": \"Ter um bom dia dos namorados ideias com a pessoa que voc\u00ea mais ama pode ser algo dif\u00edcil de planejar, mas n\u00e3o se preocupe! Vamos te ajudar!\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/dia-dos-namorados-ideias.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/dia-dos-namorados-ideias.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/dicas-presentes\\\/dia-dos-namorados-ideias\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Dicas &amp; Presentes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/dicas-presentes\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Dia dos namorados ideias: dicas para surpreender seu amor\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/769f6d5d2a02b6dc674d59915929b5ec\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia dos namorados ideias: dicas para surpreender seu amor","description":"Ter um bom dia dos namorados ideias com a pessoa que voc\u00ea mais ama pode ser algo dif\u00edcil de planejar, mas n\u00e3o se preocupe! Vamos te ajudar!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/","og_locale":"pt_BR","og_type":"article","og_title":"Dia dos namorados ideias: dicas para surpreender seu amor","og_description":"Ter um bom dia dos namorados ideias com a pessoa que voc\u00ea mais ama pode ser algo dif\u00edcil de planejar, mas n\u00e3o se preocupe! Vamos te ajudar!","og_url":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/","og_site_name":"Online Star Register","article_published_time":"2021-06-04T06:00:24+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias.jpg","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"headline":"Dia dos namorados ideias: dicas para surpreender seu amor","datePublished":"2021-06-04T06:00:24+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/"},"wordCount":397,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias.jpg","keywords":["amor","namorados","Presentes"],"articleSection":["Dicas &amp; Presentes"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/","url":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/","name":"Dia dos namorados ideias: dicas para surpreender seu amor","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias.jpg","datePublished":"2021-06-04T06:00:24+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec"},"description":"Ter um bom dia dos namorados ideias com a pessoa que voc\u00ea mais ama pode ser algo dif\u00edcil de planejar, mas n\u00e3o se preocupe! Vamos te ajudar!","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2021\/05\/dia-dos-namorados-ideias.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/dicas-presentes\/dia-dos-namorados-ideias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Dicas &amp; Presentes","item":"https:\/\/osr.org\/pt-br\/dicas-presentes\/"},{"@type":"ListItem","position":3,"name":"Dia dos namorados ideias: dicas para surpreender seu amor"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/769f6d5d2a02b6dc674d59915929b5ec","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/162491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=162491"}],"version-history":[{"count":6,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/162491\/revisions"}],"predecessor-version":[{"id":162864,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/162491\/revisions\/162864"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=162491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=162491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=162491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}