{"id":142951,"date":"2020-11-13T08:00:23","date_gmt":"2020-11-13T06:00:23","guid":{"rendered":"https:\/\/osr.org\/?p=142951"},"modified":"2020-11-04T02:16:12","modified_gmt":"2020-11-04T00:16:12","slug":"a-ciencia-mais-antiga-da-humanidade","status":"publish","type":"post","link":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/","title":{"rendered":"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia"},"content":{"rendered":"<p>N\u00e3o \u00e9 a toa que a a ci\u00eancia mais antiga da humanidade \u00e9 a astronomia. Observar os astros celestes n\u00e3o s\u00f3 traz conhecimentos c\u00f3smicos, mas principalmente conhecimentos sobre a terra em que vivemos.<\/p>\n<p>As vezes \u00e9 comum esquecermos que fazemos parte de um gigantesco universo. A Terra n\u00e3o \u00e9 um sistema isolado, n\u00f3s estamos dentro de uma gal\u00e1xia afinal de contas, e gra\u00e7as a fen\u00f4menos externos podemos experienciar diferentes esta\u00e7\u00f5es ao redor do mundo inteiro.<\/p>\n<p>Cada uma dessas esta\u00e7\u00f5es possibilita que determinada \u00e1rea de nosso planeta passe por mudan\u00e7as incr\u00edveis. E tudo isso foi descoberto por meio da astronomia, que inclusive nos deu a no\u00e7\u00e3o exata de tempo. N\u00e3o \u00e9 a toa que esta \u00e9 a ci\u00eancia mais antiga da humanidade.<\/p>\n<h2><span style=\"color: #15acdf\">A ci\u00eancia mais antiga da humanidade e os alicerces de nossa civiliza\u00e7\u00e3o<\/span><\/h2>\n<p>Ap\u00f3s alguns povos explorarem a astronomia, ela acabou se tornando um dos mais resistentes alicerces em v\u00e1rios pa\u00edses. \u00cdndia, China, Egito, Europa e muitos outros lugares tiveram suas formas independentes de astronomia.<\/p>\n<p>Com a constru\u00e7\u00e3o de grandes cidades, e com o advento da agricultura, a marca\u00e7\u00e3o do tempo para uma boa planta\u00e7\u00e3o se tornou uma necessidade. A astronomia veio para auxiliar nesse e outros pontos, inclusive servindo como m\u00e9todo de posicionamento.<\/p>\n<div id=\"attachment_142909\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-142909\" class=\"size-full wp-image-142909\" title=\"ci\u00eancia mais antiga da humanidade\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg\" alt=\"ci\u00eancia mais antiga da humanidade\" width=\"758\" height=\"433\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg 758w, https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes-300x171.jpg 300w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><p id=\"caption-attachment-142909\" class=\"wp-caption-text\"><p class=\"caption-text\"><a href=\"https:\/\/wallpapers.com\/wallpapers\/planets-of-the-solar-system-aesthetic-xdofilrz2i5hnvas.html\">Wallpaper by salvatoreamura<\/a> on Wallpapers.com<\/p><\/figure> Pixabay<\/p><\/div>\n<p>As <a href=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/estrelas-no-ceu\/?currency=BRL\">estrelas<\/a> podem servir como uma b\u00fassola, se voc\u00ea souber us\u00e1-las, o que na verdade n\u00e3o \u00e9 t\u00e3o complicado. Al\u00e9m disso, a astronomia sempre esteve diretamente ligada com a religi\u00e3o, e n\u00e3o a toa eventos astron\u00f4micos eram ligados a profecias com grande frequ\u00eancia.<\/p>\n<p>Na \u00e9poca em que nossa civiliza\u00e7\u00e3o estava surgindo, n\u00e3o havia uma clara separa\u00e7\u00e3o entre a astrologia e a astronomia. Isso s\u00f3 foi acontecer recentemente, e ambas as vertentes acabaram seguindo caminhos extremamente diferentes.<\/p>\n<p>Hoje em dia a astronomia tem uma pegada muito mais cient\u00edfica, e \u00e9 por meio dela que estudamos o cosmos de forma intensa. Gigantescos \u00f3rg\u00e3os, como a NASA, surgiram, e agora estamos a poucos passos de realmente colocar os p\u00e9s em outros planetas!<\/p>\n<p>Se voc\u00ea gosta de astronomia e astrologia, n\u00e3o deixe de acompanhar nosso blog.<\/p>\n<p style=\"text-align: center\"><a class=\"button button-blue medium arrow\" href=\"https:\/\/osr.org\/pt-br\/blog\/?currency=BRL\">Conhe\u00e7a nosso Blog!<\/a><\/p>\n<p>As estrelas est\u00e3o te esperando. De verdade. E voc\u00ea pode at\u00e9 nomear uma delas! Aprenda como fazer isso agora!<\/p>\n<p style=\"text-align: center\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/pt-br\/\">Nomeie uma estrela!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o \u00e9 a toa que a a ci\u00eancia mais antiga da humanidade \u00e9 a astronomia. Observar os astros celestes n\u00e3o s\u00f3 traz conhecimentos c\u00f3smicos, mas principalmente conhecimentos sobre a terra em que vivemos. As vezes \u00e9 comum esquecermos que fazemos parte de um gigantesco universo. A Terra n\u00e3o \u00e9 um sistema isolado, n\u00f3s estamos dentro [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[486],"tags":[516,556,490],"class_list":["post-142951","post","type-post","status-publish","format-standard","hentry","category-astronomia-br","tag-astronomia","tag-ciencia","tag-estrelas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia<\/title>\n<meta name=\"description\" content=\"A ci\u00eancia mais antiga da humanidade \u00e9 muito mais presente em seu dia a dia do que voc\u00ea imagina. Ela est\u00e1 at\u00e9 mesmo em seu celular!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia\" \/>\n<meta property=\"og:description\" content=\"A ci\u00eancia mais antiga da humanidade \u00e9 muito mais presente em seu dia a dia do que voc\u00ea imagina. Ela est\u00e1 at\u00e9 mesmo em seu celular!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-13T06:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg\" \/>\n<meta name=\"author\" content=\"Larissa Sanders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Larissa Sanders\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Larissa Sanders\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/9f29f2ddba5f99500c50af0d4640c807\"\n\t            },\n\t            \"headline\": \"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia\",\n\t            \"datePublished\": \"2020-11-13T06:00:23+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/\"\n\t            },\n\t            \"wordCount\": 417,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg\",\n\t            \"keywords\": [\n\t                \"astronomia\",\n\t                \"ciencia\",\n\t                \"Estrelas\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Astronomia\"\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/\",\n\t            \"name\": \"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg\",\n\t            \"datePublished\": \"2020-11-13T06:00:23+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/9f29f2ddba5f99500c50af0d4640c807\"\n\t            },\n\t            \"description\": \"A ci\u00eancia mais antiga da humanidade \u00e9 muito mais presente em seu dia a dia do que voc\u00ea imagina. Ela est\u00e1 at\u00e9 mesmo em seu celular!\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"pt-BR\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/astronomia-br\\\/a-ciencia-mais-antiga-da-humanidade\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronomia\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/astronomia-br\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"pt-BR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/9f29f2ddba5f99500c50af0d4640c807\",\n\t            \"name\": \"Larissa Sanders\",\n\t            \"description\": \"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/pt-br\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/laricsanders\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/pt-br\\\/blog\\\/author\\\/larissa-sanders\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia","description":"A ci\u00eancia mais antiga da humanidade \u00e9 muito mais presente em seu dia a dia do que voc\u00ea imagina. Ela est\u00e1 at\u00e9 mesmo em seu celular!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/","og_locale":"pt_BR","og_type":"article","og_title":"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia","og_description":"A ci\u00eancia mais antiga da humanidade \u00e9 muito mais presente em seu dia a dia do que voc\u00ea imagina. Ela est\u00e1 at\u00e9 mesmo em seu celular!","og_url":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/","og_site_name":"Online Star Register","article_published_time":"2020-11-13T06:00:23+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg","type":"","width":"","height":""}],"author":"Larissa Sanders","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Larissa Sanders","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/#article","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/"},"author":{"name":"Larissa Sanders","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/9f29f2ddba5f99500c50af0d4640c807"},"headline":"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia","datePublished":"2020-11-13T06:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/"},"wordCount":417,"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg","keywords":["astronomia","ciencia","Estrelas"],"articleSection":["Astronomia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/","url":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/","name":"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia","isPartOf":{"@id":"https:\/\/osr.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg","datePublished":"2020-11-13T06:00:23+00:00","author":{"@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/9f29f2ddba5f99500c50af0d4640c807"},"description":"A ci\u00eancia mais antiga da humanidade \u00e9 muito mais presente em seu dia a dia do que voc\u00ea imagina. Ela est\u00e1 at\u00e9 mesmo em seu celular!","breadcrumb":{"@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2020\/11\/astronomia-o-que-e-historia-definicao-e-o-estudo-dos-corpos-celestes.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/pt-br\/blog\/astronomia-br\/a-ciencia-mais-antiga-da-humanidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Astronomia","item":"https:\/\/osr.org\/pt-br\/astronomia-br\/"},{"@type":"ListItem","position":3,"name":"A ci\u00eancia mais antiga da humanidade: um pouco mais sobre a astronomia"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/pt-br\/#website","url":"https:\/\/osr.org\/pt-br\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/osr.org\/pt-br\/#\/schema\/person\/9f29f2ddba5f99500c50af0d4640c807","name":"Larissa Sanders","description":"Larissa Sanders \u00e9 bacharel em Publicidade e Propaganda, com MBA em International Marketing Management. Trabalha na \u00e1rea h\u00e1 12 anos - principalmente escrevendo, editando e traduzindo conte\u00fados digitais. Na OSR, Larissa cria textos sobre astrologia, astronomia e presentes desde 2018, trazendo novidades semanalmente para o blog brasileiro. Ela \u00e9 t\u00e3o apaixonada pelo c\u00e9u, que decidiu ter uma estrela pra chamar de sua, al\u00e9m de uma cole\u00e7\u00e3o de objetos que remetem ao universo, carinhosamente espalhados pelo pr\u00f3prio apartamento. \u201cUnder the sky, under the heavens, there is but one family.\u201d \u2015 Bruce Lee","sameAs":["https:\/\/osr.org\/pt-br\/","https:\/\/www.linkedin.com\/in\/laricsanders\/"],"url":"https:\/\/osr.org\/pt-br\/blog\/author\/larissa-sanders\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/142951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/comments?post=142951"}],"version-history":[{"count":4,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/142951\/revisions"}],"predecessor-version":[{"id":142986,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/posts\/142951\/revisions\/142986"}],"wp:attachment":[{"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/media?parent=142951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/categories?post=142951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/pt-br\/wp-json\/wp\/v2\/tags?post=142951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}