{"id":49800,"date":"2019-01-18T10:44:01","date_gmt":"2019-01-18T08:44:01","guid":{"rendered":"https:\/\/osr.org\/?p=49800\/"},"modified":"2019-07-07T17:46:46","modified_gmt":"2019-07-07T15:46:46","slug":"couronne-australe-caracteristiques-etoiles-principales-mythologie","status":"publish","type":"post","link":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/","title":{"rendered":"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie"},"content":{"rendered":"<p>La constellation de la Couronne australe est d\u00e9j\u00e0 sue d\u2019Eudoxie de Cnide entre 408 et 355 avant J-C et aussi \u00e9voqu\u00e9e dans l\u2019\u0153uvre po\u00e9tique intitul\u00e9e \u00ab\u00a0Les Ph\u00e9nom\u00e8nes d\u2019Aratos\u00a0\u00bb de Soles entre 315 et 245 avant J-C. La constellation de la Couronne australe ne renferme pas d\u2019objets particuli\u00e8rement int\u00e9ressants. Malgr\u00e9 le fait que les chinois identifi\u00e8rent dans l\u2019alignement de ses Etoiles une forme de tortue, son nom provient de l\u2019analogie d\u2019apparence avec la Couronne bor\u00e9ale situ\u00e9e dans l\u2019h\u00e9misph\u00e8re nord. Toutefois, la Couronne australe regorge un ensemble d\u2019aspects non moins importants que nous allons tenter de d\u00e9couvrir.<\/p>\n<h2>Les caract\u00e9ristiques de la constellation de la Couronne australe<\/h2>\n<p>La couronne australe constitue une constellation pas tr\u00e8s grande et qui se situe au niveau de l\u2019h\u00e9misph\u00e8re sud. Int\u00e9gr\u00e9e par Ptol\u00e9m\u00e9e dans son trait\u00e9 d\u2019astronomie Almageste, le nom de la constellation de la Couronne austral est pendant \u00e9galement \u00e0 celui d\u2019une autre constellation appel\u00e9e Couronne bor\u00e9ale. La disposition de ses Etoiles est fonction d\u2019un arc-en-ciel rappelant \u00e9galement une autre couronne.<\/p>\n<p>D\u2019aucun dit qu\u2019il s\u2019agirait m\u00eame de la Couronne du Sagittaire, pas tr\u00e8s loin. La Couronne australe est certainement un diad\u00e8me assez complexe ou simplement une guirlande avec ses feuilles.<\/p>\n<p>La constellation de la Couronne austral est faible avec une magnitude apparente situ\u00e9e entre 4 et 5. La forme de la constellation est\u00a0\u00a0beaucoup moins apparente que celle de la Couronne bor\u00e9ale, sa s\u0153ur. Pour rep\u00e9rer la Couronne australe, il faut partir de Scorpion, du c\u00f4t\u00e9 Est de la queue, mais aussi de Sagittaire, du c\u00f4t\u00e9 sud du cou Nunki. Egalement, la Contour australe est limit\u00e9 par la Voie Lact\u00e9e.<\/p>\n<p>Les auteurs les plus classiques surnomme cette constellation la Couronne du Centaure et ce, d\u00fb au fait que le Sagittaire lui-m\u00eame constitue un centaure. On lui associe sept Etoiles distinctes. Elle est \u00e9galement appel\u00e9e Alaclil al-Genubi par les astronomes arabes ou m\u00eame Al-kubba (la tortue) du fait de la forme circulaire. Du c\u00f4t\u00e9 des astronomes h\u00e9breux, la Couronne australe est surnomm\u00e9e Athora.<\/p>\n<h2>Les \u00e9toiles les plus importantes de la Couronne australe<\/h2>\n<p>Bien que la Couronne australe soit peu pourvue en objets distinguables, il contient bien quelques Etoiles principales. Parmi les Etoiles les plus importantes de la Couronne australe, il y\u2019a l\u2019Alfecca Meridiana ou\u00a0\u03b1\u00a0Coronae Australis. Le nom de cette Etoile est tir\u00e9 de celui de l\u2019Etoile phare de la Couronne bor\u00e9ale, \u00e0 savoir Alphecca, une Etoile qui poss\u00e8de une magnitude 4,11. L\u2019Etoile majeure de la Couronne australe appartient \u00e0 la cat\u00e9gorie<\/p>\n<p>A classique, des lors qu\u2019elle effectue une rotation rapide sue elle-m\u00eame sous une vitesse de 180 km\/s au niveau de l\u2019\u00e9quateur. Autre Etoile principale, c\u2019est le\u00a0k\u00a0Coronae Australis qui est une Etoile double poss\u00e9dant des composantes ayant 5,6 et 6,3 de magnitudes distantes de 21,4\u2019\u2019 visibles au moyen d\u2019un petit t\u00e9lescope.<\/p>\n<p>Parmi les autres Etoiles, on peut \u00e9galement citer le\u00a0\u03b3\u00a0CrA, une Etoile binaire avec une magnitude de 4,23, une p\u00e9riode orbitale de 120 ans et situ\u00e9e a 58 a.l de nous. Le \u03b3\u00a0CrA contient donc deux Etoiles de 5<sup>e<\/sup>\u00a0magnitude et de cat\u00e9gorie F8. On peut aussi le \u03b4\u00a0CrA, une g\u00e9ante orange de classe spectral K1 qui poss\u00e8de une magnitude de 4,57 et qui est s\u00e9par\u00e9 de la Terre par une distance de 175 a.l. Le\u00a0a\u00a0Coronae Australis, de la classe A1, est une Etoile de magnitude 4,1 et qui se trouve \u00e0 130 a.l de la Terre. La \u03b2\u00a0CrA constitue une g\u00e9ante orange de classe K0 \u00e9loign\u00e9e de la Terre \u00e0 pr\u00e8s de 500 a.l. Elle a une magnitude 4,11. Une Etoile \u00e0 neutrons a \u00e9t\u00e9 d\u00e9couverte en 1997 par Hubble, un t\u00e9lescope spatial, une Etoile vue dans le ciel au niveau de la Couronne australe.<\/p>\n<h2>La mythologie de la Constellation de la Couronne australe<\/h2>\n<p>Le secret de vie constitue le plus embl\u00e9matique secret de tout l\u2019univers et des temps. Il n\u2019existe pas d\u2019home encore moins de femme capable de percer ce myst\u00e8re de la vie dans toute sa grandeur. Toutefois, l\u2019humanit\u00e9 est au courant que, et ce depuis bien longtemps, c\u2019est bien la plus \u00e9logieuse m\u00e8re en tout temps, \u00e0 savoir la d\u00e9esse Dana qui repr\u00e9sente la gardienne. De l\u2019abysse de son corps altruiste et monstrueux, \u00e0 la fois \u00e9pouvantable et exaltant, \u00e9taient apparus les premiers dieux et ainsi de suite jusqu\u2019aux mortels.<\/p>\n<p>Dana, la d\u00e9esse dite de la fertilit\u00e9 s\u2019\u00e9tait alli\u00e9e sur Terre avec l\u2019Aub\u00e9pine et se servait de la Couronne australe comme compl\u00e9ment c\u00e9leste, constitu\u00e9e de 7 Etoiles, symboles de la travers\u00e9e entre deux univers. Repr\u00e9sentant la premi\u00e8re m\u00e8re de la l\u00e9gende des dieux et des hommes, la Couronne australe est parfois l\u2019individu le plus egocentrique et le plus cruel du monde. En plus de se croire tout connaitre, elle est persuad\u00e9e de repr\u00e9senter le centre du monde, pour ainsi \u00eatre consid\u00e9r\u00e9 et v\u00e9n\u00e9r\u00e9e.<\/p>\n<p>Elle peut rapidement changer certains aspects banals de la vie en des myst\u00e8res occultes grandioses, qui sont impossibles \u00e0 acc\u00e9der pour les humains. Pour elle, les autres sont des moins que rien. Il apparait v\u00e9ridique que la Couronne australe, quand il s\u2019agit de projeter de la poudre d\u2019Etoiles, est effectivement tr\u00e8s dou\u00e9e, au vu et au su de ses semblables qui tombent souvent dans le pi\u00e8ge du fait de leur na\u00efvet\u00e9 et de leur manque de raisonnement.<\/p>\n<h2>Les autres objets des classes Messier et NGC de la Couronne australe<\/h2>\n<p>Le NGC 6541 constitue un amas globulaire qui se trouve au niveau de l\u2019angle Sud-Ouest de cette constellation dite de la Couronne australe, pas loin de la base du Scorpion. Cet amas globulaire se situe \u00e0 23\u00a0000 ann\u00e9es lumi\u00e8res de la Terre. Autre objet, c\u2019est le NGC 6726-7 qui repr\u00e9sente l\u2019\u00e9l\u00e9ment la plus lumineuse d\u2019une large gamme de n\u00e9buleuses obscures et brillantes et de particules absorbantes au niveau de la constellation de la Couronne australe \u00e0 pr\u00e8s de 7,5 degr\u00e9s au sud de\u00a0z\u00a0SGR. Cette n\u00e9buleuse a \u00e9t\u00e9 identifi\u00e9e par Schmidt en 1861.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La constellation de la Couronne australe est d\u00e9j\u00e0 sue d\u2019Eudoxie de Cnide entre 408 et 355 avant J-C et aussi \u00e9voqu\u00e9e dans l\u2019\u0153uvre po\u00e9tique intitul\u00e9e \u00ab\u00a0Les Ph\u00e9nom\u00e8nes d\u2019Aratos\u00a0\u00bb de Soles entre 315 et 245 avant J-C. La constellation de la Couronne australe ne renferme pas d\u2019objets particuli\u00e8rement int\u00e9ressants. Malgr\u00e9 le fait que les chinois identifi\u00e8rent [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[519],"tags":[],"class_list":["post-49800","post","type-post","status-publish","format-standard","hentry","category-constellations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"La constellation de la Couronne australe est d\u00e9j\u00e0 sue d\u2019Eudoxie de Cnide entre 408 et 355 avant J-C et aussi \u00e9voqu\u00e9e dans l\u2019\u0153uvre po\u00e9tique intitul\u00e9e \u00ab\u00a0Les Ph\u00e9nom\u00e8nes d\u2019Aratos\u00a0\u00bb de Soles entre 315 et 245 avant J-C. La constellation de la Couronne australe ne renferme pas d\u2019objets particuli\u00e8rement int\u00e9ressants. Malgr\u00e9 le fait que les chinois identifi\u00e8rent [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-18T08:44:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-07T15:46:46+00:00\" \/>\n<meta name=\"author\" content=\"Luca Isotta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luca Isotta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/astronomie\\\/constellations\\\/couronne-australe-caracteristiques-etoiles-principales-mythologie\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/astronomie\\\/constellations\\\/couronne-australe-caracteristiques-etoiles-principales-mythologie\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Luca Isotta\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#\\\/schema\\\/person\\\/a75478c8087ac37498b5b3d09f9ec58a\"\n\t            },\n\t            \"headline\": \"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie\",\n\t            \"datePublished\": \"2019-01-18T08:44:01+00:00\",\n\t            \"dateModified\": \"2019-07-07T15:46:46+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/astronomie\\\/constellations\\\/couronne-australe-caracteristiques-etoiles-principales-mythologie\\\/\"\n\t            },\n\t            \"wordCount\": 1079,\n\t            \"articleSection\": [\n\t                \"Constellations\"\n\t            ],\n\t            \"inLanguage\": \"fr-FR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/astronomie\\\/constellations\\\/couronne-australe-caracteristiques-etoiles-principales-mythologie\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/astronomie\\\/constellations\\\/couronne-australe-caracteristiques-etoiles-principales-mythologie\\\/\",\n\t            \"name\": \"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2019-01-18T08:44:01+00:00\",\n\t            \"dateModified\": \"2019-07-07T15:46:46+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#\\\/schema\\\/person\\\/a75478c8087ac37498b5b3d09f9ec58a\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/astronomie\\\/constellations\\\/couronne-australe-caracteristiques-etoiles-principales-mythologie\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"fr-FR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/astronomie\\\/constellations\\\/couronne-australe-caracteristiques-etoiles-principales-mythologie\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/astronomie\\\/constellations\\\/couronne-australe-caracteristiques-etoiles-principales-mythologie\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/fr\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronomie\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/fr\\\/astronomie\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constellations\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/fr\\\/astronomie\\\/constellations\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/fr\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/fr\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"fr-FR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#\\\/schema\\\/person\\\/a75478c8087ac37498b5b3d09f9ec58a\",\n\t            \"name\": \"Luca Isotta\",\n\t            \"description\": \"Appassionato del mondo digitale, mi occupo prevalentemente di SEO e Copywriting. In OSR unisco la mia passione per la scrittura con quella per l'astronomia, creando contenuti basati su ricerche scientifiche e che possano appassionare l'utente.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/it\\\/blog\\\/\",\n\t                \"https:\\\/\\\/it.linkedin.com\\\/in\\\/lucaisotta\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/author\\\/luca-isotta\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/","og_locale":"fr_FR","og_type":"article","og_title":"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie - Online Star Register","og_description":"La constellation de la Couronne australe est d\u00e9j\u00e0 sue d\u2019Eudoxie de Cnide entre 408 et 355 avant J-C et aussi \u00e9voqu\u00e9e dans l\u2019\u0153uvre po\u00e9tique intitul\u00e9e \u00ab\u00a0Les Ph\u00e9nom\u00e8nes d\u2019Aratos\u00a0\u00bb de Soles entre 315 et 245 avant J-C. La constellation de la Couronne australe ne renferme pas d\u2019objets particuli\u00e8rement int\u00e9ressants. Malgr\u00e9 le fait que les chinois identifi\u00e8rent [&hellip;]","og_url":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/","og_site_name":"Online Star Register","article_published_time":"2019-01-18T08:44:01+00:00","article_modified_time":"2019-07-07T15:46:46+00:00","author":"Luca Isotta","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Luca Isotta","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/#article","isPartOf":{"@id":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/"},"author":{"name":"Luca Isotta","@id":"https:\/\/osr.org\/fr\/#\/schema\/person\/a75478c8087ac37498b5b3d09f9ec58a"},"headline":"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie","datePublished":"2019-01-18T08:44:01+00:00","dateModified":"2019-07-07T15:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/"},"wordCount":1079,"articleSection":["Constellations"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/","url":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/","name":"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/fr\/#website"},"datePublished":"2019-01-18T08:44:01+00:00","dateModified":"2019-07-07T15:46:46+00:00","author":{"@id":"https:\/\/osr.org\/fr\/#\/schema\/person\/a75478c8087ac37498b5b3d09f9ec58a"},"breadcrumb":{"@id":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/fr\/blog\/astronomie\/constellations\/couronne-australe-caracteristiques-etoiles-principales-mythologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Astronomie","item":"https:\/\/osr.org\/fr\/astronomie\/"},{"@type":"ListItem","position":3,"name":"Constellations","item":"https:\/\/osr.org\/fr\/astronomie\/constellations\/"},{"@type":"ListItem","position":4,"name":"Constellation Couronne australe:\u00a0Caract\u00e9ristiques, \u00e9toiles principales, mythologie"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/fr\/#website","url":"https:\/\/osr.org\/fr\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/osr.org\/fr\/#\/schema\/person\/a75478c8087ac37498b5b3d09f9ec58a","name":"Luca Isotta","description":"Appassionato del mondo digitale, mi occupo prevalentemente di SEO e Copywriting. In OSR unisco la mia passione per la scrittura con quella per l'astronomia, creando contenuti basati su ricerche scientifiche e che possano appassionare l'utente.","sameAs":["https:\/\/osr.org\/it\/blog\/","https:\/\/it.linkedin.com\/in\/lucaisotta"],"url":"https:\/\/osr.org\/fr\/blog\/author\/luca-isotta\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/posts\/49800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/comments?post=49800"}],"version-history":[{"count":2,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/posts\/49800\/revisions"}],"predecessor-version":[{"id":102232,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/posts\/49800\/revisions\/102232"}],"wp:attachment":[{"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/media?parent=49800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/categories?post=49800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/tags?post=49800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}