{"id":12372,"date":"2015-11-16T23:32:41","date_gmt":"2015-11-16T21:32:41","guid":{"rendered":"https:\/\/osr.org\/fr\/?p=12372"},"modified":"2024-08-05T11:31:47","modified_gmt":"2024-08-05T09:31:47","slug":"le-grand-amour-de-ta-vie","status":"publish","type":"post","link":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/","title":{"rendered":"Le grand amour de ta vie"},"content":{"rendered":"<p style=\"text-align: justify\">\nIl m\u2019accompagne dans chacun de mes pas, chacune de mes guerres et est l\u2019invit\u00e9 d\u2019honneur de chacune de mes r\u00e9ussites. Il est l\u2019essence m\u00eame de ma raison de vivre, mon coeur bat au rythme de ses paroles, des regards qu\u2019il pose sur moi et de l\u2019opinion qu\u2019il \u00e0 de moi.\n<\/p>\n<p style=\"text-align: justify\">Vous pouvez fr\u00e9quent\u00e9 autant de personnes que vous le souhaitez mais croyez moi quand vous aurez trouv\u00e9 l\u2019amour de votre vie, vous comprendrez de suite pourquoi \u00e7a n\u2019a pas march\u00e9 avec les autres, pourquoi tout paraissait superficiel avec les autres, pourquoi rien n\u2019avait de sens avant lui.\n<\/p>\n<p style=\"text-align: justify\">\nUne relation comme celle la sera trop unique pour la vivre deux fois dans votre vie. Rien ne pourra jamais \u00e9gal\u00e9 ce que vous ressentez pour lui, rien de rien. Et j\u2019y pensais, je me suis dit, mais ce que je vie est si fort, si intense si r\u00e9el. J\u2019ai voulu tout faire avec lui chaque \u00e9tapes de ma vie, j\u2019aurais m\u00eame voulue revivre ma vie depuis le commencement avec lui juste pour que ma vie soit plus intense et plus remplie d\u2019amour inconditionnelle.<\/p>\n<p style=\"text-align: justify\">Nous avons v\u00e9cut \u00e9norm\u00e9ment de choses ensemble alors j\u2019ai voulu marqu\u00e9 \u00e7a, j\u2019ai acheter une \u00e9toile \u00e0 mon amour. J\u2019ai acheter une \u00e9toile splendide comme lui, l\u2019\u00e9toile qui marque et marquera \u00e0 tout jamais notre relation. Il faut acheter une \u00e9toile pour comprendre la signification que cela peut avoir, pour comprendre l\u2019importance et la place qu\u2019elle prend dans la vie. Offrir une \u00e9toile  c\u2019est une \u00e9tape \u00e9norme et pourtant on en \u00e0 v\u00e9cus des choses spectaculaire mais \u00e7a c\u2019est vraiment au del\u00e0 de ce que l\u2019ont peut imaginer. Honn\u00eatement tent\u00e9 l\u2019aventure \u00e7a sera plus simple \u00e0 comprendre :). <\/p>\n<p style=\"text-align: justify\">Quand on se pose sur notre terrasse, que l\u2019ont partage ce moment de complicit\u00e9 pour regarder notre \u00e9toile\u2026  J\u2019ai \u00e0 ce moment la une seul chose en t\u00eate \u2026 \u201cj\u2019ai la chance d\u2019avoir le grand amour de ma vie \u00e0 mes c\u00f4t\u00e9s\u201d. Alors si vous aussi c\u2019est le cas, un conseil soyez reconnaissant :). <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il m\u2019accompagne dans chacun de mes pas, chacune de mes guerres et est l\u2019invit\u00e9 d\u2019honneur de chacune de mes r\u00e9ussites. Il est l\u2019essence m\u00eame de ma raison de vivre, mon coeur bat au rythme de ses paroles, des regards qu\u2019il pose sur moi et de l\u2019opinion qu\u2019il \u00e0 de moi. Vous pouvez fr\u00e9quent\u00e9 autant de [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[318],"tags":[],"class_list":["post-12372","post","type-post","status-publish","format-standard","hentry","category-evenements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le grand amour de ta vie - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le grand amour de ta vie - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"Il m\u2019accompagne dans chacun de mes pas, chacune de mes guerres et est l\u2019invit\u00e9 d\u2019honneur de chacune de mes r\u00e9ussites. Il est l\u2019essence m\u00eame de ma raison de vivre, mon coeur bat au rythme de ses paroles, des regards qu\u2019il pose sur moi et de l\u2019opinion qu\u2019il \u00e0 de moi. Vous pouvez fr\u00e9quent\u00e9 autant de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-16T21:32:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T09:31:47+00:00\" \/>\n<meta name=\"author\" content=\"Jules\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jules\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/evenements\\\/le-grand-amour-de-ta-vie\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/evenements\\\/le-grand-amour-de-ta-vie\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Jules\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#\\\/schema\\\/person\\\/c8f972170947d8fe52c5eb7eec1ee0dc\"\n\t            },\n\t            \"headline\": \"Le grand amour de ta vie\",\n\t            \"datePublished\": \"2015-11-16T21:32:41+00:00\",\n\t            \"dateModified\": \"2024-08-05T09:31:47+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/evenements\\\/le-grand-amour-de-ta-vie\\\/\"\n\t            },\n\t            \"wordCount\": 370,\n\t            \"articleSection\": [\n\t                \"Astuces et cadeaux\"\n\t            ],\n\t            \"inLanguage\": \"fr-FR\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/evenements\\\/le-grand-amour-de-ta-vie\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/evenements\\\/le-grand-amour-de-ta-vie\\\/\",\n\t            \"name\": \"Le grand amour de ta vie - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2015-11-16T21:32:41+00:00\",\n\t            \"dateModified\": \"2024-08-05T09:31:47+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#\\\/schema\\\/person\\\/c8f972170947d8fe52c5eb7eec1ee0dc\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/evenements\\\/le-grand-amour-de-ta-vie\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"fr-FR\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/evenements\\\/le-grand-amour-de-ta-vie\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/evenements\\\/le-grand-amour-de-ta-vie\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/fr\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astuces et cadeaux\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/fr\\\/evenements\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Le grand amour de ta vie\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/fr\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/fr\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"fr-FR\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/fr\\\/#\\\/schema\\\/person\\\/c8f972170947d8fe52c5eb7eec1ee0dc\",\n\t            \"name\": \"Jules\",\n\t            \"description\": \"Ing\u00e9nieur en \u00e9lectronique de formation, j\u2019ai toujours \u00e9t\u00e9 passionn\u00e9 par les sciences. J'ai d\u00e9couvert l'observation astronomique gr\u00e2ce au t\u00e9lescope Celestron CPC 1100 qui m'a r\u00e9v\u00e9l\u00e9 les lunes de M\u00e9dicis un jour avant Galil\u00e9e... mais 405 ans plus tard. Depuis, ma passion n'a cess\u00e9 de grandir et je la combine aujourd'hui avec la photographie, un autre grand hobby.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/fr\\\/blog\\\/author\\\/jules\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le grand amour de ta vie - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/","og_locale":"fr_FR","og_type":"article","og_title":"Le grand amour de ta vie - Online Star Register","og_description":"Il m\u2019accompagne dans chacun de mes pas, chacune de mes guerres et est l\u2019invit\u00e9 d\u2019honneur de chacune de mes r\u00e9ussites. Il est l\u2019essence m\u00eame de ma raison de vivre, mon coeur bat au rythme de ses paroles, des regards qu\u2019il pose sur moi et de l\u2019opinion qu\u2019il \u00e0 de moi. Vous pouvez fr\u00e9quent\u00e9 autant de [&hellip;]","og_url":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/","og_site_name":"Online Star Register","article_published_time":"2015-11-16T21:32:41+00:00","article_modified_time":"2024-08-05T09:31:47+00:00","author":"Jules","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jules","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/#article","isPartOf":{"@id":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/"},"author":{"name":"Jules","@id":"https:\/\/osr.org\/fr\/#\/schema\/person\/c8f972170947d8fe52c5eb7eec1ee0dc"},"headline":"Le grand amour de ta vie","datePublished":"2015-11-16T21:32:41+00:00","dateModified":"2024-08-05T09:31:47+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/"},"wordCount":370,"articleSection":["Astuces et cadeaux"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/","url":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/","name":"Le grand amour de ta vie - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/fr\/#website"},"datePublished":"2015-11-16T21:32:41+00:00","dateModified":"2024-08-05T09:31:47+00:00","author":{"@id":"https:\/\/osr.org\/fr\/#\/schema\/person\/c8f972170947d8fe52c5eb7eec1ee0dc"},"breadcrumb":{"@id":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/fr\/blog\/evenements\/le-grand-amour-de-ta-vie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Astuces et cadeaux","item":"https:\/\/osr.org\/fr\/evenements\/"},{"@type":"ListItem","position":3,"name":"Le grand amour de ta vie"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/fr\/#website","url":"https:\/\/osr.org\/fr\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/osr.org\/fr\/#\/schema\/person\/c8f972170947d8fe52c5eb7eec1ee0dc","name":"Jules","description":"Ing\u00e9nieur en \u00e9lectronique de formation, j\u2019ai toujours \u00e9t\u00e9 passionn\u00e9 par les sciences. J'ai d\u00e9couvert l'observation astronomique gr\u00e2ce au t\u00e9lescope Celestron CPC 1100 qui m'a r\u00e9v\u00e9l\u00e9 les lunes de M\u00e9dicis un jour avant Galil\u00e9e... mais 405 ans plus tard. Depuis, ma passion n'a cess\u00e9 de grandir et je la combine aujourd'hui avec la photographie, un autre grand hobby.","sameAs":["https:\/\/osr.org\/fr\/blog\/"],"url":"https:\/\/osr.org\/fr\/blog\/author\/jules\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/posts\/12372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/comments?post=12372"}],"version-history":[{"count":2,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/posts\/12372\/revisions"}],"predecessor-version":[{"id":12636,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/posts\/12372\/revisions\/12636"}],"wp:attachment":[{"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/media?parent=12372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/categories?post=12372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/fr\/wp-json\/wp\/v2\/tags?post=12372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}