{"id":49189,"date":"2018-12-11T00:58:29","date_gmt":"2018-12-10T22:58:29","guid":{"rendered":"https:\/\/osr.org\/?p=49189\/"},"modified":"2024-08-05T10:59:43","modified_gmt":"2024-08-05T08:59:43","slug":"constelacion-piscis-austrinus-pez-austral","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/","title":{"rendered":"Constelaci\u00f3n Pez Austral (Piscis Austrinus)"},"content":{"rendered":"<p>El Pez Austral, es una constelaci\u00f3n conocida desde la antig\u00fcedad, es una de las 48 constelaciones que fueron introducidas por Ptolomeo, y es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, ostentando la posici\u00f3n n\u00famero 60 en relaci\u00f3n a su dimensi\u00f3n.<\/p>\n<p>Las constelaciones vecinas o colindantes del Pez Austral, son las constelaciones de, Aquarius, Capricornus, Grus, Microscopium, Sculptor. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Octubre.<\/p>\n<h2>Principales estrellas de la constelaci\u00f3n, Piscis Austrinus Pez Austral.<\/h2>\n<ul>\n<li>\u03b1 Piscis Austrini es la estrella mas brillante de la constelaci\u00f3n Pez Austral, su nombre en \u00e1rabe, significa \u00abboca del pez, es una estrella de color blanca de la secuencia principal posee una magnitud aparente de 1,16 que tiene un disco circunestelar. Tambi\u00e9n tiene un planeta extrasolar. Adem\u00e1s es conocida con los nombres de Os Piscis Meridiana, Os Piscis Meridionalis, Os Piscis Notii y Difda al Auwel.<\/li>\n<li>\u03b5 Piscis Austrini, esta es segunda estrella m\u00e1s brillante de la constelaci\u00f3n posee una magnitud aparente de 4,18.<\/li>\n<li>\u03b4 Piscis Austrini, es una estrella gigante de color amarilla con una magnitud aparente de 4,23, la tercera estrella m\u00e1s brillante del Pez Austral.<\/li>\n<li>\u03b2 Piscis Austrini, es una estrella doble cuyas componentes, posee una magnitud aparente de 4,29 y 7,04, las cuales est\u00e1n separadas 30 segundos de arco.<\/li>\n<li>\u03b3 Piscis Austrini, es una estrella de color blanca posee una magnitud aparente de 4,46.<\/li>\n<li>\u03bc Piscis Austrini, es una estrella sub gigante de color blanca posee una magnitud aparente de 4,50.<\/li>\n<li>\u03c0 Piscis Austrini, es un sistema binario posee una magnitud aparente de 5,12 que muestra un exceso en el infrarrojo.<\/li>\n<li>\u03c4 Piscis Austrini, es una estrella enana de color amarilla m\u00e1s luminosa que el Sol posee una magnitud aparente de 4,92.<\/li>\n<li>R Piscis Austrini, es una estrella variable Mira con un per\u00edodo de 297,6 d\u00edas que en brillo m\u00e1ximo alcanza magnitud aparente de 8,3.<\/li>\n<li>TW Piscis Austrini, es una estrella enana de color naranja posee una magnitud aparente de 6,48 se encuentra situada a una distancia de 25 a\u00f1os luz de la Tierra.<\/li>\n<li>VV Piscis Austrini, es una estrella Be posee una magnitud aparente de 7,00.<\/li>\n<li>Lacaille 9352 (GJ 887), es una estrella tenue enana de color roja posee una magnitud aparente de 7,34 situada a 10,7 a\u00f1os luz que posee un gran movimiento propio.<\/li>\n<li>HIP 112312, es una estrella binaria formada por dos estrellas presecuencia principal, denominadas WW Piscis Austrini y TX Piscis Austrini.<\/li>\n<li>HD 205739 y HD 216770,estas estrellas albergan planetas extrasolares.<\/li>\n<li>Otra estrella de inter\u00e9s es Lacaille 9352, es una estrella una enana de color roja situada a menos de 11 a\u00f1os luz del sistema solar, lo que la convierte en la d\u00e9cimo primera o und\u00e9cima estrella m\u00e1s cercana a nuestro sistema solar, posee una magnitud de +7,34, no es observable a simple vista, esta estrella fue seleccionada como objetivo prioritario de la Space Interferometry Mission (SIM) de la NASA, proyecto de b\u00fasqueda de planetas terrestres.<\/li>\n<li>\u03b6 PsA 6,43;<\/li>\n<li>12\/\u03b7 PsA 5,43;<\/li>\n<li>10\/\u03b8 PsA 5,02;<\/li>\n<li>9\/\u03b9 PsA 4,35;<\/li>\n<li>16\/\u03bb PsA 5,45;<\/li>\n<li>\u03c5 PsA 4,99.<\/li>\n<li>2 PsA 5,20;<\/li>\n<li>3 PsA 5,41;<\/li>\n<li>5 PsA 6,52;<\/li>\n<li>6 PsA 5,97;<\/li>\n<li>7 PsA 6,10;<\/li>\n<li>8 PsA 5,73;<\/li>\n<li>13 PsA 6,45;<\/li>\n<li>19 PsA 6,12;<\/li>\n<li>21 PsA 5,99<\/li>\n<\/ul>\n<h2>Caracter\u00edsticas de la constelaci\u00f3n, Piscis Austrinus Pez Austral.<\/h2>\n<ul>\n<li>La Constelaci\u00f3n, EL Pez Austral, es conocida desde la antig\u00fcedad y es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna.<\/li>\n<li>LA Visibilidad de esta constelaci\u00f3n es completa, entre 90\u00b0 S y 53\u00b0 N y parcial, entre 53\u00b0 N y 65\u00b0 N.<\/li>\n<li>La Constelaci\u00f3n de Pez Austral, contiene algunas galaxias d\u00e9biles.<\/li>\n<li>La estrella principal de la constelaci\u00f3n Pez Austral, conocida como Fomalhaut, brilla a primera magnitud por lo cual es una estrella f\u00e1cil de identificar, tiene un disco circumestelar y un exoplaneta, se encuentra a una distancia de 25 a\u00f1os luz.<\/li>\n<li>El Objeto de cielo profundo con mayor relevancia dentro de la constelaci\u00f3n del Pez Austral es la galaxia espiral NGC 7314.<\/li>\n<li>La Constelaci\u00f3n, Piscis Austrinus, Pez Austral se extiende en el hemisferio sur, se sit\u00faa al norte de las constelaciones de Acuario y Capricornio y al oeste de la constelaci\u00f3n el Microscopio, al este el Escultor y al sur la Grulla.<\/li>\n<li>En la constelaci\u00f3n El Pez Austral, no se dan Lluvias de meteoritos.<\/li>\n<li>Su Estrella m\u00e1s brillante es Fomalhaut tambi\u00e9n es una de las estrellas brillantes m\u00e1s conocidas esta estrella tiene un planeta orbitando a su alrededor. Est\u00e1 situada a una distancia de 25 a\u00f1os luz de la Tierra y la rodeada por un enorme disco de polvo, est\u00e1 Situada al sur de Acuario y Capricornio.<\/li>\n<li>No suele ser una constelaci\u00f3n muy atractiva, esta se encuentra a 60\u00ba al sur del ecuador de la V\u00eda L\u00e1ctea, es por esto que no es posible visualizar gran cantidad de sus estrellas.<\/li>\n<\/ul>\n<h2>Mitolog\u00eda de la constelaci\u00f3n, Piscis Austrinus Pez Austral.<\/h2>\n<p>La Constelaci\u00f3n Pez Austral, es una constelaci\u00f3n conocida desde la antig\u00fcedad, en la mitolog\u00eda griega se dice que El Gran Pez, que se encuentra tomando el agua derramada por la constelaci\u00f3n de acuario.<\/p>\n<p>Tambi\u00e9n se cuenta que en la mitolog\u00eda egipcia, este pez salv\u00f3 la vida de la diosa egipcia Isis, y en agradecimiento esta es colocada en el cielo como constelaci\u00f3n en compa\u00f1\u00eda de sus descendientes.<\/p>\n<p>Se dice que inicialmente el Pez Austral, Piscis Austrinus fue la \u00fanica constelaci\u00f3n con forma de pez. En el siglo VIII antes de Cristo.<\/p>\n<p>Los \u00e1rabes interpretaron esta constelaci\u00f3n como el gran pez del sur.<\/p>\n<p>Al igual que muchas otras constelaciones, para la constelaci\u00f3n El Pez Austral, existen diversas mitolog\u00edas que justifican su existencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Pez Austral, es una constelaci\u00f3n conocida desde la antig\u00fcedad, es una de las 48 constelaciones que fueron introducidas por Ptolomeo, y es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, ostentando la posici\u00f3n n\u00famero 60 en relaci\u00f3n a su dimensi\u00f3n. Las constelaciones vecinas o colindantes del Pez Austral, son las constelaciones de, [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[485],"tags":[],"class_list":["post-49189","post","type-post","status-publish","format-standard","hentry","category-constelaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constelaci\u00f3n Pez Austral (Piscis Austrinus) - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constelaci\u00f3n Pez Austral (Piscis Austrinus) - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"El Pez Austral, es una constelaci\u00f3n conocida desde la antig\u00fcedad, es una de las 48 constelaciones que fueron introducidas por Ptolomeo, y es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, ostentando la posici\u00f3n n\u00famero 60 en relaci\u00f3n a su dimensi\u00f3n. Las constelaciones vecinas o colindantes del Pez Austral, son las constelaciones de, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-10T22:58:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T08:59:43+00:00\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-piscis-austrinus-pez-austral\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-piscis-austrinus-pez-austral\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"headline\": \"Constelaci\u00f3n Pez Austral (Piscis Austrinus)\",\n\t            \"datePublished\": \"2018-12-10T22:58:29+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:43+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-piscis-austrinus-pez-austral\\\/\"\n\t            },\n\t            \"wordCount\": 918,\n\t            \"articleSection\": [\n\t                \"Constelaci\u00f3nes\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-piscis-austrinus-pez-austral\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-piscis-austrinus-pez-austral\\\/\",\n\t            \"name\": \"Constelaci\u00f3n Pez Austral (Piscis Austrinus) - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-12-10T22:58:29+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:43+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-piscis-austrinus-pez-austral\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-piscis-austrinus-pez-austral\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-piscis-austrinus-pez-austral\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronom\u00eda\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constelaci\u00f3nes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/constelaciones\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constelaci\u00f3n Pez Austral (Piscis Austrinus)\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constelaci\u00f3n Pez Austral (Piscis Austrinus) - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/","og_locale":"es_ES","og_type":"article","og_title":"Constelaci\u00f3n Pez Austral (Piscis Austrinus) - Online Star Register","og_description":"El Pez Austral, es una constelaci\u00f3n conocida desde la antig\u00fcedad, es una de las 48 constelaciones que fueron introducidas por Ptolomeo, y es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, ostentando la posici\u00f3n n\u00famero 60 en relaci\u00f3n a su dimensi\u00f3n. Las constelaciones vecinas o colindantes del Pez Austral, son las constelaciones de, [&hellip;]","og_url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2018-12-10T22:58:29+00:00","article_modified_time":"2024-08-05T08:59:43+00:00","author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"headline":"Constelaci\u00f3n Pez Austral (Piscis Austrinus)","datePublished":"2018-12-10T22:58:29+00:00","dateModified":"2024-08-05T08:59:43+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/"},"wordCount":918,"articleSection":["Constelaci\u00f3nes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/","url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/","name":"Constelaci\u00f3n Pez Austral (Piscis Austrinus) - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2018-12-10T22:58:29+00:00","dateModified":"2024-08-05T08:59:43+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-piscis-austrinus-pez-austral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Astronom\u00eda","item":"https:\/\/osr.org\/es\/astronomia\/"},{"@type":"ListItem","position":3,"name":"Constelaci\u00f3nes","item":"https:\/\/osr.org\/es\/astronomia\/constelaciones\/"},{"@type":"ListItem","position":4,"name":"Constelaci\u00f3n Pez Austral (Piscis Austrinus)"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/49189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=49189"}],"version-history":[{"count":3,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/49189\/revisions"}],"predecessor-version":[{"id":49201,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/49189\/revisions\/49201"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=49189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=49189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=49189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}