{"id":49183,"date":"2018-12-30T18:15:51","date_gmt":"2018-12-30T16:15:51","guid":{"rendered":"https:\/\/osr.org\/?p=49183\/"},"modified":"2024-08-05T10:59:38","modified_gmt":"2024-08-05T08:59:38","slug":"constelacion-pegasus-pegaso","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/","title":{"rendered":"Constelaci\u00f3n Pegasus, Pegaso"},"content":{"rendered":"<p>La constelaci\u00f3n Pegaso es una de las 88 constelaciones actualmente reconocidas por la astronom\u00eda moderna, ocupando por su extensi\u00f3n el puesto n\u00famero 7 de este conteo.<\/p>\n<p>En esta constelaci\u00f3n se dan 2 lluvias de meteoritos, conocidas con los nombres de Iota Peg\u00e1sidas de junio, Peg\u00e1sidas de julio.<\/p>\n<p>Sus constelaciones vecinas o colindantes son las constelaciones de Andr\u00f3meda, Aquarius, Cygnus, Delphinus, Equuleus, Lacerta, Pisces, Vulpecula.<\/p>\n<p>El mejor mes para observar esta constelaci\u00f3n es durante el mes de Septiembre.<\/p>\n<h2>Principales estrella de la Constelaci\u00f3n Pegasus, Pegaso<\/h2>\n<ul>\n<li>Enif ( \u03b5 Pegasi ) es la estrella m\u00e1s brillante de la constelaci\u00f3n adem\u00e1s de ello esta estrella ocupa la posici\u00f3n n\u00famero 84\u00aa de las m\u00e1s brillante del cielo, posee una magnitud aparente de 2,39, es una supe gigante naranja, hacia 175 veces mayor que el Sol y 11 veces m\u00e1s masiva. Est\u00e1 catalogada como estrella variable, pues eyectado una vasta cantidad de materia en 1972 que ha reducido temporalmente su magnitud hasta 0,70.<\/li>\n<li>Markab. Alfa de Pegasus (a). Es una estrella de color blanca de tipo A, posee una magnitud aparente de 2,5. Se encuentra situada a 90 a\u00f1os luz, de distancia.<\/li>\n<li>Scheat. Beta de Pegasus (b). Se trata de una estrella de color roja del tipo M, posee una Magnitud aparente de 2,3. Se encuentra a una distancia de 190 a\u00f1os luz.<\/li>\n<li>Algenib. Gamma de Pegasus (g). Es una estrella de color blanca, del tipo B, posee una magnitud aparente de 2,8. Se encuentra situada a 480 a\u00f1os luz de distancia.<\/li>\n<li>Homan. Zeta de Pegasus (z). Es una estrella de color blanca de tipo B, posee una magnitud aparente de de 3,4. Se encuentra a una distancia de 160 a\u00f1os luz.<\/li>\n<li>Matar. Eta de Pegasus (h). Es una estrella de color amarilla del tipo G, posee una magnitud aparente de 2,9.se encuentra situada a una distancia de 190 a\u00f1os luz.<\/li>\n<li>Baham. Theta de Pegasus (q). Es una estrella de color blanco amarilla del tipo F, posee una magnitud aparente de 4,2. Se encuentra situada a una distancia de 70 a\u00f1os luz.<\/li>\n<li>Sadalbari. Mu de Pegasus (m). Es una estrella de color anaranjada del tipo K, posee una magnitud aparente de 3,5. Est\u00e1 situada a una distancia de 80 a\u00f1os luz.<\/li>\n<li>34 Vulpeculae, es una estrella gigante de color naranja perteneciente al disco grueso de la galaxia.<\/li>\n<li>U Pegasi, es una estrella binaria eclipsante posee una magnitud aparente de 9,23.<\/li>\n<li>HN Pegasi, es sistema un binario compuesto por una estrella enana de color amarilla joven y una estrella enana de color marr\u00f3n.<\/li>\n<li>HR Pegasi, es una estrella de tipo S y variable semirregular<\/li>\n<li>II Pegasi, es una estrella variable eruptiva RS Canum Venaticorum<\/li>\n<li>IK Pegasi, es una estrella binaria cuya componente B es el candidato mejor conocido a supernova<\/li>\n<li>MT Pegasi, es un an\u00e1logo solar posee una magnitud aparente de 6,61.<\/li>\n<li>NZ Pegasi, es una variable Gamma Doradus posee una magnitud aparente de 5,78.<\/li>\n<li>OO Pegasi, es una estrella binaria eclipsante posee una magnitud media 8,26<\/li>\n<li>HD 209458 (V376 Peg) 7.65 tiene un planeta transitorio<\/li>\n<li>HR 8799 (HD 218396), es una estrella de color blanca de la secuencia principal con tres planetas<\/li>\n<li>V391 Pegasi, es una estrella subenana de color azul con un planeta extrasolar<\/li>\n<li>EQ Pegasi (Gliese 896), Gliese 829 y Gliese 880, estrellas enanas de color rojas se encuentran respectivamente a 20,7, 21,9 y 22,4 a\u00f1os luz de distancia del Sistema Solar; la primera es la estrella m\u00e1s cercana a nosotros en esta constelaci\u00f3n.<\/li>\n<\/ul>\n<h2>Caracter\u00edsticas de la Constelaci\u00f3n Pegasus, Pegaso<\/h2>\n<ul>\n<li>La Constelaci\u00f3n Pegaso, es una constelaci\u00f3n Boreal, con una visibilidad, Completa, entre 53\u00b0 S y 90\u00b0 N y parcial entre 87\u00b0 S y 53\u00b0<\/li>\n<li>Es una de las 88 constelaciones actualmente reconocidas por la astronom\u00eda moderna, ostentando la posici\u00f3n n\u00famero 7 de acuerdo a sus dimensiones, adem\u00e1s forma parte de las 48 constelaciones descritas por el astr\u00f3nomo Ptolomeo.<\/li>\n<li>En esta constelaci\u00f3n se dan 2 lluvias de meteoritos.<\/li>\n<li>La Constelaci\u00f3n Pegaso, es reconocible por su peculiar forma de cuadril\u00e1tero formado por 4 estrellas, sin embargo una de esas estrellas pertenece a su constelaci\u00f3n vecina, Andr\u00f3meda, y es la estrella que se encuentra situada al extremo occidental superior, siendo esta caracter\u00edstica lo que m\u00e1s destaca de esta constelaci\u00f3n, ya que a excepci\u00f3n de esta caracter\u00edstica se considera una constelaci\u00f3n poco atractiva, a pesar de su extenso tama\u00f1o.<\/li>\n<li>La Constelaci\u00f3n Pegaso, es una constelaci\u00f3n particularmente libre de las nubes y polvo estelares, lo que permite observar c\u00famulos globulares y galaxias con bastante facilidad.<\/li>\n<li>Los Objetos de cielo profundo presentes en la constelaci\u00f3n de Pegaso son, M15 , un c\u00famulo globular cerca de Enif, la NGC 7742 , una galaxia de Seyfert de tipo 2, Galaxias espirales NGC 7217 y NGC 7331, el HCG 92 , tambi\u00e9n conocido con el nombre de Quinteto de Stephan, el cual es un peque\u00f1o c\u00famulo conformado por cinco galaxias : NGC 7317 , NGC 7318 , NGC 7318B , NGC 7319 y NGC 7320.<\/li>\n<\/ul>\n<h2>Mitolog\u00eda de la Constelaci\u00f3n Pegasus, Pegaso<\/h2>\n<p>Pegaso, es una constelaci\u00f3n conocida desde la antig\u00fcedad, a esta constelaci\u00f3n se te atribuye en la mitolog\u00eda griega, una historia donde se dice que Pegaso era un caballo con alas, que fue el primero en estar entre los dioses.<\/p>\n<p>Este era el caballo de Zeus, dios del Cielo y de la Tierra. Se cuenta que Perseo, naci\u00f3 de la mezcla de espuma de mar con la sangre que brot\u00f3 cuando Perseo cort\u00f3 la cabeza a la Gorgona Medusa.<\/p>\n<p>Sin embargo tambi\u00e9n se dice que era hijo de Poseid\u00f3n.<\/p>\n<p>Atenea llev\u00f3 a Pegaso al Monte Helic\u00f3n, donde, con una simple patada, cre\u00f3 el manantial de Hipocrene consagrado a las Musas y fuente de inspiraci\u00f3n po\u00e9tica.<\/p>\n<p>Sin embargo al igual que en muchas otras constelaciones hay diversas variaciones de la mitolog\u00eda en torno a la existencia de esta constelaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La constelaci\u00f3n Pegaso es una de las 88 constelaciones actualmente reconocidas por la astronom\u00eda moderna, ocupando por su extensi\u00f3n el puesto n\u00famero 7 de este conteo. En esta constelaci\u00f3n se dan 2 lluvias de meteoritos, conocidas con los nombres de Iota Peg\u00e1sidas de junio, Peg\u00e1sidas de julio. Sus constelaciones vecinas o colindantes son las constelaciones [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[485],"tags":[],"class_list":["post-49183","post","type-post","status-publish","format-standard","hentry","category-constelaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constelaci\u00f3n Pegasus, Pegaso - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constelaci\u00f3n Pegasus, Pegaso - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"La constelaci\u00f3n Pegaso es una de las 88 constelaciones actualmente reconocidas por la astronom\u00eda moderna, ocupando por su extensi\u00f3n el puesto n\u00famero 7 de este conteo. En esta constelaci\u00f3n se dan 2 lluvias de meteoritos, conocidas con los nombres de Iota Peg\u00e1sidas de junio, Peg\u00e1sidas de julio. Sus constelaciones vecinas o colindantes son las constelaciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-30T16:15:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T08:59:38+00:00\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-pegasus-pegaso\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-pegasus-pegaso\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"headline\": \"Constelaci\u00f3n Pegasus, Pegaso\",\n\t            \"datePublished\": \"2018-12-30T16:15:51+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:38+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-pegasus-pegaso\\\/\"\n\t            },\n\t            \"wordCount\": 966,\n\t            \"articleSection\": [\n\t                \"Constelaci\u00f3nes\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-pegasus-pegaso\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-pegasus-pegaso\\\/\",\n\t            \"name\": \"Constelaci\u00f3n Pegasus, Pegaso - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-12-30T16:15:51+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:38+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-pegasus-pegaso\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-pegasus-pegaso\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-pegasus-pegaso\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronom\u00eda\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constelaci\u00f3nes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/constelaciones\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constelaci\u00f3n Pegasus, Pegaso\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constelaci\u00f3n Pegasus, Pegaso - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/","og_locale":"es_ES","og_type":"article","og_title":"Constelaci\u00f3n Pegasus, Pegaso - Online Star Register","og_description":"La constelaci\u00f3n Pegaso es una de las 88 constelaciones actualmente reconocidas por la astronom\u00eda moderna, ocupando por su extensi\u00f3n el puesto n\u00famero 7 de este conteo. En esta constelaci\u00f3n se dan 2 lluvias de meteoritos, conocidas con los nombres de Iota Peg\u00e1sidas de junio, Peg\u00e1sidas de julio. Sus constelaciones vecinas o colindantes son las constelaciones [&hellip;]","og_url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2018-12-30T16:15:51+00:00","article_modified_time":"2024-08-05T08:59:38+00:00","author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"headline":"Constelaci\u00f3n Pegasus, Pegaso","datePublished":"2018-12-30T16:15:51+00:00","dateModified":"2024-08-05T08:59:38+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/"},"wordCount":966,"articleSection":["Constelaci\u00f3nes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/","url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/","name":"Constelaci\u00f3n Pegasus, Pegaso - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2018-12-30T16:15:51+00:00","dateModified":"2024-08-05T08:59:38+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-pegasus-pegaso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Astronom\u00eda","item":"https:\/\/osr.org\/es\/astronomia\/"},{"@type":"ListItem","position":3,"name":"Constelaci\u00f3nes","item":"https:\/\/osr.org\/es\/astronomia\/constelaciones\/"},{"@type":"ListItem","position":4,"name":"Constelaci\u00f3n Pegasus, Pegaso"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/49183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=49183"}],"version-history":[{"count":2,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/49183\/revisions"}],"predecessor-version":[{"id":49301,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/49183\/revisions\/49301"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=49183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=49183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=49183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}