{"id":48016,"date":"2018-11-18T11:48:54","date_gmt":"2018-11-18T09:48:54","guid":{"rendered":"https:\/\/osr.org\/?p=48016\/"},"modified":"2024-08-05T10:59:51","modified_gmt":"2024-08-05T08:59:51","slug":"constelacion-horologium-el-reloj","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/","title":{"rendered":"Constelaci\u00f3n Horologium, El Reloj"},"content":{"rendered":"<p>Esta constelaci\u00f3n fue introducida por el astr\u00f3nomo Nicolas Louis de Lacaille, es uno de las menores constelaciones del sur.<\/p>\n<p>Las constelaciones vecinas o colindantes de Horologium, son las constelaciones de Caelum, Dorado, Eridanus, Hydrus, Reticulum. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Diciembre.<\/p>\n<h2>Principales estrellas de la constelaci\u00f3n Horologium, El Reloj<\/h2>\n<ul>\n<li>Alfa Horologii, es una estella gugante de color naranja de tipo K1 III, con una magnitud aparente de 3,85 a una distancia de 117 a\u00f1os luz<\/li>\n<li>R Horologii es una estrella \u2022 Variable Mira con un per\u00edodo de 13 meses y medio, con una magnitud aparente de 4,00, se encuentra a 1004 a\u00f1os luz de distancia.<\/li>\n<li>Delta Horologii es una estrella blanca de la secuencia principal, se encuentra a 175 a\u00f1os luz de distancia y posee una magnitud aparente de 4,93.<\/li>\n<li>Beta Horologii es una estrella Gigante de color blanca con l\u00edneas met\u00e1licas, posee una magnitud de 4,98 y se encuentra a 313 a\u00f1os luz de distancia.<\/li>\n<li>Mu Horologii es una estrella Subgigante de color blanco amarilla, con una magnitud aparente de 5,11, se encuentra a 138 a\u00f1os luz de distancia.<\/li>\n<li>Zeta Horologii es una estrella \u2022 Binaria cuyo per\u00edodo es de 12,93 d\u00edas, con una magnitud aparente de 5,21, situada a 159 a\u00f1os luz de distancia.<\/li>\n<li>Iota Horologii es una estrella similar al Sol posee un planeta extrasolar, con una magnitud de 5,41 se encuentra a 56 a\u00f1os luz de distancia.<\/li>\n<li>TW Horologii es una estrella de carbono y variable semirregular, con una magnitud de 5,74, situada a 1331 a\u00f1os luz de distancia.<\/li>\n<li>TZ Horologii, es una estrella variable irregular, con una magnitud aparente de 6,41, situada a 932 a\u00f1os luz.<\/li>\n<li>Gliese 146, es una estrella enana de color naranja distante 43 a\u00f1os luz, con una magnitud aparente de 8,57.<\/li>\n<li>Gliese 114.1 A, es una estrella enana de color roja con una magnitud aparente de 10,72 distante a 42,2 a\u00f1os luz.<\/li>\n<li>GJ 1061 Es una estrella enana de color roja cercana al Sistema Solar, con una magnitud de 13,03, se encuentra a unos 12,0 a\u00f1os luz de distancia.<\/li>\n<li>Ni Horologii, es una estrella de magnitud aparente 5,26, se encuentra a 165 a\u00f1os luz de distancia.<\/li>\n<li>Eta Horologii es una estrella de magnitud aparente 5,31, se encuentra a 146 a\u00f1os luz de distancia.<\/li>\n<li>Lambda Horologii, es una estrella de magnitud Lambda Horologii, se encuentra a 160 a\u00f1os luz de distancia.<\/li>\n<li>Gamma Horologii, es una estrella de magnitud aparente de 5,74, se encuentra a 179 a\u00f1os luz de distancia.<\/li>\n<\/ul>\n<h2>Caracter\u00edsticas de la constelaci\u00f3n Horologium, El Reloj<\/h2>\n<p>La constelaci\u00f3n de Horologium (el reloj) es una constelaci\u00f3n d\u00e9bil la cual ue introducida por el astr\u00f3nomo franc\u00e9s Lacaille en la d\u00e9cada de 1750.<\/p>\n<p>Inicialmente se la llam\u00f3 Horologium Oscillitorium en honor al inventor del reloj de p\u00e9ndulo, Christian Huygens,<\/p>\n<p>Entre los objetos de ciclo profundo presentes en la constelaci\u00f3n Horologium, se encuentra Galaxia espiral barrada NGC 1512, el NGC 1261, un c\u00famulo globular de magnitud 8 que puede verse bien con un telescopio grande, Es el objeto de cielo profundo m\u00e1s brillante de esta constelaci\u00f3n. Se trata de un c\u00famulo globular descubierto por Dunlop en 1826 que tiene magnitud 8,40 un tama\u00f1o angular de 6,9 minutos de arco y se encuentra a una distancia de unos 54.000 a\u00f1os luz. Tambi\u00e9n se encuentra la Galaxia espiral barrada NGC 1512. Y la galaxia NGC 1433: Es la galaxia m\u00e1s brillante de esta constelaci\u00f3n. Est\u00e1 clasificada como espiral barrada y tiene magnitud 10,75 siendo su tama\u00f1o angular de 6,8\u2019 x 6,0\u2019 de arco.<\/p>\n<p>En esta constelaci\u00f3n fue descubierto el cumulo globular AM1 que es el m\u00e1s lejano que se ha detectado, a unos 400.000 a\u00f1os luz de distancia. Este descubrimiento se realiz\u00f3 en el a\u00f1o 1977 Este d\u00e9bil y lejano c\u00famulo tiene una magnitud de 15,8 por lo que es bastante complicada su visibilidad para los astr\u00f3nomos aficionados.<\/p>\n<p>La Constelaci\u00f3n Horologium es visible desde el hemisferio sur, su visibilidad Completa: es entre 90\u00b0 S y 23\u00b0 N y Parcial entre 23\u00b0 N y 50\u00b0 N.<\/p>\n<p>La Constelaci\u00f3n Horologium, el Reloj puede ser localizada en el espacio celeste, entre la constelaci\u00f3n de Reticulum y la constelaci\u00f3n de Eridanus, la estrella Achernar de Eridanus puede ser utilizada de referencia para encontrarla esta constelaci\u00f3n, ya que se trata de una constelaci\u00f3n donde sus estrellas son bastante d\u00e9biles.<\/p>\n<p>La Constelaci\u00f3n Horologium se ve desde los tr\u00f3picos y desde el hemisferio sur; tiene su punto m\u00e1s \u00e1lgido en el mes de Diciembre<\/p>\n<p>La Constelaci\u00f3n de Horologium, el Reloj, es uno de las constelaciones se\u00f1aladas con instrumentos astron\u00f3micos a\u00f1adidas pores astr\u00f3nomo Nicolas Louis LaCaille a mitad de los a\u00f1os 1700. Este instrumento se supone que es un reloj de p\u00e9ndulo de estilo antiguo de los que muchos astr\u00f3nomos utilizaban para esa fecha.<\/p>\n<p>En la constelaci\u00f3n Horologium, no se presentan lluvias de meteoros.<\/p>\n<p>Es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, ocupando el puesto n\u00famero 58.<\/p>\n<p><strong>Mitologia de la constelaci\u00f3n Horologium, El Reloj.<\/strong><\/p>\n<p>La Constelaci\u00f3n Horologium, es una constelaci\u00f3n moderna, correspondiente al siglo XVII, esta constelaci\u00f3n no era visible para los pueblos del Mediterr\u00e1neo, es por ello que en la actualidad no hay historias mitol\u00f3gicas relacionadas con ella.<\/p>\n<p>El Astronomo franc\u00e9s Nicol\u00e1s de Lacaille cre\u00f3 la figura de esta constelaci\u00f3n en el a\u00f1o 1.751 1.752 lo realizo a partir de un hilo de estrellas situadas en la orilla oriental de la constelaci\u00f3n del Rio.<\/p>\n<p>El nombre que originalmente, se le dio era Horologium Oscillatorium (\u00abel reloj de p\u00e9ndulo\u00bb), en honor al invento que llev\u00f3 a cabo en 1.650 el cient\u00edfico holand\u00e9s Christiaan Huygens. Sin embargo al ser un nombre tan raro lo acort\u00f3 teniendo finalmente el nombre de Horologium o el reloj.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta constelaci\u00f3n fue introducida por el astr\u00f3nomo Nicolas Louis de Lacaille, es uno de las menores constelaciones del sur. Las constelaciones vecinas o colindantes de Horologium, son las constelaciones de Caelum, Dorado, Eridanus, Hydrus, Reticulum. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Diciembre. Principales estrellas de la constelaci\u00f3n Horologium, El [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[485],"tags":[],"class_list":["post-48016","post","type-post","status-publish","format-standard","hentry","category-constelaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constelaci\u00f3n Horologium, El Reloj - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constelaci\u00f3n Horologium, El Reloj - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"Esta constelaci\u00f3n fue introducida por el astr\u00f3nomo Nicolas Louis de Lacaille, es uno de las menores constelaciones del sur. Las constelaciones vecinas o colindantes de Horologium, son las constelaciones de Caelum, Dorado, Eridanus, Hydrus, Reticulum. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Diciembre. Principales estrellas de la constelaci\u00f3n Horologium, El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-18T09:48:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T08:59:51+00:00\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-horologium-el-reloj\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-horologium-el-reloj\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"headline\": \"Constelaci\u00f3n Horologium, El Reloj\",\n\t            \"datePublished\": \"2018-11-18T09:48:54+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:51+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-horologium-el-reloj\\\/\"\n\t            },\n\t            \"wordCount\": 966,\n\t            \"articleSection\": [\n\t                \"Constelaci\u00f3nes\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-horologium-el-reloj\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-horologium-el-reloj\\\/\",\n\t            \"name\": \"Constelaci\u00f3n Horologium, El Reloj - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-11-18T09:48:54+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:51+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-horologium-el-reloj\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-horologium-el-reloj\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-horologium-el-reloj\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronom\u00eda\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constelaci\u00f3nes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/constelaciones\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constelaci\u00f3n Horologium, El Reloj\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constelaci\u00f3n Horologium, El Reloj - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/","og_locale":"es_ES","og_type":"article","og_title":"Constelaci\u00f3n Horologium, El Reloj - Online Star Register","og_description":"Esta constelaci\u00f3n fue introducida por el astr\u00f3nomo Nicolas Louis de Lacaille, es uno de las menores constelaciones del sur. Las constelaciones vecinas o colindantes de Horologium, son las constelaciones de Caelum, Dorado, Eridanus, Hydrus, Reticulum. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Diciembre. Principales estrellas de la constelaci\u00f3n Horologium, El [&hellip;]","og_url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2018-11-18T09:48:54+00:00","article_modified_time":"2024-08-05T08:59:51+00:00","author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"headline":"Constelaci\u00f3n Horologium, El Reloj","datePublished":"2018-11-18T09:48:54+00:00","dateModified":"2024-08-05T08:59:51+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/"},"wordCount":966,"articleSection":["Constelaci\u00f3nes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/","url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/","name":"Constelaci\u00f3n Horologium, El Reloj - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2018-11-18T09:48:54+00:00","dateModified":"2024-08-05T08:59:51+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-horologium-el-reloj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Astronom\u00eda","item":"https:\/\/osr.org\/es\/astronomia\/"},{"@type":"ListItem","position":3,"name":"Constelaci\u00f3nes","item":"https:\/\/osr.org\/es\/astronomia\/constelaciones\/"},{"@type":"ListItem","position":4,"name":"Constelaci\u00f3n Horologium, El Reloj"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/48016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=48016"}],"version-history":[{"count":2,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/48016\/revisions"}],"predecessor-version":[{"id":48730,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/48016\/revisions\/48730"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=48016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=48016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=48016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}