{"id":47229,"date":"2018-09-05T10:54:46","date_gmt":"2018-09-05T08:54:46","guid":{"rendered":"https:\/\/osr.org\/?p=47229\/"},"modified":"2024-08-05T11:00:14","modified_gmt":"2024-08-05T09:00:14","slug":"constelacion-sagitta-la-flecha","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/","title":{"rendered":"Constelaci\u00f3n Sagitta, La Flecha"},"content":{"rendered":"<p>Esta constelaci\u00f3n est\u00e1 compuesta por unas 26 estrellas, siendo su estrella principal Gamma Sagittae, sus constelaciones vecinas o colindantes son las siguientes 4 constelaciones, Aquila, Delphinus, Hercules, Vulpecula. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Septiembre.<\/p>\n<h2>Principales estrellas de la constelaci\u00f3n Sagitta, La flecha<\/h2>\n<ul>\n<li>\u03b3 Sagittae, es la estrella m\u00e1s brillante dela constelaci\u00f3n Sagita posee una magnitud aparente de 3,47; es una estrella gigante de color roja se encuentra a unos 275 a\u00f1os luz de distancia.<\/li>\n<li>\u03b1 Sagittae (Sham), Es una estrella gigante de color amarilla situada a unos 475 a\u00f1os luz de distancia. aunque ostenta la denominaci\u00f3n de Bayer Alfa, es s\u00f3lo la tercera estrella m\u00e1s brillante de la constelaci\u00f3n con magnitud 4,37,esta estrella se encuentra a 475 a\u00f1os luz de distancia<\/li>\n<li>\u03b2 Sagittae, es una estrella gigante de color amarilla con una magnitud aparente de 4,39.<\/li>\n<li>\u03b4 Sagittae, es una estrella binaria espectrosc\u00f3pica compuesta por una gigante de color roja y una estrella de color blanca.<\/li>\n<li>\u03b5 Sagittae, es una estrella gigante de color amarillo anaranjada con una magnitud aparente de 5,67.<\/li>\n<li>\u03b6 Sagittae, es una estrella m\u00faltiple con una magnitud aparente +5,00.<\/li>\n<li>\u03b7 Sagittae, es una estrella gigante de color naranja con una magnitud aparente de 5,10.<\/li>\n<li>13 Sagittae (VZ Sagittae), es una estrella gigante de color roja y variable irregular cuyo brillo var\u00eda entre de magnitud 5,27 y 5,57.<\/li>\n<li>15 Sagittae, es una estrella binaria formada por una enana de color amarilla similar al Sol y una enana de color marr\u00f3n, posee una magnitud aparente 5,8.<\/li>\n<li>S Sagittae (10 Sagittae), es una estrella variable cefeida cuyo brillo oscila entre 5,24 y 6,04 con un per\u00edodo de 8,382 d\u00edas.<\/li>\n<li>U Sagittae, una interesante variable eclipsante compuesta por una estrella de color azul y otra decolor naranja, cuya magnitud oscila entre 6,5 y 9,3 en algo m\u00e1s de tres d\u00edas y nueve horas.<\/li>\n<li>FG Sagittae, es una estrella de una nebulosa planetaria cuyo color y temperatura ha ido cambiando a lo largo de los \u00faltimos 100 a\u00f1os.<\/li>\n<li>HD 178428, es una estrella binaria espectrosc\u00f3pica con una magnitud aparente de 6,07.<\/li>\n<li>HD 231701, es una estrella de color blanco amarilla con un planeta extrasolar.<\/li>\n<li>WR 124, es una estrella de Wolf-Rayet rodeada por la nebulosa M1-67.<\/li>\n<li>Gliese 745, es un sistema compuesto por dos estrellas subenanas de color rojas del disco grueso.<\/li>\n<\/ul>\n<h2>Caracter\u00edsticas de la constelaci\u00f3n Sagitta, La flecha<\/h2>\n<ul>\n<li>La Constelaci\u00f3n Sagitta, La flecha, es una de las constelaciones m\u00e1s peque\u00f1as del espacio celeste<\/li>\n<li>No posee lluvias de Meteoros<\/li>\n<li>Est\u00e1 conformada por unas 26 estrellas en forma de flecha incrustada en el cielo entre las constelaciones de Vulpecula, delf\u00edn, el cisne y el \u00c1guila<\/li>\n<li>Esta constelaci\u00f3n es una de las 48 constelaciones introducidas por Ptolomeo.<\/li>\n<li>Esta peque\u00f1a e interesante constelaci\u00f3n es reconocida en diversas culturas como la persa, Hebrea, Griega, y Romana.<\/li>\n<li>Sus estrellas son de magnitud 3.8 a 5, por lo que se aprecia de manera d\u00e9bil.<\/li>\n<li>En esta constelaci\u00f3n est\u00e1 el c\u00famulo globular M71, este cumulo Fue descubierto por Philippe Loys de Ch\u00e9seaux en 1746, est\u00e1 situado tan cercano a la tierra a unos 2000 a\u00f1os luz desde la Tierra y abarca unos 27 a\u00f1os luz, por lo cual es posible que se puedan observar sus estrellas gigantes rojas desde cualquier telescopio. La dimensi\u00f3n aparente de este cumulo es como un quinto de la dimensi\u00f3n de la luna.<\/li>\n<li>Para los hebreos, persas, \u00e1rabes, griegos y romanos ya se consideraba que este grupo de estrellas era una flecha.<\/li>\n<li>En esta constelaci\u00f3n tambi\u00e9n se encuentra el cumulo abierto Harvard 20, es un cumulo pobre de una magnitud aparente de 7.7.<\/li>\n<li>La constelaci\u00f3n Sagitta, La Flecha, se encuentra entre las constelaciones Aquila, el \u00e1guila, y Cygnus, el cisne.<\/li>\n<li>Sagitta la tercera m\u00e1s peque\u00f1a de las 88 constelaciones reconocidas por la astronom\u00eda moderna.<\/li>\n<li>Es posible observar la constelaci\u00f3n Sagitta desde cualquier parte del planeta, excepto desde la Ant\u00e1rtida.<\/li>\n<li>El ecuador cruza la constelaci\u00f3n de Sagitta de norte a sur, por lo tanto, en ella se pueden observar gran cantidad de estrellas d\u00e9biles y c\u00famulos estelares y c\u00famulos globulares.<\/li>\n<li>La constelaci\u00f3n Sagitta, la flecha posee abundantes nebulosas planetarias.<\/li>\n<\/ul>\n<h2>Mitolog\u00eda de la constelaci\u00f3n Sagitta, La flecha<\/h2>\n<p>Se dice que esta constelacion no posee mitolog\u00edas asociadas, sin embargo, al igual que otras tantas constelaciones posee diversas historias en las cuales se explica el significado de la existencia de esta constelaci\u00f3n Sagitta, La flecha.<\/p>\n<p>Una de las historias es la de Ptolomeo, quien robo fuego de los dioses y lo llevo a los mortales lo que provoc\u00f3 la ira de Zeus, por lo cual lo encadenaron al \u00c1guila, H\u00e9rcules, lo salvo de este castigo matando el ave con una flecha y dej\u00e1ndolo libre, de esta manera lo hizo libre, este fue uno de los 12 trabajos de H\u00e9rcules.<\/p>\n<p>En otra historia La Flecha, habr\u00eda sido con la que Apo.lo mato a los ciclopes, para vengar que su hijo Asclenio hab\u00eda sido fulminado. Apolo luego escondi\u00f3 la flecha en el pa\u00eds de los hiperb\u00f3reos y la recuper\u00f3 una vez que Zeus hubo perdonado este acto una vez que Apolo hubo servido al rey Admeto de Feras.<\/p>\n<p>En otra de las leyendas Heracles mat\u00f3 las Aves Estimf\u00e0lides, que aterrorizaban la Arcadia, con un petarrelleig. Las mismas aves estimf\u00e0lides eran identificadas como Aquila, Cygnus y Lyra.<\/p>\n<p>Tambien Sagitta fue interpretada como la flecha de Cupido o como una flecha lanzada por Sagittarius a Scorpius.<\/p>\n<p>Otras interpretaciones consideran que la flecha fue lanzada por Centaurus en Aquila, dado que Centaurus est\u00e1 de cara a la direcci\u00f3n correcta y en un \u00e1ngulo apropiado respecto a la saeta, mientras Sagittarius es inmediatamente debajo y de cara en la direcci\u00f3n opuesta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta constelaci\u00f3n est\u00e1 compuesta por unas 26 estrellas, siendo su estrella principal Gamma Sagittae, sus constelaciones vecinas o colindantes son las siguientes 4 constelaciones, Aquila, Delphinus, Hercules, Vulpecula. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Septiembre. Principales estrellas de la constelaci\u00f3n Sagitta, La flecha \u03b3 Sagittae, es la estrella m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[485],"tags":[],"class_list":["post-47229","post","type-post","status-publish","format-standard","hentry","category-constelaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constelaci\u00f3n Sagitta, La Flecha - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constelaci\u00f3n Sagitta, La Flecha - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"Esta constelaci\u00f3n est\u00e1 compuesta por unas 26 estrellas, siendo su estrella principal Gamma Sagittae, sus constelaciones vecinas o colindantes son las siguientes 4 constelaciones, Aquila, Delphinus, Hercules, Vulpecula. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Septiembre. Principales estrellas de la constelaci\u00f3n Sagitta, La flecha \u03b3 Sagittae, es la estrella m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-05T08:54:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T09:00:14+00:00\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-sagitta-la-flecha\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-sagitta-la-flecha\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"headline\": \"Constelaci\u00f3n Sagitta, La Flecha\",\n\t            \"datePublished\": \"2018-09-05T08:54:46+00:00\",\n\t            \"dateModified\": \"2024-08-05T09:00:14+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-sagitta-la-flecha\\\/\"\n\t            },\n\t            \"wordCount\": 963,\n\t            \"articleSection\": [\n\t                \"Constelaci\u00f3nes\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-sagitta-la-flecha\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-sagitta-la-flecha\\\/\",\n\t            \"name\": \"Constelaci\u00f3n Sagitta, La Flecha - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-09-05T08:54:46+00:00\",\n\t            \"dateModified\": \"2024-08-05T09:00:14+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-sagitta-la-flecha\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-sagitta-la-flecha\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-sagitta-la-flecha\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronom\u00eda\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constelaci\u00f3nes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/constelaciones\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constelaci\u00f3n Sagitta, La Flecha\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constelaci\u00f3n Sagitta, La Flecha - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/","og_locale":"es_ES","og_type":"article","og_title":"Constelaci\u00f3n Sagitta, La Flecha - Online Star Register","og_description":"Esta constelaci\u00f3n est\u00e1 compuesta por unas 26 estrellas, siendo su estrella principal Gamma Sagittae, sus constelaciones vecinas o colindantes son las siguientes 4 constelaciones, Aquila, Delphinus, Hercules, Vulpecula. El mejor mes para observar esta constelaci\u00f3n es durante el mes de Septiembre. Principales estrellas de la constelaci\u00f3n Sagitta, La flecha \u03b3 Sagittae, es la estrella m\u00e1s [&hellip;]","og_url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2018-09-05T08:54:46+00:00","article_modified_time":"2024-08-05T09:00:14+00:00","author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"headline":"Constelaci\u00f3n Sagitta, La Flecha","datePublished":"2018-09-05T08:54:46+00:00","dateModified":"2024-08-05T09:00:14+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/"},"wordCount":963,"articleSection":["Constelaci\u00f3nes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/","url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/","name":"Constelaci\u00f3n Sagitta, La Flecha - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2018-09-05T08:54:46+00:00","dateModified":"2024-08-05T09:00:14+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-sagitta-la-flecha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Astronom\u00eda","item":"https:\/\/osr.org\/es\/astronomia\/"},{"@type":"ListItem","position":3,"name":"Constelaci\u00f3nes","item":"https:\/\/osr.org\/es\/astronomia\/constelaciones\/"},{"@type":"ListItem","position":4,"name":"Constelaci\u00f3n Sagitta, La Flecha"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=47229"}],"version-history":[{"count":2,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47229\/revisions"}],"predecessor-version":[{"id":47463,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47229\/revisions\/47463"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=47229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=47229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=47229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}