{"id":47226,"date":"2018-09-24T09:00:21","date_gmt":"2018-09-24T07:00:21","guid":{"rendered":"https:\/\/osr.org\/?p=47226\/"},"modified":"2024-08-05T11:00:06","modified_gmt":"2024-08-05T09:00:06","slug":"constelacion-leo-minor-el-leon-menor","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/","title":{"rendered":"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor"},"content":{"rendered":"<p>La Constelaci\u00f3n Leo Minor, puede ser reconocida como un peque\u00f1o triangulo, es una constelaci\u00f3n del hemisferio norte, con solo unas pocas estrellas luminosas, fue introducida por Johannes Hevelius, quien fue un astr\u00f3nomo oriundo de Polonia, tambi\u00e9n es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna.<\/p>\n<p>Las constelaciones vecinas o colindantes de Leo Minor son, Cancer, Leo, Lynx, Ursa Major, y el mejor mes para observar esta constelacion es durante el mes de Abril.<\/p>\n<h2>Principales estrellas de la Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor<\/h2>\n<ul>\n<li>\u03b2 Leonis Minoris, no es la estrella m\u00e1s brillante posee una magnitud aparente de 4,21. Es una estrella binaria cuya componente principal es una gigante de color amarilla, la estrella gigante tiene una temperatura superficial de 5075 K y una luminosidad 36 veces mayor que la del Sol. Su radio es 7,8 veces m\u00e1s grande que el radio solar y su masa se estima en algo menos de dos masas solares, Se encuentra a 146 a\u00f1os luz de distancia del Sistema Solar.<\/li>\n<li>11 Leonis Minoris, es un sistema binario que se encuentra a 36,5 a\u00f1os luz de distancia, esta compuesto por una enana de color amarilla variable y una enana de color roja, Su masa se estima en torno al 86% de la masa del Sol, siendo su di\u00e1metro incierto, con estimaciones comprendidas entre 0,85 y 1,44 veces el valor del di\u00e1metro solar. Brilla con una luminosidad bolom\u00e9trica equivalente al 78% de la luminosidad solar. De metalicidad comparable a la del Sol.<\/li>\n<li>19 Leonis Minoris, es una estrella de color blanca con una magnitud aparente de 5,11.<\/li>\n<li>20 Leonis Minoris, es una estrella binaria formada por una enana de color amarilla y una enana de color roja activa a 49 a\u00f1os luz, se encuentra a 48,6 a\u00f1os luz de distancia del Sistema Solar.<\/li>\n<li>21 Leonis Minoris, es una estrella de color blanca de la secuencia principal con una magnitud aparente de 4,48, es la tercera m\u00e1s brillante de la constelaci\u00f3n, Forma parte de la corriente de estrellas de la Asociaci\u00f3n estelar de la Osa Mayor, Es una estrella de caracter\u00edsticas similares a \u03b8 Cassiopeiae, aunque es menos luminosa. Su luminosidad es 10 veces mayor que la del Sol y su radio es 1,6 veces m\u00e1s grande que el del mismo. \u200b Su velocidad de rotaci\u00f3n de m\u00e1s de 165 km\/s5\u200b es 80 veces mayor que la del Sol, pero es normal en una estrella de su clase. Tiene un contenido met\u00e1lico pr\u00e1cticamente igual al del Sol<\/li>\n<li>24 Leonis Minoris, es un an\u00e1logo solar con una magnitud aparente de 6,47 se encuentra a 104 a\u00f1os luz de distancia del Sistema Solar, 24 Leonis Minoris tiene un contenido relativo de hierro comparable al del Sol ([Fe\/H] = +0,05). Diversos elementos evaluados presentan valores semejantes a los solares. Cabe se\u00f1alar el escandio, algo m\u00e1s abundante y, en el otro extremo, el azufre, cuyo contenido es un 33% menor que en nuestra estrella<\/li>\n<li>37 Leonis Minoris, gigante luminosa amarilla de magnitud 4,69, tienen una luminosidad notablemente elevada pero no son tan brillantes ni tan masivas como para ser clasificadas como supergigantes, 37 Leonis Minoris es muy luminosa, 269 veces m\u00e1s que nuestro Sol<\/li>\n<li>46 Leonis Minoris (Praecipua), es la estrella m\u00e1s brillante de la constelacion de Leo Minor a pesar de no tener denominaci\u00f3n de Bayer. Es una gigante de color naranja se encuentra a 98 a\u00f1os luz de distancia, posee una magnitud aparente de +3,83, Praecipua es un nombre relativamente moderno y proviene del t\u00e9rmino en lat\u00edn que significa \u00abjefe\u00bb o \u00abprimero\u00bb, aludiendo a su condici\u00f3n de estrella m\u00e1s brillante. Se encuentra a 98 a\u00f1os luz de distancia del Sistema Solar<\/li>\n<li>51 Leonis Minoris, es una estrella del disco grueso con una magnitud aparente de 7,60.<\/li>\n<li>R Leonis Minoris, es una variable tipo Mira, posee una magnitud variable entre 6,3 y 13,2 en un ciclo de 372,19 d\u00edas.<\/li>\n<li>RY Leonis Minoris (G117-B15A), es una estrella enana de color blanca variable del tipo ZZ Ceti.<\/li>\n<li>HD 87883, es una estrella enana de color naranja con un planeta extrasolar.<\/li>\n<\/ul>\n<h2>Caracter\u00edsticas de la Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor<\/h2>\n<ul>\n<li>la Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor, fue creada por el astr\u00f3nomo polaco Johannes Hevelius hacia 1660 (en una obra publicada en 1690, despu\u00e9s de su muerte) para llenar un espacio entre Ursa Maior y Leo, no posee ninguna estrella Alfa, ya que fue olvidada accidentalmente por el astr\u00f3nomo Francis Baily en la asignaci\u00f3n de las letras griegas, forma parte de las 88 constelaciones actualmente reconocidas por la astronomia moderna.<\/li>\n<li>En el espacio celeste al visualizar la Osa Mayor y la constelaci\u00f3n de Leo, se encuentra cercana la constelaci\u00f3n de Leo Minor, Esta peque\u00f1a constelaci\u00f3n se situa exactamente entre las dos constelaciones, al pie de la Osa Mayor y de la cabeza de Leo. La cabeza de Leo Minor casi toca la cola del Lince, otra constelaci\u00f3n poco conocida.<\/li>\n<li>Esta peque\u00f1a constelaci\u00f3n ocupa unos 232,0 grados cuadrados, su puede visualizar Completa, entre 48\u00b0 S y 90\u00b0 N y Parcial, Entre 67\u00b0 S y 48\u00b0 S.<\/li>\n<li>En la constelaci\u00f3n Leo Minor, se presentan dos lluvias de meteoros conocidas con los nombres de Leo Min\u00f3ridas, Leo Min\u00f3ridas de diciembre.<\/li>\n<li>El mejor mes para visualizar esta constelaci\u00f3n es durante el mes de Abril<\/li>\n<\/ul>\n<h2>Mitolog\u00eda de la Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor<\/h2>\n<p>La constelaci\u00f3n de Leo Minor el le\u00f3n menor fue creada por Jonnanes Hevelius en el a\u00f1o 1687 esto para rellenar el hueco que ocupaba la zona muy pobre en estrellas entre el Leo, Le\u00f3n y la Osa Mayor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Constelaci\u00f3n Leo Minor, puede ser reconocida como un peque\u00f1o triangulo, es una constelaci\u00f3n del hemisferio norte, con solo unas pocas estrellas luminosas, fue introducida por Johannes Hevelius, quien fue un astr\u00f3nomo oriundo de Polonia, tambi\u00e9n es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna. Las constelaciones vecinas o colindantes de Leo Minor [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[485],"tags":[],"class_list":["post-47226","post","type-post","status-publish","format-standard","hentry","category-constelaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"La Constelaci\u00f3n Leo Minor, puede ser reconocida como un peque\u00f1o triangulo, es una constelaci\u00f3n del hemisferio norte, con solo unas pocas estrellas luminosas, fue introducida por Johannes Hevelius, quien fue un astr\u00f3nomo oriundo de Polonia, tambi\u00e9n es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna. Las constelaciones vecinas o colindantes de Leo Minor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-24T07:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T09:00:06+00:00\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-leo-minor-el-leon-menor\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-leo-minor-el-leon-menor\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"headline\": \"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor\",\n\t            \"datePublished\": \"2018-09-24T07:00:21+00:00\",\n\t            \"dateModified\": \"2024-08-05T09:00:06+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-leo-minor-el-leon-menor\\\/\"\n\t            },\n\t            \"wordCount\": 938,\n\t            \"articleSection\": [\n\t                \"Constelaci\u00f3nes\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-leo-minor-el-leon-menor\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-leo-minor-el-leon-menor\\\/\",\n\t            \"name\": \"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-09-24T07:00:21+00:00\",\n\t            \"dateModified\": \"2024-08-05T09:00:06+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-leo-minor-el-leon-menor\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-leo-minor-el-leon-menor\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-leo-minor-el-leon-menor\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronom\u00eda\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constelaci\u00f3nes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/constelaciones\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/","og_locale":"es_ES","og_type":"article","og_title":"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor - Online Star Register","og_description":"La Constelaci\u00f3n Leo Minor, puede ser reconocida como un peque\u00f1o triangulo, es una constelaci\u00f3n del hemisferio norte, con solo unas pocas estrellas luminosas, fue introducida por Johannes Hevelius, quien fue un astr\u00f3nomo oriundo de Polonia, tambi\u00e9n es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna. Las constelaciones vecinas o colindantes de Leo Minor [&hellip;]","og_url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2018-09-24T07:00:21+00:00","article_modified_time":"2024-08-05T09:00:06+00:00","author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"headline":"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor","datePublished":"2018-09-24T07:00:21+00:00","dateModified":"2024-08-05T09:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/"},"wordCount":938,"articleSection":["Constelaci\u00f3nes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/","url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/","name":"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2018-09-24T07:00:21+00:00","dateModified":"2024-08-05T09:00:06+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-leo-minor-el-leon-menor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Astronom\u00eda","item":"https:\/\/osr.org\/es\/astronomia\/"},{"@type":"ListItem","position":3,"name":"Constelaci\u00f3nes","item":"https:\/\/osr.org\/es\/astronomia\/constelaciones\/"},{"@type":"ListItem","position":4,"name":"Constelaci\u00f3n Leo Minor, El Le\u00f3n Menor"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=47226"}],"version-history":[{"count":2,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47226\/revisions"}],"predecessor-version":[{"id":47466,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47226\/revisions\/47466"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=47226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=47226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=47226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}