{"id":47223,"date":"2018-11-29T15:11:57","date_gmt":"2018-11-29T13:11:57","guid":{"rendered":"https:\/\/osr.org\/?p=47223\/"},"modified":"2024-08-05T10:59:47","modified_gmt":"2024-08-05T08:59:47","slug":"constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/","title":{"rendered":"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina"},"content":{"rendered":"<p>Hydrus, fue introducida por Pieter Dirkszoon Keyser y Frederick de Houtman entre los a\u00f1os de 1595 y 1597, tambi\u00e9n es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, debido a su posici\u00f3n austral no fue visible para las culturas antiguas no tiene mitolog\u00eda relacionada.<\/p>\n<p>En esta constelaci\u00f3n no se presentan lluvias de meteoros, sus constelaciones vecinas o colindantes son, Dorado, Eridanus, Horologium, Mensa, Octans, Phoenix, Reticulum, Tucana.<\/p>\n<h2>Principales estrellas de La Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina<\/h2>\n<ul>\n<li>\u03b2 Hydri, con magnitud 2,80, es una estrella subgigante de color amarilla cercana, situada a poco m\u00e1s de 24 a\u00f1os luz del Sistema Solar, es 108 por ciento de la masa del Sol y alrededor de 181 por ciento del radio solar. Es 3.494 veces m\u00e1s luminosa que el Sol, es una de las estrellas m\u00e1s antiguas del entorno del Sol.<\/li>\n<li>\u03b1 Hydri, es una estrella de color blanco amarilla de la secuencia principal, la segunda m\u00e1s brillante de esta constelaci\u00f3n con magnitud 2,90, Alfa Hydri es 80 veces m\u00e1s grande que el Sol y el doble de masiva. Es 32 veces m\u00e1s luminosa que el astro. Se supone que esta estrella tenga alrededor de 810 millones a\u00f1os de edad<\/li>\n<li>\u03b3 Hydri, es una estrella gigante de color roja con una magnitud aparente de 3,26. Se encuentra en el v\u00e9rtice sureste del asterismo triangular que domina la constelaci\u00f3n. Se encuentra a unos 214 a\u00f1os luz de distancia de la Tierra.<\/li>\n<li>\u03b4 Hydri, es una estrella de color blanca de la secuencia principal con una magnitud aparente de 4,08.<\/li>\n<li>\u03b8 Hydri, una estrella qu\u00edmicamente peculiar del tipo Bw muestra l\u00edneas d\u00e9biles de helio en su espectro de magnitud aparente de 5,50.<\/li>\n<li>\u03b7 Hydri es una denominaci\u00f3n de Bayer compartida por dos estrellas disintas; \u03b71 Hydri, de magnitud 6,77, y \u03b72 Hydri, de magnitud 4,69, estrella gigante con un planeta extrasolar masivo.<\/li>\n<li>Gliese 127.1, es una estrella enana de color blanca se encuentra a 33,1 a\u00f1os luz de distancia<\/li>\n<li>Gliese 3021, es una estrella enana de color amarilla con un planeta extrasolar.<\/li>\n<li>HD 13551, es una estrella peculiar considerada hoy una estrella CH.<\/li>\n<\/ul>\n<h2>Caracter\u00edsticas de La Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina<\/h2>\n<ul>\n<li>La constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina, es una de Las 20 constelaciones creadas por Pieter Dirkszoon Keyser y Frederick de Houtman, y est\u00e1n entre las 88 constelaciones que actualmente son reconocidas por la astronom\u00eda moderna.<\/li>\n<li>En esta constelaci\u00f3n no se presentan lluvias de meteoros.<\/li>\n<li>Dado que fue creada en el siglo XVII y debido a su posici\u00f3n austral no fue visible para las culturas antiguas.<\/li>\n<li>Esta constelaci\u00f3n ocupa 243 grados cuadrados y unas 33 estrellas, Se encuentra en el primer cuadrante del hemisferio sur (SQ1) y se puede ver en las latitudes entre 8 \u00b0 y -90 \u00b0.<\/li>\n<li>Las principales estrellas de Hydrus, conocidas con los nombres de \u03b1 Hydri, \u03b2 Hydri y \u03b3 Hydri son estrellas de tercera magnitud ellas forman un tri\u00e1ngulo al sur de la brillante estrella Achernar (\u03b1 Eridani). \u03b2 Hydri, la cual se encuentra a 24 a\u00f1os luz de distancia del Sistema Solar, esta es una estrella decolor amarilla m\u00e1s evolucionada y antigua que nuestro Sol que se encuentra en fase de subgigante. Alrededor de \u03b72 Hydri estrella gigante en esta constelaci\u00f3n se ha detectado un planeta extrasolar masivo.<\/li>\n<li>Los objetos astron\u00f3micos de mayor relevancia en la constelaci\u00f3n son: el c\u00famulo globular NGC 1466; el cual se presume est\u00e1 asociado a la gran nube de Magallanes, que es una galaxia sat\u00e9lite de la V\u00eda L\u00e1ctea, John Dreyer lo describi\u00f3 como \u00abpF, pS, iR, glbM, * 7 f\u00bb, que significa \u00abbastante d\u00e9bil, bastante peque\u00f1o, redondo irregular, gradualmente un poco m\u00e1s brillante en el medio, con una estrella de s\u00e9ptima magnitud cerca, El grupo se caracteriza por la gran cantidad de estrellas variables de tipo RR Lyrae, y las m\u00e1s brillantas son de magnitud 19. y tambi\u00e9n la galaxia espiral NGC 1511,la cual es una galaxia espiral barrada, se encuentra a unos 61 millones de a\u00f1os luz de la V\u00eda L\u00e1ctea esta acompa\u00f1ada por otras dos galaxias, se encuentra en la misma regi\u00f3n del cielo que las galaxias NGC 1511A (ESO 55-5) y NGC 1511B (ESO 55-6). Su distancia de la V\u00eda L\u00e1ctea var\u00eda de 59 a 61 millones de a\u00f1os luz. Por lo tanto, se cree que forman un triplete de galaxia. Tiene una magnitud visual aparente de 11,0. y fue descubierta por el astr\u00f3nomo brit\u00e1nico J. Herschel el a\u00f1o 1.834.<\/li>\n<li>NGC 1473 la cual es una galaxia irregular. con una magnitud visual aparente de 13,0 esta galaxia fue descubierta por J. Herschel en el a\u00f1o 1.834.<\/li>\n<li>Esta constelaci\u00f3n contiene cuatro estrellas con planetas conocidos y no tiene objetos Messier.<\/li>\n<li>Esta constelaci\u00f3n, aunque presenta un nombre similar no debe confundirse con la inmensa Galaxia de Hidra, la cual es la m\u00e1s extensa del espacio celeste.<\/li>\n<li>La Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina la cabeza de Hydrus toca al Octante en el polo sur, y su cola sube hasta acercarse a Achernar (\u03b1. Eri)<\/li>\n<\/ul>\n<h2>Mitolog\u00eda de La Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina<\/h2>\n<p>La Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina, Debido a su posici\u00f3n austral de La Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina, no era visible para las culturas antiguas, es por ello que no tiene mitolog\u00eda relacionada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hydrus, fue introducida por Pieter Dirkszoon Keyser y Frederick de Houtman entre los a\u00f1os de 1595 y 1597, tambi\u00e9n es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, debido a su posici\u00f3n austral no fue visible para las culturas antiguas no tiene mitolog\u00eda relacionada. En esta constelaci\u00f3n no se presentan lluvias de meteoros, [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[485],"tags":[],"class_list":["post-47223","post","type-post","status-publish","format-standard","hentry","category-constelaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"Hydrus, fue introducida por Pieter Dirkszoon Keyser y Frederick de Houtman entre los a\u00f1os de 1595 y 1597, tambi\u00e9n es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, debido a su posici\u00f3n austral no fue visible para las culturas antiguas no tiene mitolog\u00eda relacionada. En esta constelaci\u00f3n no se presentan lluvias de meteoros, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-29T13:11:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T08:59:47+00:00\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"headline\": \"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina\",\n\t            \"datePublished\": \"2018-11-29T13:11:57+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:47+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\\\/\"\n\t            },\n\t            \"wordCount\": 916,\n\t            \"articleSection\": [\n\t                \"Constelaci\u00f3nes\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\\\/\",\n\t            \"name\": \"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-11-29T13:11:57+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:47+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronom\u00eda\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constelaci\u00f3nes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/constelaciones\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/","og_locale":"es_ES","og_type":"article","og_title":"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina - Online Star Register","og_description":"Hydrus, fue introducida por Pieter Dirkszoon Keyser y Frederick de Houtman entre los a\u00f1os de 1595 y 1597, tambi\u00e9n es una de las 88 constelaciones reconocidas por la astronom\u00eda moderna, debido a su posici\u00f3n austral no fue visible para las culturas antiguas no tiene mitolog\u00eda relacionada. En esta constelaci\u00f3n no se presentan lluvias de meteoros, [&hellip;]","og_url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2018-11-29T13:11:57+00:00","article_modified_time":"2024-08-05T08:59:47+00:00","author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"headline":"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina","datePublished":"2018-11-29T13:11:57+00:00","dateModified":"2024-08-05T08:59:47+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/"},"wordCount":916,"articleSection":["Constelaci\u00f3nes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/","url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/","name":"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2018-11-29T13:11:57+00:00","dateModified":"2024-08-05T08:59:47+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hydrus-la-hidra-macho-o-la-serpiente-marina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Astronom\u00eda","item":"https:\/\/osr.org\/es\/astronomia\/"},{"@type":"ListItem","position":3,"name":"Constelaci\u00f3nes","item":"https:\/\/osr.org\/es\/astronomia\/constelaciones\/"},{"@type":"ListItem","position":4,"name":"Constelaci\u00f3n Hydrus, La Hidra Macho o la Serpiente Marina"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=47223"}],"version-history":[{"count":2,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47223\/revisions"}],"predecessor-version":[{"id":48733,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47223\/revisions\/48733"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=47223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=47223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=47223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}