{"id":47216,"date":"2018-11-30T10:14:00","date_gmt":"2018-11-30T08:14:00","guid":{"rendered":"https:\/\/osr.org\/?p=47216\/"},"modified":"2024-08-05T10:59:46","modified_gmt":"2024-08-05T08:59:46","slug":"constelacion-hidra-la-hydra","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/","title":{"rendered":"Constelaci\u00f3n Hidra, La Hydra"},"content":{"rendered":"<p>La Hydra es tan larga que cuatro constelaciones se desplazan por su cara norte. (C\u00e1ncer, Leo, Virgo y Libra), esta Bella constelaci\u00f3n del hemisferio sur, tambi\u00e9n conocida como la serpiente hembra. En ella se presenta 4 lluvias de meteoros conocidas como, Alfa H\u00eddridas, Eta H\u00eddridas, Pi H\u00eddridas, Sigma H\u00eddridas.<\/p>\n<h2>Principales estrellas de la constelaci\u00f3n de Hidra, La Hydra<\/h2>\n<ul>\n<li>\u03b1 Hydrae (Alfard, Alphard o Cor Hydrae), es una estrella gigante de color naranja con una magnitud aparente de 1,99.<\/li>\n<li>\u03b3 Hydrae (Dhanab al Shuja), es una estrella gigante de color amarilla con una magnitud aparente de 2,99, es la segunda estrella m\u00e1s brillante de Hidra.<\/li>\n<li>\u03b2 Hydrae, estrella binaria con una magnitud aparente de 4,29 cuyas componentes estan separadas 1,7 segundos de arco.<\/li>\n<li>\u03b4 Hydrae, es una estrella de color blanca con una magnitud aparente de 4,14.<\/li>\n<li>\u03b5 Hydrae, es un sistema estelar m\u00faltiple con una magnitud conjunta 3,38.<\/li>\n<li>\u03b6 Hydrae, es una gigante luminosa de color amarilla con una magnitud aparente de 3,11.<\/li>\n<li>\u03b7 Hydrae, es una estrella de color blanco azulada con una magnitud aparente de 4,30.<\/li>\n<li>\u03b8 Hydrae, es una estrella de color blanco azulada de la secuencia principal con una magnitud aparente 3,88.<\/li>\n<li>\u03b9 Hydrae, es una estrella gigante de color naranja con una magnitud aparente de 3,91.<\/li>\n<li>\u03bb Hydrae, es una estrella gigante de color naranja con una magnitud aparente de 3,61 rica en cian\u00f3geno.<\/li>\n<li>\u03bc Hydrae, es una estrella gigante de color naranja, siendo su magnitud 3,83.<\/li>\n<li>\u03bd Hydrae, es una estrella gigante de color naranja con una magnitud aparente de 3,11.<\/li>\n<li>\u03be Hydrae, es una estrella gigante la cual ha sido estudiada en el campo de la astrosismolog\u00eda; tiene una superficie, al igual que la del Sol, se mueve de arriba abajo produciendo ondas sonoras.<\/li>\n<li>\u03c0 Hydrae, es una estrella gigante de color naranja con una magnitud aparente 3,26.<\/li>\n<li>\u03c3 Hydrae (Al Minliar al Shuja o Minchir), es una estrella gigante de color naranja con una magnitud aparente de 4,45.<\/li>\n<li>\u03c41 Hydrae (Ukdah Prima), es una estrella enana de color blanco amarilla m\u00e1s caliente y luminosa que el Sol.<\/li>\n<li>\u03c51 Hydrae, es una estrella gigante de color amarilla con una magnitud de 4,11 que tiene como acompa\u00f1ante a una enana de color marr\u00f3n.<\/li>\n<li>\u03c9 Hydrae, es una estrella supergigante de color naranja con una magnitud aparente de 5,00.<\/li>\n<li>C Hydrae (30 Monocerotis), es una estrella de color blanca con dos cinturones de polvo diferenciados.<\/li>\n<li>2 Sextantis, es una estrella gigante de color naranja con una magnitud aparente de 4,69; pese a su nombre, se encuentra en la constelaci\u00f3n de Hidra.<\/li>\n<li>3 Hydrae (HV Hydrae), estrella peculiar y variable Alfa2 Canum Venaticorum.<\/li>\n<li>9 Hydrae, es una estrella gigante de color naranja con una magnitud aparente 4,87.<\/li>\n<li>12 Hydrae (D Hydrae), es una estrella gigante de color amarilla con una magnitud aparente 4,32.<\/li>\n<li>21 Hydrae (KW Hydrae), es una estrella binaria eclipsante con una magnitud aparente de 6,10.<\/li>\n<li>27 Hydrae, estrella m\u00faltiple formada por dos binarias; la separaci\u00f3n entre ellas es de 229 segundos de arco.<\/li>\n<\/ul>\n<h2>Caracter\u00edsticas de la constelaci\u00f3n de Hidra, La Hydra<\/h2>\n<ul>\n<li>La Hydra, tambi\u00e9n conocida con el nombre de la serpiente de mar, es la constelaci\u00f3n m\u00e1s grande del espacio celeste.<\/li>\n<li>Es una de las 48 constelaciones introducidas por Ptolomeo, y la m\u00e1s grande las 88 constelaciones de la astronom\u00eda moderna.<\/li>\n<li>A pesar de su extenso tama\u00f1o es algo complicado identificarla ya que sus estrellas son de poco brillo, sin embargo se puede ver casi desde cualquier punto del planeta.<\/li>\n<li>La Hydra, tiene una superficie total de 100\u00ba y cruza gran parte de la b\u00f3veda celeste, Es una constelaci\u00f3n muy alargada se encuentra paralela al ecuador de la V\u00eda L\u00e1ctea limitando al sur de la misma.<\/li>\n<li>Las estrellas que conforman la constelaci\u00f3n La Hydra, son d\u00e9biles de la segunda magnitud a excepci\u00f3n de alfa de magnitud 1,99 situada en el sector oriental y limita con C\u00e1ncer y Monoceros.<\/li>\n<li>En ella se presenta 4 lluvias de meteoros.<\/li>\n<\/ul>\n<h2>Mitolog\u00eda de la constelaci\u00f3n de Hidra, La Hydra<\/h2>\n<p>En mitolog\u00eda, la constelaci\u00f3n La Hydra, se la asocia con la Hidra de Lerna, la cual fue vencida por H\u00e9rcules en el segundo de sus trabajos. Ten\u00eda una posici\u00f3n en el cielo situada bajo la ecl\u00edptica y junto a la constelaci\u00f3n C\u00e1ncer (cerca de su cabeza) puede ser el origen de parte del mito.<\/p>\n<p>Lerna, que viv\u00eda bajo el terror de hidra, un monstruo de nueve cabezas que emitia vapores venenosos, era tan monstruosa que por cada cabeza que se le quitara nac\u00edan 3 cabezas nuevas. H\u00e9rcules con el fin de aniquilarlo lo forz\u00f3 a salir de su madriguera dispar\u00e1ndole dardos de fuego y no respir\u00f3 mientras dur\u00f3 el combate. Cort\u00f3 las cabezas, pero a cada golpe de su espada nac\u00edan otras nuevas. Yalao acudi\u00f3 en su ayuda prendi\u00f3 fuego en una esquina de la cueva y, con las ramas encendidas, quem\u00f3 y cauterizo las heridas de la Hidra, as\u00ed de este modo paro el flujo de sangre para impedir que se formaran nuevas cabezas. H\u00e9rcules encontr\u00f3 la inmortal cabeza de oro de Hidra; la arranc\u00f3 del cuerpo y la enterr\u00f3 debajo de una pesada roca. Despu\u00e9s, la eviscer\u00f3 y moj\u00f3 las puntas de sus flechas en la hiel del monstruo. Desde entonces cualquier herida producida con estas flechas ha tenido consecuencias fatales.<\/p>\n<p>Esta constelaci\u00f3n se presenta como una serpiente retorci\u00e9ndose, y as\u00ed aparece en algunos mitos griegos.<\/p>\n<p>Otra historia cuenta que, Apolo tiene como sirviente a un cuervo a quien envi\u00f3 en busca de, sin embargo este se detiene durante su viaje y, cuando finalmente recoge agua en una taza, trae tambi\u00e9n una culebra de agua como excusa. Apolo se da cuenta del enga\u00f1o y, enojado, lanza al cuervo, la taza y la serpiente al cielo. El origen de la historia parece venir de la cercan\u00eda de esta constelaci\u00f3n con las de Cr\u00e1ter, y Corvus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Hydra es tan larga que cuatro constelaciones se desplazan por su cara norte. (C\u00e1ncer, Leo, Virgo y Libra), esta Bella constelaci\u00f3n del hemisferio sur, tambi\u00e9n conocida como la serpiente hembra. En ella se presenta 4 lluvias de meteoros conocidas como, Alfa H\u00eddridas, Eta H\u00eddridas, Pi H\u00eddridas, Sigma H\u00eddridas. Principales estrellas de la constelaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[485],"tags":[],"class_list":["post-47216","post","type-post","status-publish","format-standard","hentry","category-constelaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constelaci\u00f3n Hidra, La Hydra - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constelaci\u00f3n Hidra, La Hydra - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"La Hydra es tan larga que cuatro constelaciones se desplazan por su cara norte. (C\u00e1ncer, Leo, Virgo y Libra), esta Bella constelaci\u00f3n del hemisferio sur, tambi\u00e9n conocida como la serpiente hembra. En ella se presenta 4 lluvias de meteoros conocidas como, Alfa H\u00eddridas, Eta H\u00eddridas, Pi H\u00eddridas, Sigma H\u00eddridas. Principales estrellas de la constelaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-30T08:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T08:59:46+00:00\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hidra-la-hydra\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hidra-la-hydra\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"headline\": \"Constelaci\u00f3n Hidra, La Hydra\",\n\t            \"datePublished\": \"2018-11-30T08:14:00+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:46+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hidra-la-hydra\\\/\"\n\t            },\n\t            \"wordCount\": 976,\n\t            \"articleSection\": [\n\t                \"Constelaci\u00f3nes\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hidra-la-hydra\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hidra-la-hydra\\\/\",\n\t            \"name\": \"Constelaci\u00f3n Hidra, La Hydra - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-11-30T08:14:00+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:59:46+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hidra-la-hydra\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hidra-la-hydra\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-hidra-la-hydra\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronom\u00eda\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constelaci\u00f3nes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/constelaciones\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constelaci\u00f3n Hidra, La Hydra\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constelaci\u00f3n Hidra, La Hydra - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/","og_locale":"es_ES","og_type":"article","og_title":"Constelaci\u00f3n Hidra, La Hydra - Online Star Register","og_description":"La Hydra es tan larga que cuatro constelaciones se desplazan por su cara norte. (C\u00e1ncer, Leo, Virgo y Libra), esta Bella constelaci\u00f3n del hemisferio sur, tambi\u00e9n conocida como la serpiente hembra. En ella se presenta 4 lluvias de meteoros conocidas como, Alfa H\u00eddridas, Eta H\u00eddridas, Pi H\u00eddridas, Sigma H\u00eddridas. Principales estrellas de la constelaci\u00f3n de [&hellip;]","og_url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2018-11-30T08:14:00+00:00","article_modified_time":"2024-08-05T08:59:46+00:00","author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"headline":"Constelaci\u00f3n Hidra, La Hydra","datePublished":"2018-11-30T08:14:00+00:00","dateModified":"2024-08-05T08:59:46+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/"},"wordCount":976,"articleSection":["Constelaci\u00f3nes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/","url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/","name":"Constelaci\u00f3n Hidra, La Hydra - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2018-11-30T08:14:00+00:00","dateModified":"2024-08-05T08:59:46+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-hidra-la-hydra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Astronom\u00eda","item":"https:\/\/osr.org\/es\/astronomia\/"},{"@type":"ListItem","position":3,"name":"Constelaci\u00f3nes","item":"https:\/\/osr.org\/es\/astronomia\/constelaciones\/"},{"@type":"ListItem","position":4,"name":"Constelaci\u00f3n Hidra, La Hydra"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=47216"}],"version-history":[{"count":2,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47216\/revisions"}],"predecessor-version":[{"id":48734,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/47216\/revisions\/48734"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=47216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=47216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=47216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}