{"id":45943,"date":"2018-03-11T13:58:37","date_gmt":"2018-03-11T11:58:37","guid":{"rendered":"https:\/\/osr.org\/?p=45943\/"},"modified":"2024-08-05T10:57:07","modified_gmt":"2024-08-05T08:57:07","slug":"constelacion-de-virgo","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/","title":{"rendered":"Constelaci\u00f3n de Virgo"},"content":{"rendered":"<p>Virgo o La virgen por su significado en lat\u00edn, forma parte de las 12 constelaciones que componen el zodiaco, y tambi\u00e9n de las 88 constelaciones reconocidas por la astronom\u00eda moderna, realmente esta constelaci\u00f3n es muy extensa, ocupa una superficie del espacio celeste de aproximadamente 1300 grados cuadrados, lo cual representa el 3,138 %<\/p>\n<p>A lo largo de su extensi\u00f3n tiene unas 271 estrellas, de las cuales la m\u00e1s brillantes es conocida con el nombre de \u03b1 Virginis (Espiga o Spica), esta es la m\u00e1s brillante de la constelaci\u00f3n, y adem\u00e1s es la estrella n\u00famero 16 m\u00e1s brillantes del cielo nocturno posee una magnitud aparente de +1,0, se trata de una gigante decolor azul.<\/p>\n<p>Virgo, es la segunda constelaci\u00f3n m\u00e1s grande del firmamento, su tama\u00f1o solo es superado por Hydra, esta constelaci\u00f3n se puede localizar de forma sencilla visualizando la curva que va desde el Carro u Osa Mayor hacia (\u03b1 Bootis) hasta llegar a Espiga.y es visible entre + 80 \u00b0 y -80\u00b0.<\/p>\n<p>Virgo considerada una diosa de la Justicia, conocida en la mitolog\u00eda como Temis o Astrea, es representada llevando una balanza, as\u00ed como tambi\u00e9n una espiga de trigo. Por su ubicaci\u00f3n en el espacio celeste se encuentra entre Leo al oeste y Libra al este, Su Principal estrella \u03b1 Virginis (Espiga o Spica), es una gigante azul, una de las 16 estrellas m\u00e1s brillantes del cielo nocturno y la m\u00e1s brillante de la constelaci\u00f3n con magnitud aparente +1,0, es dos veces m\u00e1s luminosa y m\u00e1s potente que el sol, a pesar de la inmensidad de esta constelacion solo su estrella principal es la m\u00e1s luminosa, por lo que no suele ser la constelacion m\u00e1s luminosa del espacio celeste.<\/p>\n<p>Sus constelaciones vecinas o colindantes son las constelaciones de Leo, Libra, Bo\u00f6tes, Hydra, Berenices, Corvus, Crater, y Serpens Caput.<\/p>\n<p>Virgo considerada una diosa de la Justicia, conocida en la mitolog\u00eda como Temis o Astrea, es representada llevando una balanza, as\u00ed como tambi\u00e9n una espiga de trigo. Por su ubicaci\u00f3n en el espacio celeste se encuentra entre Leo al oeste y Libra al este, Su Principal estrella \u03b1 Virginis (Espiga o Spica), es una gigante azul, una de las 16 estrellas m\u00e1s brillantes del cielo nocturno y la m\u00e1s brillante de la constelaci\u00f3n con magnitud aparente +1,0, es dos veces mas luminosa y mas potente que el sol, a pesar de la inmensidad de esta constelacion solo su estrella principal es la m\u00e1s luminosa, por lo que no suele ser la constelacion m\u00e1s luminosa del espacio celeste.<\/p>\n<p>Tiene a su alrededor las constelaciones de Leo, Libra, Bo\u00f6tes, Hydra, Berenices, Corvus, Crater, y Serpens Caput.<\/p>\n<p>Esta constelacion dado su gran tama\u00f1o agrupa un extenso numero de estrellas galaxias y planetas fuera del sistema solar, de hecho se cree que fue en esta constelacion que ue descubrierto uno de los primeros planetas fuera del sistema solar<\/p>\n<h2>Sus estrellas Principales<\/h2>\n<ul>\n<li><a href=\"https:\/\/es.wikipedia.org\/wiki\/Alfa_Virginis\">\u03b1 Virginis<\/a>\u00a0(Espiga o Spica), la m\u00e1s brillante de la constelaci\u00f3n la estrella numero 16 mas brillantes del cielo nocturno y laq mas brillante de la constelaci\u00f3n de virgo, tiene una \u00a0magnitud +1,0, es una gigante azul,<\/li>\n<li>\u03b2 Virginis (Zavijava o Zavijah), Beta, b; denominada Zavijah, de magnitud 3,6 es una enana de color amarilla con una luminosidad aprox 3600 mas que la del sol, m\u00e1s caliente y luminosa que el Sol<\/li>\n<li>Virginis (Porrima),. Gamma, g; denominada Porrima, es una estrella doble de magnitud 2,74 de color blanca ambas estrellas pr\u00e1cticamente iguales; esta en el centro de la constelaci\u00f3n. Esta ubicada a 38 a\u00f1os luz de la Tierra y es aproximadamente 9 veces m\u00e1s brillante que el Sol.<\/li>\n<li>\u03b4 Virginis (Minelava o Auva), estrella gigante roja de magnitud 3,39 esta estrella da origen al conjunto de estrellas entre las que esta se incluye.<\/li>\n<li>\u03b5 Virginis (Vindemiatrix o Almured\u00edn), de magnitud 2,83 es una estrella gigante amarilla. Est\u00e1 situada a una distancia de 110 a\u00f1os luz, Virginis (Vindemiatrix o Almured\u00edn), tambi\u00e9n se le conoce con los nombres de Protrigeix, Almuredin y Alaraph, es conocida como \u201cvendimiadora\u201d, fue relacionada con el mito de Dem\u00e9ter y las diosas de la tierra en distintas mitolog\u00edas.<\/li>\n<li>\u03b6 Virginis (Heze), Posee una amgnitud de 3,38 es una estrella de color blanca situada a 73 a\u00f1os luz cerca del ecuador celeste y con una luminosidad de 18 soles.<\/li>\n<li>\u03b7 Virginis (Zaniah), de magnitud 3,89, un sistema estelar triple, Su nombre proviene del \u00e1rabe donde quiere decir \u201cel \u00e1ngulo\u201d<\/li>\n<\/ul>\n<h2>Caracter\u00edsticas destacables de la Constelaci\u00f3n de Virgo<\/h2>\n<p>Virgo en el zodiaco corresponde al elemento tierra, su planeta regente es Mercurio, comprendido entre el 23 de agosto-22 de septiembre. Es el \u00fanico signo representado por una mujer. Simboliza la cosecha, de ah\u00ed que Virgo sea representada a veces sosteniendo dos espigas en la mano, por ser laboriosa, meticulosa y fiable en sus actividades.<\/p>\n<p>En mitolog\u00eda Virgo es la representaci\u00f3n de Astrea, hija de Zeus y Temis, era la diosa virgen que llevaba los rayos de Zeus en sus brazos. A los nacidos bajo este signo, los astr\u00f3logos les atribuyen generosidad y disponibilidad para con los dem\u00e1s, perfeccionistas y meticulosos, no son muy entregados a la aventura. Por ser una de las constelaciones del zodiaco a los nacidos bajo este signo, los astr\u00f3logos les atribuyen generosidad y disponibilidad para con los dem\u00e1s, perfeccionistas y meticulosos, no son muy entregados a la aventura.<\/p>\n<ul>\n<li>Representado por LA VIRGEN, es uno de los signos del elemento tierra, su planeta regente es Mercurio, comprendido entre el 23 de agosto-22 de septiembre.<\/li>\n<li>Es el \u00fanico signo representado por una mujer.<\/li>\n<li>Virgo es la sexta constelaci\u00f3n de las 12 del zodiaco<\/li>\n<li>Virgo en el zodiaco corresponde al elemento tierra, su planeta regente es Mercurio, comprendido entre el 23 de agosto-22 de septiembre. Es el \u00fanico signo representado por una mujer. Simboliza la cosecha, de ah\u00ed que Virgo sea representada a veces sosteniendo dos espigas en la mano, por ser laboriosa, meticulosa y fiable en sus actividades. En mitolog\u00eda Virgo es la representaci\u00f3n de Astrea, hija de Zeus y Temis, era la diosa virgen que llevaba los rayos de Zeus en sus brazos. A los nacidos bajo este signo, los astr\u00f3logos les atribuyen generosidad y disponibilidad para con los dem\u00e1s, perfeccionistas y meticulosos, no son muy entregados a la aventura.<\/li>\n<li>Esta Simboliza la cosecha, es por ello que Virgo sea representada a veces sosteniendo dos espigas en la mano, se caracteriza por ser laboriosa, meticulosa y fiable en sus actividades.<\/li>\n<li>En mitolog\u00eda Virgo es la representaci\u00f3n de Astrea, Diosa de la Justicia Huamana, es la hija de Zeus y Temis, llevaba los rayos de Zeus en sus brazos.<\/li>\n<li>Por ser una de las constelaciones del zodiaco a los nacidos bajo este signo, los astr\u00f3logos les atribuyen generosidad y disponibilidad para con los dem\u00e1s, perfeccionistas y meticulosos, no son muy entregados a la aventura.<\/li>\n<li>Se cree que alrededor de esta constelaci\u00f3n y el movimiento de los equinoccios, al medir la distancia entre Espiga y R\u00e9gulo, de la constelaci\u00f3n de Leo, fue donde se descubri\u00f3 lo que se conoce posteriormente como la procesi\u00f3n de los equinoccios.<\/li>\n<li>Su estrella principal es una de las 16 estrellas m\u00e1s brillantes. Superando incluso la famosa Regulus.<\/li>\n<li>En esta inmensa constelacion se destacar un c\u00famulo importante de galaxias conocido como el C\u00famulo de Virgo, contiene hasta once galaxias del cat\u00e1logo de Messier.<\/li>\n<li>Por su dimensi\u00f3n, en la constelacion de virgo se agrupa un gran n\u00famero de estrellas, galaxias y planetas fuera del sistema solar.<\/li>\n<li>Se cree que fue en la constelaci\u00f3n de Virgo donde se descubri\u00f3 uno de los primeros planetas fuera del sistema solar.<\/li>\n<li>La constelaci\u00f3n de Virgo est\u00e1 formada por 271 estrellas (la segunda m\u00e1s extensa)<\/li>\n<li>La constelaci\u00f3n de Virgo se puede observar en el cielo nocturno entre la constelaci\u00f3n de Leo, al oeste, y la de Libra, al este.<\/li>\n<li>La Mayoria de las estrellas que conforman est\u00e1n inmensa constelacion son poco brillantes a excepsion de su principal estrella Espiga, que es una Gigante Azul dos Veces mas luminosa que el sol.<\/li>\n<li>Espiga es una de las 16 estrellas m\u00e1s brillantes del cielo nocturno.<\/li>\n<li>En la constelacion de virgo se dan 5 lluvias de meteoros conocidas como<\/li>\n<li>\u2022 \u00c9psilon Virg\u00ednidas de febrero<\/li>\n<li>\u2022 H Virg\u00ednidas<\/li>\n<li>\u2022 Ji Virg\u00ednidas de diciembre<\/li>\n<li>\u2022 Mu Virg\u00ednidas de febrero<\/li>\n<li>\u2022 Sigma Virg\u00ednidas de diciembre<\/li>\n<li>La palabra virgo significa en lat\u00edn \u201caut\u00f3nomo\u201d o \u201cautosuficiente\u201d.<\/li>\n<li>El mejor mes para apreciar esta constelaci\u00f3n es el mes de Mayo.<\/li>\n<li>Virgo, el c\u00famulo de galaxias m\u00e1s grande que tambi\u00e9n contiene el Grupo Local, que a su vez incluye la Galaxia Andr\u00f3meda y la V\u00eda L\u00e1ctea.<\/li>\n<li>El cumulo de Virgo esta situado aproximadamente a una distancia de 59 \u00b1 4 millones de a\u00f1os-luz (18.0 \u00b1 1.2 Mpc)3\u200b en direcci\u00f3n de la constelaci\u00f3n de Virgo. Contiene unas 1300 galaxias, aunque puede que lleguen a ser hasta 2000 y forma la regi\u00f3n central del mayor Superc\u00famulo Local, del cual forma tambi\u00e9n parte el Grupo Local. Se estima que su masa es de 1.2\u00d71015 MS hasta unos 8 grados del centro del c\u00famulo, lo que equivale a un radio de aproximadamente 2.2 Mpc.3\u200b. Muchas de las galaxias brillantes de este c\u00famulo, incluida la galaxia el\u00edptica gigante Messier 87, las cuales fueron descubiertas a finales de la d\u00e9cada de 1770 e inicios de la d\u00e9cada de 1780.<\/li>\n<li>Al ser una de las constelaciones m\u00e1s grandes del espacio celeste el Sol permanece en ella m\u00e1s de cuarenta d\u00edas, en concreto 45 d\u00edas, siendo el mes solar de mayor duraci\u00f3n. El Sol entra en esta constelaci\u00f3n el 16 de septiembre, y permanece en ella hasta el 30 de octubre.<\/li>\n<li>La mejor \u00e9poca para observar esta constelaci\u00f3n es durante el mes de mayo.<\/li>\n<li>Virgo Se encuentra muy cerca del polo norte de nuestra V\u00eda L\u00e1ctea o nuestra galaxia, esto implica una ventana abierta al firmamento y a la contemplaci\u00f3n de galaxias y c\u00famulos globulares.<\/li>\n<li>Esta constelaci\u00f3n est\u00e1 representada por, LA VIRGEN, es uno de los signos del elemento tierra, su planeta regente es Mercurio.<\/li>\n<li>Es una de las 12 constelaciones del zod\u00edaco, siendo la sexta constelaci\u00f3n en el mismo, y adem\u00e1s es una de las 88 constelaciones actualmente reconocidas por la astronom\u00eda moderna, donde por sus dimensiones y su inmensidad ocupa la posici\u00f3n n\u00famero 2 de este conteo.<\/li>\n<li>Es el \u00fanico signo representado por una mujer.<\/li>\n<\/ul>\n<h2>Mitolog\u00eda de la Constelaci\u00f3n de Virgo.<\/h2>\n<p>En la mitolog\u00eda griega esta constelaci\u00f3n es asociada a la Diosa de la Justicia, Astrea, hija de Zeus y Titaness Themis, se caracteriza por llevar en las manos una balanza y u na espiga de trigo, se dice que nacio mortal y durante edad de oro donde reinaba la paz y la prosperidad vivi\u00f3 en la tierra para administrar la justicia de los hombres, luego en la edad de la tierra no era tan prospera los hombres no solian honrar a los Dioses como solian hacerlo, luego llego la edad de plata y hierro donde Astrea decide abandonar la tierra y se ubica en los cielos ya que no soportaba lo que se hab\u00eda convertido la raza humana.<\/p>\n<p>Tambi\u00e9n existe otra historia del mito de virgo, donde, la diosa de la justicia humana es Dice quien al igual que en el mito de Astrea vive en la tierra de los humano durante la edad de oro, plata y bronce, donde decidi\u00f3 abandonar la tierra y mudarse al cielo, sin la jusembargo es solo en esta parte de la historia donde son similares, ya que Astrea es recordada por su colaboraci\u00f3n a Zeus en la guerra de los titanes., mientras que Dice se recuerda por repartir justicia a los humanos.<\/p>\n<p>Sin embargo Virgo al igual que much\u00edsimas otras constelaciones est\u00e1n envueltas en numerosos mitos, no solo en la mitolog\u00eda griega, tambi\u00e9n en la mitolog\u00eda romana, la mitolog\u00eda babil\u00f3nica, egipcia, en la que existen personificaciones e historias diversas de esta diosa que representa Virgo.<\/p>\n<p>Tanto griegos como romanos, describen una relaci\u00f3n entre la constelaci\u00f3n de Virgo con la diosa Dem\u00e9ter, la Diosa de la Cosecha, Otras sugieren que virgo no se refiere a una doncella virgen, a cambio, es la representaci\u00f3n de la madre naturaleza que nutre toda la vida.<\/p>\n<p>Virgo es una constelaci\u00f3n muy interesante, en la que se conoces m\u00e1s de una historia que fundamenta su existencia, no solo en la mitolog\u00eda griega, tambi\u00e9n en la mitolog\u00eda romana, la mitolog\u00eda babil\u00f3nica, egipcia, en la que existen personificaciones e historias diversas de esta diosa que representa Virgo.<\/p>\n<p>En la mitolog\u00eda griega esta constelaci\u00f3n es asociada a la Diosa de la Justicia, Astrea, hija de Zeus y Titaness Themis, se caracteriza por llevar en las manos una balanza y u na espiga de trigo, se dice que nacio mortal y durante edad de oro donde reinaba la paz y la prosperidad vivi\u00f3 en la tierra para administrar la justicia de los hombres, luego en la edad de la tierra no era tan prospera los hombres no solian honrar a los Dioses como solian hacerlo, luego llego la edad de plata y hierro donde Astrea decide abandonar la tierra y se ubica en los cielos ya que no soportaba lo que se hab\u00eda convertido la raza humana.<\/p>\n<p>Tambi\u00e9n existe otra historia del mito de virgo, donde, la diosa de la justicia humana es Dice quien al igual que en el mito de Astrea vive en la tierra de los humano durante la edad de oro, plata y bronce, donde decidi\u00f3 abandonar la tierra y mudarse al cielo, sin la jusembargo es solo en esta parte de la historia donde son similares, ya que Astrea es recordada por su colaboraci\u00f3n a Zeus en la guerra de los titanes., mientras que Dice se recuerda por repartir justicia a los humanos.<\/p>\n<p>De forma caracter\u00edstica, las mitolog\u00edas de esta constelaci\u00f3n, tanto griegos como romanos, describen una relaci\u00f3n entre la constelaci\u00f3n de Virgo con la diosa Dem\u00e9ter, la Diosa de la Cosecha, Otras sugieren que virgo no se refiere a una doncella virgen, a cambio, es la representaci\u00f3n de la madre naturaleza que nutre toda la vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Virgo o La virgen por su significado en lat\u00edn, forma parte de las 12 constelaciones que componen el zodiaco, y tambi\u00e9n de las 88 constelaciones reconocidas por la astronom\u00eda moderna, realmente esta constelaci\u00f3n es muy extensa, ocupa una superficie del espacio celeste de aproximadamente 1300 grados cuadrados, lo cual representa el 3,138 % A lo [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[485],"tags":[],"class_list":["post-45943","post","type-post","status-publish","format-standard","hentry","category-constelaciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constelaci\u00f3n de Virgo - Online Star Register<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constelaci\u00f3n de Virgo - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"Virgo o La virgen por su significado en lat\u00edn, forma parte de las 12 constelaciones que componen el zodiaco, y tambi\u00e9n de las 88 constelaciones reconocidas por la astronom\u00eda moderna, realmente esta constelaci\u00f3n es muy extensa, ocupa una superficie del espacio celeste de aproximadamente 1300 grados cuadrados, lo cual representa el 3,138 % A lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-11T11:58:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T08:57:07+00:00\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-de-virgo\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-de-virgo\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"headline\": \"Constelaci\u00f3n de Virgo\",\n\t            \"datePublished\": \"2018-03-11T11:58:37+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:57:07+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-de-virgo\\\/\"\n\t            },\n\t            \"wordCount\": 2405,\n\t            \"articleSection\": [\n\t                \"Constelaci\u00f3nes\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-de-virgo\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-de-virgo\\\/\",\n\t            \"name\": \"Constelaci\u00f3n de Virgo - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-03-11T11:58:37+00:00\",\n\t            \"dateModified\": \"2024-08-05T08:57:07+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-de-virgo\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-de-virgo\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/astronomia\\\/constelaciones\\\/constelacion-de-virgo\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Astronom\u00eda\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Constelaci\u00f3nes\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/astronomia\\\/constelaciones\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Constelaci\u00f3n de Virgo\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/24c3ce13844c8731c5d95d4b3253ecd4\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constelaci\u00f3n de Virgo - Online Star Register","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/","og_locale":"es_ES","og_type":"article","og_title":"Constelaci\u00f3n de Virgo - Online Star Register","og_description":"Virgo o La virgen por su significado en lat\u00edn, forma parte de las 12 constelaciones que componen el zodiaco, y tambi\u00e9n de las 88 constelaciones reconocidas por la astronom\u00eda moderna, realmente esta constelaci\u00f3n es muy extensa, ocupa una superficie del espacio celeste de aproximadamente 1300 grados cuadrados, lo cual representa el 3,138 % A lo [&hellip;]","og_url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2018-03-11T11:58:37+00:00","article_modified_time":"2024-08-05T08:57:07+00:00","author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"headline":"Constelaci\u00f3n de Virgo","datePublished":"2018-03-11T11:58:37+00:00","dateModified":"2024-08-05T08:57:07+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/"},"wordCount":2405,"articleSection":["Constelaci\u00f3nes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/","url":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/","name":"Constelaci\u00f3n de Virgo - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2018-03-11T11:58:37+00:00","dateModified":"2024-08-05T08:57:07+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4"},"breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/constelacion-de-virgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Astronom\u00eda","item":"https:\/\/osr.org\/es\/astronomia\/"},{"@type":"ListItem","position":3,"name":"Constelaci\u00f3nes","item":"https:\/\/osr.org\/es\/astronomia\/constelaciones\/"},{"@type":"ListItem","position":4,"name":"Constelaci\u00f3n de Virgo"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/24c3ce13844c8731c5d95d4b3253ecd4","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/45943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=45943"}],"version-history":[{"count":5,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/45943\/revisions"}],"predecessor-version":[{"id":412525,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/45943\/revisions\/412525"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=45943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=45943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=45943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}