{"id":455104,"date":"2024-10-06T11:45:04","date_gmt":"2024-10-06T09:45:04","guid":{"rendered":"https:\/\/osr.org\/?p=455104"},"modified":"2024-07-31T00:38:05","modified_gmt":"2024-07-30T22:38:05","slug":"osa-menor","status":"publish","type":"post","link":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/","title":{"rendered":"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra?"},"content":{"rendered":"<p>Observar el cielo, es uno de los placeres que nos regala el universo, algunos, lo miramos simplemente para disfrutar de su belleza e inmensidad, sin embargo, otros han encontrado en el la forma de estudiar y conocer esos misterios que esconde m\u00e1s all\u00e1 de lo que podemos ver.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-455254 alignleft\" title=\"impresionante-vista-del-cielo-nocturno\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno-300x200.png\" alt=\"Observaci\u00f3n a simple vista del cielo nocturno\" width=\"300\" height=\"200\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno-300x200.png 300w, https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><strong>Si te dijera<\/strong> <strong>\u00bfnombra al menos 4 cosas que se vengan a tu mente al pensar en el cielo?<\/strong> De seguro, las estrellas y constelaciones, formar\u00edan parte de esa lista. Estas son sin discusi\u00f3n alguna, de las maravillas capaces de acaparar por completo nuestra atenci\u00f3n, solo con levantar la mirada, ese espacio de luz en medio de la oscuridad, nos da una m\u00ednima idea de la inmensidad del universo.<\/p>\n<p>Y si ahora, te dijera, piensa en una estrella \u00bfen qu\u00e9 pensar\u00edas? <strong>De nuevo es muy f\u00e1cil que la Osa Menor, se encuentre entre las respuestas.<\/strong><\/p>\n<p>Aunque el cielo aloja millones de estrellas, la Osa Menor adem\u00e1s de ser una de las m\u00e1s populares, tiene un simbolismo especial, y una interesante mitolog\u00eda, que la hace presente de muchas formas en lo que conocemos del cielo.<\/p>\n<p>\u00bfPor qu\u00e9 la conocemos? Entre otras cosas por ser el hogar de la estrella Polar, su estrella m\u00e1s brillante y un punto de referencia para viajeros desde la antig\u00fcedad. Pero, hay mucho que conocer de esta estrella. Hoy sabremos un poco sobre los secretos de la Osa Menor, que es, qu\u00e9 estrellas la acompa\u00f1an, <strong>su historia y c\u00f3mo encontrarla en el cielo nocturno.<\/strong><\/p>\n<h2><strong>\u00bfQu\u00e9 es la Osa Menor?<\/strong><\/h2>\n<p>Sabemos que la Osa Menor es una de las constelaciones m\u00e1s famosas del cielo y en ella se encuentra el punto de referencia para navegantes y viajeros, <strong>la <a href=\"https:\/\/osr.org\/es\/blog\/astronomia\/constelaciones\/estrella-polar-como-detectarla\/\">estrella polar<\/a>.<\/strong><\/p>\n<p>Se conforma por 7 estrellas, 4 de ellas hacen una especie de figura con forma de un carro, y las otras 3 una forma parecida a la del mango, con una silueta similar a la de la Osa Mayor.<\/p>\n<h2><strong>\u00bfQu\u00e9 estrellas est\u00e1n presentes en esta constelaci\u00f3n?<\/strong><\/h2>\n<p>Aunque la Osa Menor pueda parecer una peque\u00f1a representaci\u00f3n la Osa Mayor, tiene una gran importancia en el cielo, <strong>no solo por tener entre sus estrellas a Polaris<\/strong>, sino porque el resto de estrellas tambi\u00e9n son interesantes dentrodel mapa estelar:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-455275 alignright\" title=\"estrellas y constelaciones\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/estrellas-y-constelaciones-300x270.png\" alt=\"Estrellas y constelaciones del cielo nocturno\" width=\"300\" height=\"270\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/estrellas-y-constelaciones-300x270.png 300w, https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/estrellas-y-constelaciones-1024x921.png 1024w, https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/estrellas-y-constelaciones-768x690.png 768w, https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/estrellas-y-constelaciones-534x480.png 534w, https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/estrellas-y-constelaciones.png 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Estas tres estrellas, son las que le dan luminosidad a la constelaci\u00f3n:<\/p>\n<ol>\n<li><strong>Polaris (la Estrella Polar):<\/strong> es la punta del mango del peque\u00f1o Diepper. Gracias a su brillo, y posici\u00f3n fija en el cielo, Polaris, es una gu\u00eda confiable para ubicarnos, esto ha permitido que durante siglos haya servido de br\u00fajula para navegantes;<\/li>\n<li><strong>Kochab (Beta Ursae Minoris):<\/strong> es la segunda estrella m\u00e1s brillante, esta, acompa\u00f1ada de polaris, hacen la silueta del mango de la constelaci\u00f3n;<\/li>\n<li><strong>Pherkad (Gamma Ursae Minoris):<\/strong> apodada uno de los \u00abGuardianes del Polo\u00bb junto con Kochab, Pherkad es una hermosa estrella de brillo intenso lo que la hace una buena referencia a la hora de encontrar a Polaris.<\/li>\n<\/ol>\n<p><strong>Aunque con una presencia m\u00e1s discreta, estas estrellas completan el \u00e1rea de la Osa Menor.<\/strong><\/p>\n<ol start=\"4\">\n<li><strong>Yildun (\u03b4 Ursae Minoris): s<\/strong>u nombre en \u00e1rabe significa la brillante, esta es una de las estrellas que conforma la figura del carro;<\/li>\n<li><strong>Epsilon Ursae Minoris (\u03b5 Ursae Minoris): <\/strong>acompa\u00f1a a Yildum, a dibujar la figura del carro;<\/li>\n<li><strong>Zeta Ursae Minoris (\u03b6 Ursae Minoris): <\/strong>estrella Tenue, que conforma la figura del carro;<\/li>\n<li><strong>Eta Ursae Minoris (\u03b7 Ursae Minoris): <\/strong>una estrella ligeramente m\u00e1s tenue que sus compa\u00f1eras, situada en la figura del carro.<\/li>\n<\/ol>\n<h2><strong>\u00bfPor qu\u00e9 la Osa Menor tambi\u00e9n se llama el Peque\u00f1o Carro?<\/strong><\/h2>\n<p>Cuando vemos en conjunto la constelaci\u00f3n, parte de las estrellas que la componen, parecen estar formando una figura de un carro, esta figura adem\u00e1s pareciera <strong>ser una replica a menor escala de la Osa Mayor, es por ello, que al lado de su compa\u00f1era mayo suele llam\u00e1rsele peque\u00f1o carro.<\/strong><\/p>\n<p>Este parecido, no solo ha permitido crear una relaci\u00f3n hist\u00f3rica de ambas constelaciones, sino que a trav\u00e9s de estas se ha ilustrado la mitolog\u00eda griega, donde se dice que, <strong>Zeus transform\u00f3 a la ninfa Calisto en una osa y la puso en el cielo como la Osa Mayor, y su hijo<\/strong>, Arcas, fue transformado en una osa menor y colocado cerca de ella en el cielo, formando as\u00ed la Osa Menor, una leyenda que ha pasado durante siglos, manteniendo su vigencia.<\/p>\n<h2><strong>C\u00f3mo encontrar la Osa Menor: trucos y consejos<\/strong><\/h2>\n<p><strong>\u00bfEstas listo para una expedici\u00f3n espacial? Te contamos paso a paso como encontrar la Osa Menor en.<\/strong><\/p>\n<h3><strong>Paso 1: encuentra La Osa Mayor<\/strong><\/h3>\n<p>La osa Mayor, es como la hermana mayor de la Osa Menor, por su tama\u00f1o es m\u00e1s sencillo encontrarla al norte en el cielo, <strong>y eso la convierte en un punto de partida a la hora de ubicar a la Osa Menor.<\/strong><\/p>\n<h3><strong>Paso 2: sigue la estrella Polar<\/strong><\/h3>\n<p><strong>Las estrellas Dubhe y Merak, de la Osa Mayor, conocidas como \u00ablos punteros\u00bb, apuntan directamente hacia Polaris, la Estrella Polar.<\/strong><\/p>\n<h3><strong>Paso 3: descubre el peque\u00f1o carro<\/strong><\/h3>\n<p>En la silueta de la constelaci\u00f3n, Polaris es la punta del mango de un peque\u00f1o carro, esto quiere decir que, al encontrarla, <strong>podr\u00e1s hacer un recorrido de la Osa Menor.<\/strong><\/p>\n<p>Ten en cuenta que:<\/p>\n<ul>\n<li>La Osa menor es visible a simple vista, pero puede ser dif\u00edcil de ubicar si no tiene experiencia.<\/li>\n<li>Se encuentra en el hemisferio norte y es visible durante todo el a\u00f1o en este hemisferio.<\/li>\n<li>Puedes usar una br\u00fajula o aplicaciones que puedan ayudarte a ubicarla.<\/li>\n<li>Elige un cielo despejado para encontrarla con mayor facilidad.<\/li>\n<li>No es visible a simple vista desde todos los puntos del planeta.\n<ul>\n<li><em>En el hemisferio sur la visibilidad es limitada.<\/em><\/li>\n<li><em>Cerca del ecuador tiene visibilidad limitada.<\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2><strong>La Osa Mayor y la Osa Menor: Caracter\u00edsticas Comunes<\/strong><\/h2>\n<p>Aunque la <strong>Osa Mayor<\/strong> y la <strong>Osa Menor<\/strong> son constelaciones distintas, est\u00e1n relacionadas de diferentes formas:<\/p>\n<ul>\n<li><strong>Por su forma<\/strong>: Aunque con ligeras diferencias en su inclinaci\u00f3n y por supuesto en tama\u00f1o, la forma de ambas constelaciones es similar a un cuchar\u00f3n o carro.<\/li>\n<li><strong>Por su ubicaci\u00f3n<\/strong>: Ambas constelaciones se encuentran en el Polo Norte Celeste, y son visibles en el hemisferio norte durante todo el a\u00f1o.<\/li>\n<li><strong>Importancia como punto de referencia<\/strong>: Ambas constelaciones, son un punto de referencia en el cielo, que ha permitido a los viajeros y navegantes orientarse, La Osa Menor, gracias a su estrella Polar, y la Osa Mayor, por marcar la ubicaci\u00f3n de Polaris a trav\u00e9s de sus lanceros.<\/li>\n<li><strong>Su mitolog\u00eda<\/strong>: Conectadas a traces de la mitolog\u00eda griega, La Osa Mayor y la Osa Menor, representan a la madre (Calisto) y al hijo (Arcas)<\/li>\n<\/ul>\n<p>Adem\u00e1s de ser dos constelaciones luminosas y reconocidas a trav\u00e9s de la historia, son un fascinante espect\u00e1culo del cielo nocturno, que sigue cautivando a la humanidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Observar el cielo, es uno de los placeres que nos regala el universo, algunos, lo miramos simplemente para disfrutar de su belleza e inmensidad, sin embargo, otros han encontrado en el la forma de estudiar y conocer esos misterios que esconde m\u00e1s all\u00e1 de lo que podemos ver. Si te dijera \u00bfnombra al menos 4 [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[1015,1010,483,1009,451,1047],"class_list":["post-455104","post","type-post","status-publish","format-standard","hentry","category-osr-es","tag-astronomia-es","tag-ciencia-es","tag-constelaciones","tag-planeta-es","tag-sistema-solar","tag-universo-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra? - Online Star Register<\/title>\n<meta name=\"description\" content=\"Observar el cielo, es uno de los placeres que nos regala el universo, algunos, lo miramos simplemente para disfrutar de su belleza e inmensidad, sin\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra? - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"Observar el cielo, es uno de los placeres que nos regala el universo, algunos, lo miramos simplemente para disfrutar de su belleza e inmensidad, sin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/eliana.rodriguez.14473\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-06T09:45:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno-300x200.png\" \/>\n<meta name=\"author\" content=\"Eliana Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"Eliana Rodriguez\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/30aeed14d2a8242c2b1a7a6e5a4f2a3d\"\n\t            },\n\t            \"headline\": \"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra?\",\n\t            \"datePublished\": \"2024-10-06T09:45:04+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/\"\n\t            },\n\t            \"wordCount\": 1163,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/impresionante-vista-del-cielo-nocturno-300x200.png\",\n\t            \"keywords\": [\n\t                \"astronomia\",\n\t                \"ciencia\",\n\t                \"constelaciones\",\n\t                \"planeta\",\n\t                \"sistema solar\",\n\t                \"UNIVERSO\"\n\t            ],\n\t            \"articleSection\": [\n\t                \"Gu\u00eda OSR\"\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/\",\n\t            \"name\": \"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra? - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/impresionante-vista-del-cielo-nocturno-300x200.png\",\n\t            \"datePublished\": \"2024-10-06T09:45:04+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/30aeed14d2a8242c2b1a7a6e5a4f2a3d\"\n\t            },\n\t            \"description\": \"Observar el cielo, es uno de los placeres que nos regala el universo, algunos, lo miramos simplemente para disfrutar de su belleza e inmensidad, sin\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"es\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/impresionante-vista-del-cielo-nocturno-300x200.png\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/impresionante-vista-del-cielo-nocturno-300x200.png\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/osr-es\\\/osa-menor\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Gu\u00eda OSR\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/osr-es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra?\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#\\\/schema\\\/person\\\/30aeed14d2a8242c2b1a7a6e5a4f2a3d\",\n\t            \"name\": \"Eliana Rodriguez\",\n\t            \"description\": \"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \\\"El universo es un libro infinito.\\\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.\",\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/\",\n\t                \"https:\\\/\\\/www.facebook.com\\\/eliana.rodriguez.14473\",\n\t                \"https:\\\/\\\/www.instagram.com\\\/eliceci29\\\/\",\n\t                \"https:\\\/\\\/www.linkedin.com\\\/in\\\/eliana-rodriguez-27aab1a3\\\/\"\n\t            ],\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/blog\\\/author\\\/eliana-rodriguez\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra? - Online Star Register","description":"Observar el cielo, es uno de los placeres que nos regala el universo, algunos, lo miramos simplemente para disfrutar de su belleza e inmensidad, sin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/","og_locale":"es_ES","og_type":"article","og_title":"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra? - Online Star Register","og_description":"Observar el cielo, es uno de los placeres que nos regala el universo, algunos, lo miramos simplemente para disfrutar de su belleza e inmensidad, sin","og_url":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/","og_site_name":"Online Star Register","article_author":"https:\/\/www.facebook.com\/eliana.rodriguez.14473","article_published_time":"2024-10-06T09:45:04+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno-300x200.png","type":"","width":"","height":""}],"author":"Eliana Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eliana Rodriguez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/#article","isPartOf":{"@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/"},"author":{"name":"Eliana Rodriguez","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/30aeed14d2a8242c2b1a7a6e5a4f2a3d"},"headline":"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra?","datePublished":"2024-10-06T09:45:04+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/"},"wordCount":1163,"image":{"@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno-300x200.png","keywords":["astronomia","ciencia","constelaciones","planeta","sistema solar","UNIVERSO"],"articleSection":["Gu\u00eda OSR"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/","url":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/","name":"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra? - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno-300x200.png","datePublished":"2024-10-06T09:45:04+00:00","author":{"@id":"https:\/\/osr.org\/es\/#\/schema\/person\/30aeed14d2a8242c2b1a7a6e5a4f2a3d"},"description":"Observar el cielo, es uno de los placeres que nos regala el universo, algunos, lo miramos simplemente para disfrutar de su belleza e inmensidad, sin","breadcrumb":{"@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno-300x200.png","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2024\/07\/impresionante-vista-del-cielo-nocturno-300x200.png"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/blog\/osr-es\/osa-menor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Gu\u00eda OSR","item":"https:\/\/osr.org\/es\/osr-es\/"},{"@type":"ListItem","position":3,"name":"Osa Menor: \u00bfqu\u00e9 es y d\u00f3nde se encuentra?"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/osr.org\/es\/#\/schema\/person\/30aeed14d2a8242c2b1a7a6e5a4f2a3d","name":"Eliana Rodriguez","description":"Soy apasionada de la escritura, con 10 a\u00f1os creando contenido. En OSR, combino mi pasi\u00f3n por las letras con el cosmos, conociendo historias que nos conectan con la inmensidad del universo. \"El universo es un libro infinito.\" Carl Sagan. Una frase que es una invitaci\u00f3n a reflexionar sobre nuestro lugar en \u00e9l.","sameAs":["https:\/\/osr.org\/es\/blog\/","https:\/\/www.facebook.com\/eliana.rodriguez.14473","https:\/\/www.instagram.com\/eliceci29\/","https:\/\/www.linkedin.com\/in\/eliana-rodriguez-27aab1a3\/"],"url":"https:\/\/osr.org\/es\/blog\/author\/eliana-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/455104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=455104"}],"version-history":[{"count":5,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/455104\/revisions"}],"predecessor-version":[{"id":456587,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/posts\/455104\/revisions\/456587"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=455104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/categories?post=455104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/tags?post=455104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}