{"id":3093,"date":"2015-11-17T15:18:23","date_gmt":"2015-11-17T13:18:23","guid":{"rendered":"https:\/\/osr.org\/es\/?page_id=3093"},"modified":"2019-07-29T14:40:51","modified_gmt":"2019-07-29T12:40:51","slug":"politica-privacidad","status":"publish","type":"page","link":"https:\/\/osr.org\/es\/politica-privacidad\/","title":{"rendered":"Pol\u00edtica de Privacidad de ONLINE STAR REGISTER"},"content":{"rendered":"<p align=\"CENTER\"><a href=\"https:\/\/osr.org\/es\/\">www.osr.org<\/a><\/p>\n<h3>1. Introducci\u00f3n<\/h3>\n<p>Online Star Register, OSR, tambi\u00e9n se hace referencia a continuaci\u00f3n como \u201cnosotros\u201d o \u201cnuestro\u201d, procesa Datos Personales como Responsable del Tratamiento de Datos de acuerdo con el RGPD. Nos gustar\u00eda proporcionarle informaci\u00f3n sobre esto. Consideramos que es nuestra responsabilidad proteger su privacidad tanto como sea posible y explicarle de manera apropiada la forma en que lo hacemos.<\/p>\n<p>En este documento, explicaremos los Datos personales de usted que procesamos, los fines y cu\u00e1l es la base del procesamiento de estos datos personales.<\/p>\n<h3>2. Definiciones<\/h3>\n<p><b>Online Star Register<\/b>: Online Star Register B.V., OSR, debidamente inscrita en el Registro de Comercio Holand\u00e9s bajo el n\u00famero 60333553.<br \/>\n<b>RGPD<\/b>: Regulaci\u00f3n (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, sobre la protecci\u00f3n de las personas f\u00edsicas con respecto al tratamiento de datos personales y sobre la libre circulaci\u00f3n de dichos datos, y por la que se deroga la Directiva 95\/46 \/ CE. Reglamento General de Protecci\u00f3n de Datos, RGPD.<br \/>\n<b>El Interesado<\/b>: El sujeto de datos a que se refiere el Art\u00edculo 4 (1) del RGPD.<br \/>\n<b>Cookies<\/b>: cookies y scripts. Fichero de peque\u00f1o tama\u00f1o que los sitios web env\u00edan al navegador y se descargan en los equipos inform\u00e1ticos, permitiendo almacenar y recuperar<br \/>\nInformaci\u00f3n sobre su visita.<br \/>\n<b>Datos personales<\/b>: Datos personales a los que se refiere el art\u00edculo 4, apartado 1, del RGPD.<br \/>\n<b>Encargado del tratamiento de datos<\/b>: el Encargado del tratamiento de datos a que se refiere el art\u00edculo 4, apartado 8, del RGPD.<br \/>\n<b>Tratamiento<\/b>: El tratamiento de datos al que se refiere el Art\u00edculo 4(2) del RGPD.<br \/>\n<b>Responsable del tratamiento de datos<\/b>: El Responsable del tratamiento de datos al que se refiere el Art\u00edculo 4(7) del Reglamento de Protecci\u00f3n de Datos, RGPD.<br \/>\n<b>Website<\/b>: El sitio web que puede ser abordado a trav\u00e9s de <a href=\"https:\/\/osr.org\/es\/\">www.osr.org<\/a> y sus subp\u00e1ginas.<\/p>\n<h3>3. Tratamiento de sus datos personales mediante el registro en l\u00ednea de Online Star.<\/h3>\n<p><b>3.1. Cumplimiento del acuerdo <\/b><\/p>\n<p>Primero, procesamos sus datos personales con el fin de entregar nuestros servicios o productos. Podemos procesar los siguientes datos personales suministrados por usted para este prop\u00f3sito:<\/p>\n<p>1. Nombre e informaci\u00f3n de la direcci\u00f3n y nombre de la compa\u00f1\u00eda, si usted escoge esta opci\u00f3n<br \/>\n2. Direcci\u00f3n de correo electr\u00f3nico<br \/>\n3. Informaci\u00f3n financiera, como su n\u00famero de cuenta bancaria<br \/>\n4. Otros datos personales que usted mismo menciona en la tarjeta de texto<br \/>\n5. N\u00famero telef\u00f3nico<br \/>\n6. Otros datos personales que usted mismo publique en su \u201cP\u00e1gina de Estrella \u00danica\u201d, que pueden incluir texto, fotograf\u00edas y videos<\/p>\n<p>La base para dicho tratamiento es el cumplimiento del Acuerdo que usted ha celebrado con nosotros.<\/p>\n<p><b>3.2. Contacto<\/b><br \/>\nEn segundo lugar, procesamos sus datos personales si intenta contactarnos a trav\u00e9s de nuestro formulario de contacto en el sitio web o a trav\u00e9s de <a href=\"mailto:help@osr.org\">help@osr.org<\/a>. Esto nos permite responder a las preguntas que usted tiene. Procesamos los siguientes datos personales suministrados por usted para este prop\u00f3sito:<\/p>\n<p>1. Nombre<br \/>\n2. Direcci\u00f3n de correo electr\u00f3nico<br \/>\n3. Otros datos personales que usted mismo nos menciona en su mensaje<\/p>\n<p>La base de dicho tratamiento es un inter\u00e9s leg\u00edtimo de nuestra parte, espec\u00edficamente, responder a las preguntas que usted mismo nos haga. Por lo tanto, procesamos los datos personales correspondientes solo para contactarlo con el fin de responder a sus preguntas.<\/p>\n<p><b>3.3.Bolet\u00edn informativo<\/b><\/p>\n<p>En tercer lugar, procesamos sus datos personales para enviarle nuestro bolet\u00edn informativo si se ha registrado para esto, por separado o durante el proceso de pedido. Procesamos los siguientes datos personales suministrados por usted para este prop\u00f3sito:<\/p>\n<p>1. Nombre<br \/>\n2. Direcci\u00f3n de correo electr\u00f3nico<\/p>\n<p>La base de dicho procesamiento es un inter\u00e9s leg\u00edtimo de nuestra parte, espec\u00edficamente, para mantenerlo informado de noticias, c\u00f3digos de descuento \/ ofertas y nuevos productos y servicios.<\/p>\n<p><b>3.4. Informaci\u00f3n sobre obsequios de la empresa. <\/b><\/p>\n<p>En cuarto lugar, procesamos sus datos personales para informarle, a petici\u00f3n suya, sobre regalos empresariales. Procesamos los siguientes datos personales suministrados por usted para este prop\u00f3sito:<\/p>\n<p>1. Nombre<br \/>\n2. Direcci\u00f3n de correo electr\u00f3nico<br \/>\n3. Nombre de la compa\u00f1\u00eda<br \/>\n4. Otros datos personales que usted mismo mencione en su solicitud<\/p>\n<p>La base de dicho tratamiento o procesamiento es un inter\u00e9s leg\u00edtimo de nuestra parte, espec\u00edficamente, para informarle sobre las posibilidades relacionadas con los regalos empresariales.<\/p>\n<h3>4. Per\u00edodo de conservaci\u00f3n de datos<\/h3>\n<p>No conservamos sus datos personales por m\u00e1s tiempo del necesario para los fines antes mencionados para los cuales los tratamos, a menos que la ley nos lo exija. Aplicamos los siguientes periodos espec\u00edficos de conservaci\u00f3n de datos:<\/p>\n<p>1. Para el prop\u00f3sito \u00abCumplimiento del acuerdo\u00bb, conservamos su nombre y su informaci\u00f3n de direcci\u00f3n, informaci\u00f3n financiera y n\u00famero de tel\u00e9fono durante un per\u00edodo de 20 a\u00f1os despu\u00e9s de que usted realiz\u00f3 su \u00faltimo pedido. Para este prop\u00f3sito, no hay un per\u00edodo de retenci\u00f3n espec\u00edfico para su direcci\u00f3n de correo electr\u00f3nico u otros datos personales que usted mismo mencione en la tarjeta de texto o publique en su P\u00e1gina de Estrella \u00danica.<br \/>\n2. Para el prop\u00f3sito de \u00abContacto\u00bb, conservamos sus datos personales durante un per\u00edodo de 5 a\u00f1os despu\u00e9s de nuestro \u00faltimo contacto con usted.<br \/>\n3. Para el prop\u00f3sito de \u201cBolet\u00edn informativo\u201d, conservamos sus datos personales durante un per\u00edodo de 1 a\u00f1o despu\u00e9s de que se haya registrado en el bolet\u00edn.<br \/>\n4. Para el prop\u00f3sito \u201cInformaci\u00f3n sobre obsequios de la empresa\u201d, conservamos sus datos personales durante un per\u00edodo de 5 a\u00f1os despu\u00e9s de haberle informado sobre obsequios de negocios.<br \/>\n5. Para cumplir con nuestra obligaci\u00f3n legal respecto a las devoluciones de IVA, conservamos la direcci\u00f3n de su factura y la informaci\u00f3n bancaria durante un per\u00edodo de 10 a\u00f1os.<\/p>\n<p>Si tratamos sus datos personales para m\u00faltiples prop\u00f3sitos, sus datos personales se eliminar\u00e1n una vez que haya transcurrido el \u00faltimo per\u00edodo de retenci\u00f3n actual.<\/p>\n<h3>5. Cookies<\/h3>\n<p>Utilizamos cookies en el sitio web. Hacemos esto de acuerdo con el RGPD. En particular, debemos informarle acerca de ciertas cookies y tambi\u00e9n pedir permiso para usarlas. Satisfacemos estos requisitos a trav\u00e9s de un \u201ccookie bot\u201d.<\/p>\n<h3>6. Compartir sus datos personales con terceros<\/h3>\n<p>En varios casos, debemos compartir con terceros sus datos personales que tratamos. Esto se refiere a las siguientes situaciones:<\/p>\n<p>1. En la prestaci\u00f3n de nuestros servicios y en la entrega de nuestros productos, por ejemplo, si opta porque el destinatario (un tercero), para saber de qui\u00e9n proviene el regalo o si utiliza su propia P\u00e1gina de Estrella \u00danica que puede publicarse en el sitio web;<br \/>\n2. Para cumplir con las obligaciones legales que tenemos, como la notificaci\u00f3n a la Autoridad Holandesa de Protecci\u00f3n de Datos [<i>Autoriteit Persoonsgegevens<\/i>] (un tercero);<br \/>\n3. En la contrataci\u00f3n de proveedores externos (terceros), por ejemplo, nuestro proveedor de TIC y host.<\/p>\n<p>Si utilizamos proveedores externos y estas partes procesan datos personales por nosotros, entonces celebraremos un acuerdo de Tratamiento de Datos con estas partes, de conformidad con lo establecido en el RGPD. Si estas partes no procesan datos personales por nosotros, entonces ellos mismos ser\u00e1n responsables de procesar estos datos y, por lo tanto, estar\u00e1n sujetos al RGPD.<\/p>\n<h3>7. Seguridad de sus datos personales<\/h3>\n<p>Hemos tomado las medidas t\u00e9cnicas y organizativas adecuadas para combatir el uso indebido, la p\u00e9rdida y la divulgaci\u00f3n no deseada de sus datos personales y el acceso no autorizado y los cambios no permitidos de estos datos.<\/p>\n<p>Si tiene alguna pregunta sobre la protecci\u00f3n de sus datos personales o si sospecha un uso indebido de sus datos personales, puede contactarnos a trav\u00e9s de <a href=\"mailto:help@osr.org\">help@osr.org<\/a>.<\/p>\n<h3>8. Derechos de los interesados<\/h3>\n<p><i>Derecho de acceso del interesado<\/i><\/p>\n<p>Usted tiene derecho a que le informemos a petici\u00f3n suya, si estamos tratando sus datos personales y, de ser as\u00ed, obtener acceso a estos datos personales y m\u00e1s informaci\u00f3n sobre el tratamiento de estos datos. A su solicitud, le enviaremos una copia de los datos personales que estamos tratando. Si nos solicita copias adicionales, podemos, seg\u00fan los costos administrativos, cobrar una tarifa razonable.<\/p>\n<p><i> Derecho de rectificaci\u00f3n <\/i><\/p>\n<p>Usted tiene derecho a obtener la rectificaci\u00f3n inmediata por nuestra parte de los datos personales incorrectos relacionados con usted. Sujeto a los prop\u00f3sitos del proceso descrito anteriormente, usted tiene derecho a que se completen los datos personales incompletos, por ejemplo, proporcion\u00e1ndonos una declaraci\u00f3n complementaria.<\/p>\n<p><i>Derecho de supresi\u00f3n<\/i><\/p>\n<p>A petici\u00f3n suya, sin demora injustificada, suprimiremos los datos personales relacionados con usted en los siguientes casos:<\/p>\n<p>1. Los datos personales que ya no sean necesarios para los fines para los que se han recopilado o tratado;<br \/>\n2. Cuando usted se oponga al tratamiento de datos de conformidad con el Art\u00edculo 21 (1) del RGPD, y no existan motivos leg\u00edtimos para el tratamiento, o se opone al tratamiento de conformidad con el Art\u00edculo 21 (2) del RGPD;<br \/>\n3. Los datos personales han sido procesados il\u00edcitamente;<br \/>\n4. Los datos personales deben borrarse para cumplir con una obligaci\u00f3n legal de conformidad con la legislaci\u00f3n de la UE o de Holanda a la que estamos sujetos;<br \/>\n5. Los datos personales se han recopilado con relaci\u00f3n a la oferta de servicios de la sociedad de la informaci\u00f3n a que se refiere el art\u00edculo 8 (1) del RGPD.<\/p>\n<p><i> Derecho a la limitaci\u00f3n del tratamiento <\/i><\/p>\n<p>A su solicitud, limitaremos el tratamiento de datos personales relacionados con usted en los siguientes casos:<\/p>\n<p>1. Si usted impugna la precisi\u00f3n de los datos personales, por un per\u00edodo que nos permita verificar la precisi\u00f3n de los datos personales;<br \/>\n2. El procesamiento es il\u00edcito, y usted se opone a la eliminaci\u00f3n de los datos personales y solicita la limitaci\u00f3n de su uso en su lugar;<br \/>\n3. En el caso en que ya no necesitemos los datos personales para los fines del tratamiento, pero usted los requiere para el establecimiento, el ejercicio o la defensa de reclamaciones legales;<br \/>\n4. Usted ha objetado el tratamiento de datos conforme al Art\u00edculo 21 (1) del RGPD en espera de la verificaci\u00f3n de si nuestros motivos leg\u00edtimos prevalecen sobre los suyos.<\/p>\n<p><i> Derecho a la portabilidad de datos <\/i><\/p>\n<p>Usted tiene derecho a recibir, en un formato estructurado, com\u00fanmente utilizado y legible por m\u00e1quina, sus datos personales que estamos procesando de acuerdo con las bases \u00abcumplimiento del acuerdo\u00bb e \u00abinter\u00e9s leg\u00edtimo\u00bb. Adem\u00e1s, usted tiene derecho a transferir estos datos a otro responsable de tratamiento, adem\u00e1s de nosotros, y tiene derecho a que los datos personales en cuesti\u00f3n se transfieran, si es t\u00e9cnicamente posible, directamente de nosotros al otro responsable de tratamiento.<\/p>\n<p><i> Derecho de oposici\u00f3n <\/i><\/p>\n<p>Usted podr\u00e1 oponerse, con relaci\u00f3n a su situaci\u00f3n particular, en cualquier momento al tratamiento de sus datos personales si lo hacemos de conformidad con la base del \u00abinter\u00e9s leg\u00edtimo\u00bb. En ese caso, detendremos el tratamiento de sus datos personales, a menos que presentemos motivos leg\u00edtimos convincentes para el tratamiento que invaliden sus intereses, derechos y libertades o que se relacionen con el establecimiento, ejercicio o defensa de reclamaciones legales.<br \/>\nSin embargo, usted debe comprender que objetar el tratamiento al que se hace referencia en este documento o solicitar la supresi\u00f3n de los datos personales, puede ocasionar que ya no podamos cumplir con las obligaciones con usted.<\/p>\n<h3>9. Reclamos<\/h3>\n<p>Usted puede presentar una queja ante la Autoridad Holandesa de Protecci\u00f3n de Datos en cualquier momento.<\/p>\n<h3>10. Observaciones finales<\/h3>\n<p>Tendremos que revisar este documento ocasionalmente, debido a posibles cambios en el sitio web o las reglas sobre datos personales y \/ o cookies. Podemos modificar el contenido de los T\u00e9rminos y Condiciones unilateralmente sin previo aviso. Puede consultar el sitio web para obtener la \u00faltima versi\u00f3n.<\/p>\n<h3>11. Informaci\u00f3n de contacto del responsable de datos<\/h3>\n<p>Si tiene preguntas y \/ o comentarios, comun\u00edquese con Online Star Register, OSR.<\/p>\n<p>Compa\u00f1\u00eda: Online Star Register B.V.<br \/>\nDirecci\u00f3n: Laan van de Maagd 83, 7324 BT Apeldoorn, Pa\u00edses Bajos<br \/>\nTel\u00e9fono: (+31) (0)88-8000088<br \/>\nDirecci\u00f3n de correo electr\u00f3nico: <a href=\"mailto:help@osr.org\">help@osr.org<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>www.osr.org 1. Introducci\u00f3n Online Star Register, OSR, tambi\u00e9n se hace referencia a continuaci\u00f3n como \u201cnosotros\u201d o \u201cnuestro\u201d, procesa Datos Personales como Responsable del Tratamiento de Datos de acuerdo con el RGPD. Nos gustar\u00eda proporcionarle informaci\u00f3n sobre esto. Consideramos que es nuestra responsabilidad proteger su privacidad tanto como sea posible y explicarle de manera apropiada la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-privacy-policy.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3093","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Privacidad de ONLINE STAR REGISTER - Online Star Register<\/title>\n<meta name=\"description\" content=\"Visita la p\u00e1gina web de Online Star Register para leer nuestra pol\u00edtica de privacidad y exenci\u00f3n de responsabilidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osr.org\/es\/politica-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad de ONLINE STAR REGISTER - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"Visita la p\u00e1gina web de Online Star Register para leer nuestra pol\u00edtica de privacidad y exenci\u00f3n de responsabilidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/es\/politica-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-29T12:40:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/politica-privacidad\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/politica-privacidad\\\/\",\n\t            \"name\": \"Pol\u00edtica de Privacidad de ONLINE STAR REGISTER - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2015-11-17T13:18:23+00:00\",\n\t            \"dateModified\": \"2019-07-29T12:40:51+00:00\",\n\t            \"description\": \"Visita la p\u00e1gina web de Online Star Register para leer nuestra pol\u00edtica de privacidad y exenci\u00f3n de responsabilidad.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/politica-privacidad\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"es\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/es\\\/politica-privacidad\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/politica-privacidad\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/es\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Pol\u00edtica de Privacidad de ONLINE STAR REGISTER\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/es\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/es\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/es\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"es\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidad de ONLINE STAR REGISTER - Online Star Register","description":"Visita la p\u00e1gina web de Online Star Register para leer nuestra pol\u00edtica de privacidad y exenci\u00f3n de responsabilidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osr.org\/es\/politica-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de Privacidad de ONLINE STAR REGISTER - Online Star Register","og_description":"Visita la p\u00e1gina web de Online Star Register para leer nuestra pol\u00edtica de privacidad y exenci\u00f3n de responsabilidad.","og_url":"https:\/\/osr.org\/es\/politica-privacidad\/","og_site_name":"Online Star Register","article_modified_time":"2019-07-29T12:40:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/osr.org\/es\/politica-privacidad\/","url":"https:\/\/osr.org\/es\/politica-privacidad\/","name":"Pol\u00edtica de Privacidad de ONLINE STAR REGISTER - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/es\/#website"},"datePublished":"2015-11-17T13:18:23+00:00","dateModified":"2019-07-29T12:40:51+00:00","description":"Visita la p\u00e1gina web de Online Star Register para leer nuestra pol\u00edtica de privacidad y exenci\u00f3n de responsabilidad.","breadcrumb":{"@id":"https:\/\/osr.org\/es\/politica-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/es\/politica-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/es\/politica-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidad de ONLINE STAR REGISTER"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/es\/#website","url":"https:\/\/osr.org\/es\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/pages\/3093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/comments?post=3093"}],"version-history":[{"count":5,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/pages\/3093\/revisions"}],"predecessor-version":[{"id":103833,"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/pages\/3093\/revisions\/103833"}],"wp:attachment":[{"href":"https:\/\/osr.org\/es\/wp-json\/wp\/v2\/media?parent=3093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}