{"id":112253,"date":"2019-10-30T22:26:11","date_gmt":"2019-10-30T20:26:11","guid":{"rendered":"https:\/\/osr.org\/?p=112253"},"modified":"2021-03-10T14:06:08","modified_gmt":"2021-03-10T12:06:08","slug":"weihnachtscountdown","status":"publish","type":"post","link":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/","title":{"rendered":"Der Weihnachtscountdown beginnt"},"content":{"rendered":"<p>Zudem scheint es so, als ob der Weihnachtscountdown jedes Jahr fr\u00fcher beginnt. Man kann leicht dem Shopping-Wahnsinn zum Opfer fallen und seine Weihnachtseink\u00e4ufe bereits lange Zeit vorher beginnen. Man muss aber nicht herumlaufen, im Verkehr ausharren und den panischen Zustand ertragen, in dem die meisten Leute sich zu befinden scheinen. Man kann zu Hause sitzen in seinen bequemen Hausschuhen mit einem ruhigen Gewissen sowie einem verschmitzten L\u00e4cheln im Gesicht (w\u00e4hrend man wahrscheinlich die Geschenke der Vorsaison, die man im Oktober gekauft hat, bereut \u2013 obwohl man es zumindest hinter sich gebracht hat).<\/p>\n<div id=\"attachment_112274\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-112274\" class=\"size-full wp-image-112274\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg\" alt=\"Weihnachtscountdown-Menschen-beim-Shoppen\" width=\"650\" height=\"433\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg 650w, https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen-300x200.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><p id=\"caption-attachment-112274\" class=\"wp-caption-text\"><p class=\"caption-text\">Kaufe fr\u00fch ein, um dem Weihnachtswahnsinn zu vermeiden<\/p><\/figure> Kaufe fr\u00fch ein, um dem Weihnachtswahnsinn zu vermeiden<\/p><\/div>\n<h2><span style=\"color: #15acdf;\"><strong>Weihnachtscountdown-Uhr<\/strong><\/span><\/h2>\n<p>F\u00fcr diejenigen unter euch, die viel zu besch\u00e4ftigt sind, um sich \u00fcberhaupt Gedanken \u00fcber Weihnachten zu machen \u2013 es ist gleich um die Ecke.\u00a0Der 25. Dezember f\u00e4llt in diesem Jahr auf einen Mittwoch. Damit du dich besser erinnern kannst, haben die guten Computerfreaks Countdown-Uhren entwickelt, die auf deinem Computerbildschirm angezeigt werden k\u00f6nnen.\u00a0Mit diesen kleinen Weihnachts-Widgets kannst du die Minuten bis zum gro\u00dfen Tag z\u00e4hlen.<\/p>\n<p>Sicher schenkst du dieser freundlichen Erinnerung im Moment nicht allzu viel Aufmerksamkeit.\u00a0Sie wird auf deinem Desktop sicher gut aussehen und m\u00f6glicherweise sogar zu ein paar Gespr\u00e4chen mit deinen Freunden und Bekannten f\u00fchren.\u00a0Was jetzt jedoch s\u00fc\u00df ist, wirst du sp\u00e4ter abhaken.\u00a0Dieses Weihnachts-Widget hat nur eine Aufgabe, und zwar: die Minuten, Tage und Wochen z\u00e4hlen, die vergehen.<\/p>\n<h2><span style=\"color: #15acdf;\"><strong>Weihnachtscountdown-Widget<\/strong><\/span><\/h2>\n<p>Du denkst vielleicht, du hast &#8222;viel Zeit&#8220;, um das perfekte Geschenk f\u00fcr deine\/n PartnerIn oder das beste Spielzeug f\u00fcr dein Kind zu finden, aber ein Blick auf dein nerviges, kleines Widget-Freund wird dich daran erinnern, wie viel von der kostbaren Einkaufszeit du bereits verschwendet hast.<\/p>\n<style>\n       .errordiv { padding:10px; margin:10px; border: 1px solid #555555;color: #000000;background-color: #f8f8f8; width:500px; }#advanced_iframe {visibility:visible;opacity:1;vertical-align:top;}.ai-info-bottom-iframe { position: fixed; z-index: 10000; bottom:0; left: 0; margin: 0px; text-align: center; width: 100%; background-color: #ff9999; padding-left: 5px;padding-bottom: 5px; border-top: 1px solid #aaa } a.ai-bold {font-weight: bold;}#ai-layer-div-advanced_iframe p {height:100%;margin:0;padding:0}<\/style><script type=\"text\/javascript\">var ai_iframe_width_advanced_iframe = 0;var ai_iframe_height_advanced_iframe = 0;var aiOnloadScrollTop=\"true\";var aiShowDebug=false;\n\t\tif (typeof aiReadyCallbacks === 'undefined') {\n\t\t\tvar aiReadyCallbacks = [];\n\t\t} else if (!(aiReadyCallbacks instanceof Array)) {\n\t\t\tvar aiReadyCallbacks = [];\n\t\t}    function aiShowIframeId(id_iframe) { jQuery(\"#\"+id_iframe).css(\"visibility\", \"visible\");    }    function aiResizeIframeHeight(height) { aiResizeIframeHeight(height,advanced_iframe); }    function aiResizeIframeHeightId(height,width,id) {aiResizeIframeHeightById(id,height);}<\/script><iframe id=\"advanced_iframe\"  name=\"advanced_iframe\"  src=\"https:\/\/osr.org\/wp-content\/uploads\/2016\/11\/countdown.html\"  width=\"100%\"  height=\"220\"  frameborder=\"0\"  border=\"0\"  allowtransparency=\"true\"  loading=\"lazy\"  style=\";border-width: 0px;;border: none;;width:100%;;height:220px;\" ><\/iframe><script type=\"text\/javascript\">var ifrm_advanced_iframe = document.getElementById(\"advanced_iframe\");var hiddenTabsDoneadvanced_iframe = false;\nfunction resizeCallbackadvanced_iframe() {}<\/script><script type=\"text\/javascript\"><\/script><p style=\"display:block !important; visibility:visible !important;margin: -18px 14px 0 0;padding-left: 3px;padding-top:3px;background: white; overflow: hidden; position: relative; line-height:15px;width: fit-content;\"><small style=\"display:block !important;visibility:visible !important\">powered by Advanced iFrame<\/small><\/p>\n<p>Um unser Responsive Christmas Countdown-Widget auf deiner Website zu verwenden, kannst du\u00a0<strong>https:\/\/osr.org\/wp-content\/uploads\/2016\/11\/countdown.html\u00a0<\/strong>als iframe\u00a0einbetten.<\/p>\n<h2><span style=\"color: #15acdf;\"><strong>Das Weihnachts-Widget der Zukunft<\/strong><\/span><\/h2>\n<p>Vielleicht bist du der Typ Mensch, der diese Art von Ger\u00e4ten ignoriert, die nur Platz auf deinem Computer beanspruchen.\u00a0Ein Kalender sollte ausreichen, um dich auf dem Laufenden zu halten&#8230; obwohl du m\u00f6glicherweise eine (oder zwei) Deadlines verpasst hast, weil du nicht in deinen Welpen-des-Monats-Kalender geschaut oder den Tag mit dem n\u00e4chsten Tag verwechselt hast.<\/p>\n<p>Wenn diese Weihnachtscountdown-Widgets \u00fcberhaupt funktionieren, sollten sie mit einem Alarmsystem ausgestattet sein. Ein System, das verschiedene Glocken und T\u00f6ne anspielt, um deine Aufmerksamkeit zu erregen.<\/p>\n<p>Vielleicht das Klingeln einer Weihnachtsglocke Mitte November?\u00a0Dann vielleicht die Melodie von Jingle Bells, die immer und immer wieder abgespielt wird, bis sie Anfang Dezember wie ein b\u00f6ser Traum in deinem Kopf steckt?<\/p>\n<p>W\u00e4hrend die Tage voranschreiten und wir uns dem gro\u00dfen Tag n\u00e4hern, sollte eine laute, autorit\u00e4re Stimme von uns verlangen, dass wir anfangen, uns ernsthaft mit Weihnachten zu besch\u00e4ftigen.\u00a0Wenn du dann die Dringlichkeit der\u00a0verstrichenen Zeit\u00a0nicht erkennst, tanzen eine Reihe von Zuckerstangen oder Elfen \u00fcber deinen Bildschirm, bis du den Computer herunterf\u00e4hrst und einkaufen gehst.\u00a0Sicher, es mag zuerst entz\u00fcckend sein, aber um effektiv zu sein, sollte es dich dazu bringen, davor davonzulaufen (wie Omas altmodischer Feigenpudding).<\/p>\n<div id=\"attachment_112294\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-112294\" class=\"size-full wp-image-112294\" src=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Feigenpudding.jpg\" alt=\"Weihnachtscountdown - Feigenpudding\" width=\"650\" height=\"433\" srcset=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Feigenpudding.jpg 650w, https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Feigenpudding-300x200.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><p id=\"caption-attachment-112294\" class=\"wp-caption-text\"><p class=\"caption-text\">So muss Feigenpudding aussehen<\/p><\/figure> So muss Feigenpudding aussehen<\/p><\/div>\n<p>Egal, ob du Weihnachten liebst und all die Verr\u00fccktheit, die es mit sich bringt, oder dich damit begn\u00fcgst, Heiligabend einfach verstreichen zu lassen und deine Mitmenschen am n\u00e4chsten Tag zu entt\u00e4uschen Tag, Weihnachtscountdown-Kalender sind eine hervorragende Option, um die Tage bis zum gro\u00dfen Tag zu verfolgen..<\/p>\n<p>Vielleicht bist du derjenige, der bereits fertig ist und ein gro\u00dfes, arrogantes L\u00e4cheln im Gesicht hat. Bis dein Welpen-des-Monats-Kalender dich noch einmal im Stich l\u00e4sst und dir klar wird, dass du einen weiteren Termin verpasst hast&#8230;<\/p>\n<p><em>Frohe Widget<\/em><em>&#8211;<\/em><em>Weihnachten<\/em><\/p>\n<p style=\"text-align: center;\"><a class=\"button button-orange medium arrow\" href=\"https:\/\/osr.org\/de\/geschenke-fur\/weihnacht\/\">Weihnachtsgeschenk?\u00a0Benenne einen Stern!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zudem scheint es so, als ob der Weihnachtscountdown jedes Jahr fr\u00fcher beginnt. Man kann leicht dem Shopping-Wahnsinn zum Opfer fallen und seine Weihnachtseink\u00e4ufe bereits lange Zeit vorher beginnen. Man muss aber nicht herumlaufen, im Verkehr ausharren und den panischen Zustand ertragen, in dem die meisten Leute sich zu befinden scheinen. Man kann zu Hause sitzen [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[613],"tags":[],"class_list":["post-112253","post","type-post","status-publish","format-standard","hentry","category-tipps-geschenke"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Weihnachtscountdown beginnt - Online Star Register<\/title>\n<meta name=\"description\" content=\"Z\u00e4hle die Tage. Nutze das Weihnachtscountdown-Widget f\u00fcr deinen Computer und erhalte viele Designs, die gratis und einfach herunterzuladen sind.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Weihnachtscountdown beginnt - Online Star Register\" \/>\n<meta property=\"og:description\" content=\"Z\u00e4hle die Tage. Nutze das Weihnachtscountdown-Widget f\u00fcr deinen Computer und erhalte viele Designs, die gratis und einfach herunterzuladen sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Star Register\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-30T20:26:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-10T12:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg\" \/>\n<meta name=\"author\" content=\"OSR Germany\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"OSR Germany\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"OSR Germany\",\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/#\\\/schema\\\/person\\\/989144f658e8ee9a9917c867c2d6eb75\"\n\t            },\n\t            \"headline\": \"Der Weihnachtscountdown beginnt\",\n\t            \"datePublished\": \"2019-10-30T20:26:11+00:00\",\n\t            \"dateModified\": \"2021-03-10T12:06:08+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/\"\n\t            },\n\t            \"wordCount\": 656,\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg\",\n\t            \"articleSection\": [\n\t                \"Tipps &amp; Geschenke\"\n\t            ],\n\t            \"inLanguage\": \"de\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/\",\n\t            \"name\": \"Der Weihnachtscountdown beginnt - Online Star Register\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg\",\n\t            \"datePublished\": \"2019-10-30T20:26:11+00:00\",\n\t            \"dateModified\": \"2021-03-10T12:06:08+00:00\",\n\t            \"author\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/#\\\/schema\\\/person\\\/989144f658e8ee9a9917c867c2d6eb75\"\n\t            },\n\t            \"description\": \"Z\u00e4hle die Tage. Nutze das Weihnachtscountdown-Widget f\u00fcr deinen Computer und erhalte viele Designs, die gratis und einfach herunterzuladen sind.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"de\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"de\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/osr.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/tipps-geschenke\\\/weihnachtscountdown\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/de\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Tipps &amp; Geschenke\",\n\t                    \"item\": \"https:\\\/\\\/osr.org\\\/de\\\/tipps-geschenke\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Der Weihnachtscountdown beginnt\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/de\\\/\",\n\t            \"name\": \"Online Star Register\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/osr.org\\\/de\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"de\"\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/osr.org\\\/de\\\/#\\\/schema\\\/person\\\/989144f658e8ee9a9917c867c2d6eb75\",\n\t            \"name\": \"OSR Germany\",\n\t            \"url\": \"https:\\\/\\\/osr.org\\\/de\\\/blog\\\/author\\\/osr-germany\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Weihnachtscountdown beginnt - Online Star Register","description":"Z\u00e4hle die Tage. Nutze das Weihnachtscountdown-Widget f\u00fcr deinen Computer und erhalte viele Designs, die gratis und einfach herunterzuladen sind.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"Der Weihnachtscountdown beginnt - Online Star Register","og_description":"Z\u00e4hle die Tage. Nutze das Weihnachtscountdown-Widget f\u00fcr deinen Computer und erhalte viele Designs, die gratis und einfach herunterzuladen sind.","og_url":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/","og_site_name":"Online Star Register","article_published_time":"2019-10-30T20:26:11+00:00","article_modified_time":"2021-03-10T12:06:08+00:00","og_image":[{"url":"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg","type":"","width":"","height":""}],"author":"OSR Germany","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"OSR Germany","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/#article","isPartOf":{"@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/"},"author":{"name":"OSR Germany","@id":"https:\/\/osr.org\/de\/#\/schema\/person\/989144f658e8ee9a9917c867c2d6eb75"},"headline":"Der Weihnachtscountdown beginnt","datePublished":"2019-10-30T20:26:11+00:00","dateModified":"2021-03-10T12:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/"},"wordCount":656,"image":{"@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg","articleSection":["Tipps &amp; Geschenke"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/","url":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/","name":"Der Weihnachtscountdown beginnt - Online Star Register","isPartOf":{"@id":"https:\/\/osr.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/#primaryimage"},"image":{"@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/#primaryimage"},"thumbnailUrl":"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg","datePublished":"2019-10-30T20:26:11+00:00","dateModified":"2021-03-10T12:06:08+00:00","author":{"@id":"https:\/\/osr.org\/de\/#\/schema\/person\/989144f658e8ee9a9917c867c2d6eb75"},"description":"Z\u00e4hle die Tage. Nutze das Weihnachtscountdown-Widget f\u00fcr deinen Computer und erhalte viele Designs, die gratis und einfach herunterzuladen sind.","breadcrumb":{"@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/#primaryimage","url":"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg","contentUrl":"https:\/\/osr.org\/wp-content\/uploads\/2019\/10\/Weihnachtscountdown-Menschen-beim-Shoppen.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/osr.org\/de\/blog\/tipps-geschenke\/weihnachtscountdown\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osr.org\/de\/"},{"@type":"ListItem","position":2,"name":"Tipps &amp; Geschenke","item":"https:\/\/osr.org\/de\/tipps-geschenke\/"},{"@type":"ListItem","position":3,"name":"Der Weihnachtscountdown beginnt"}]},{"@type":"WebSite","@id":"https:\/\/osr.org\/de\/#website","url":"https:\/\/osr.org\/de\/","name":"Online Star Register","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osr.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/osr.org\/de\/#\/schema\/person\/989144f658e8ee9a9917c867c2d6eb75","name":"OSR Germany","url":"https:\/\/osr.org\/de\/blog\/author\/osr-germany\/"}]}},"_links":{"self":[{"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/posts\/112253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/comments?post=112253"}],"version-history":[{"count":4,"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/posts\/112253\/revisions"}],"predecessor-version":[{"id":112317,"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/posts\/112253\/revisions\/112317"}],"wp:attachment":[{"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/media?parent=112253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/categories?post=112253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osr.org\/de\/wp-json\/wp\/v2\/tags?post=112253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}